{"id":116726,"date":"2026-03-19T12:16:42","date_gmt":"2026-03-19T18:16:42","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=116726"},"modified":"2026-03-19T12:16:42","modified_gmt":"2026-03-19T18:16:42","slug":"clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/","title":{"rendered":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-116727\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-150x100.jpeg 150w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-300x200.jpeg 300w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-696x464.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-1068x712.jpeg 1068w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Tekit, Yucat\u00e1n, a 19 de marzo de 2026<\/p>\n<p>Con una vaquer\u00eda tradicional organizada por las y los propios estudiantes de la Escuela Secundaria T\u00e9cnica No. 50, concluy\u00f3 el Modelo de Intervenci\u00f3n para la Prevenci\u00f3n de Conductas de Riesgo en Adolescentes KAAB: Panales Comunitarios, en una jornada que destac\u00f3 por el talento juvenil, la identidad cultural y la participaci\u00f3n comunitaria.<\/p>\n<p>Bajo el nombre \u201cM\u00faul Meyaj\u201d (trabajo colectivo), el evento se realiz\u00f3 en la Casa de la Cultura de Tekit y tuvo como prop\u00f3sito presentar los resultados del modelo KAAB mediante actividades que impulsan la identidad cultural y el bienestar socioemocional a trav\u00e9s del deporte y la expresi\u00f3n art\u00edstica.<\/p>\n<p>Durante la etapa de cierre, denominada \u201cMiel\u201d, las y los adolescentes compartieron con la comunidad muestras de los talleres de danza, canto, jarana y teatro regional, as\u00ed como una exposici\u00f3n de artes visuales, actividades que reflejaron el aprendizaje adquirido durante el proceso formativo.<\/p>\n<p>La celebraci\u00f3n incluy\u00f3 la develaci\u00f3n de la exposici\u00f3n art\u00edstica y una vaquer\u00eda en la que el alumnado demostr\u00f3 no solo sus habilidades esc\u00e9nicas, sino tambi\u00e9n su capacidad de organizaci\u00f3n, trabajo en equipo y apropiaci\u00f3n de su identidad cultural. Asimismo, se llev\u00f3 a cabo un torneo de quitinbol que fortaleci\u00f3 la convivencia y el trabajo en equipo.<\/p>\n<p>Durante su intervenci\u00f3n, la directora del Cepredy, Zayuri Valle Valencia, reconoci\u00f3 el talento y el potencial de las juventudes de Tekit, y se\u00f1al\u00f3 que el trabajo realizado representa una semilla que, con el acompa\u00f1amiento de las familias, puede dar frutos importantes en su desarrollo personal.<\/p>\n<p>Asimismo, destac\u00f3 que este esfuerzo forma parte de una gesti\u00f3n interinstitucional entre el Cepredy, la Secretar\u00eda de la Cultura y las Artes (Sedeculta) y el Ayuntamiento de Tekit, orientada a garantizar el acceso continuo a actividades art\u00edsticas y deportivas en la comunidad, lo que contribuye al bienestar de las y los adolescentes.<\/p>\n<p>En ese contexto, se anunci\u00f3 que, gracias a esta colaboraci\u00f3n, en el Centro Cultural de Tekit se ofrecer\u00e1n de manera gratuita clases de jarana, f\u00fatbol, m\u00fasica y artes visuales, con lo que se fortalecer\u00e1n los espacios de formaci\u00f3n y participaci\u00f3n para ni\u00f1as, ni\u00f1os y j\u00f3venes del municipio.<\/p>\n<p>Por su parte, el presidente municipal de Tekit, Jos\u00e9 Antonio Sosa Hern\u00e1ndez, destac\u00f3 que cuando existe voluntad, compromiso y trabajo en equipo es posible construir un mejor futuro para todas y todos.<\/p>\n<p>Adem\u00e1s, exhort\u00f3 a las y los j\u00f3venes a aprovechar las oportunidades, participar, continuar su formaci\u00f3n, practicar deporte y valorar su cultura como base para alcanzar sus metas.<\/p>\n<p>El evento cont\u00f3 con la asistencia del director de la Escuela Secundaria T\u00e9cnica No. 50, Ludovico Salazar Cano; el director del Instituto de Salud Mental de la Secretar\u00eda de Salud de Yucat\u00e1n, Gaspar Ra\u00fal P\u00e9rez Mart\u00ednez; la coordinadora general de Habilidades Socioemocionales de la Secretar\u00eda de Educaci\u00f3n del estado, M\u00f3nica Bargas Caporali; la jefa del Departamento de Vinculaci\u00f3n y Educaci\u00f3n de la Secretar\u00eda de la Cultura y las Artes, Roc\u00edo Acosta Novelo; y madres y padres de familia, quienes acompa\u00f1aron a las y los estudiantes en la clausura.<\/p>\n<p>La implementaci\u00f3n del modelo KAAB en Tekit benefici\u00f3 de manera directa a 521 j\u00f3venes y forma parte de las medidas del Gobierno del Estado, a trav\u00e9s del Cepredey, alineadas con la estrategia Aliados por la Vida, que impulsa el Gobernador Joaqu\u00edn D\u00edaz Mena, la cual promueve el desarrollo integral, la prevenci\u00f3n de conductas de riesgo y la construcci\u00f3n de entornos positivos para las juventudes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tekit, Yucat\u00e1n, a 19 de marzo de 2026 Con una vaquer\u00eda tradicional organizada por las y los propios estudiantes de la Escuela Secundaria T\u00e9cnica No. 50, concluy\u00f3 el Modelo de Intervenci\u00f3n para la Prevenci\u00f3n de Conductas de Riesgo en Adolescentes KAAB: Panales Comunitarios, en una jornada que destac\u00f3 por el talento juvenil, la identidad cultural [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":116727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-116726","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Tekit, Yucat\u00e1n, a 19 de marzo de 2026 Con una vaquer\u00eda tradicional organizada por las y los propios estudiantes de la Escuela Secundaria T\u00e9cnica No. 50, concluy\u00f3 el Modelo de Intervenci\u00f3n para la Prevenci\u00f3n de Conductas de Riesgo en Adolescentes KAAB: Panales Comunitarios, en una jornada que destac\u00f3 por el talento juvenil, la identidad cultural [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T18:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"YC 25\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"YC 25\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/\"},\"author\":{\"name\":\"YC 25\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\"},\"headline\":\"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional\",\"datePublished\":\"2026-03-19T18:16:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/\"},\"wordCount\":628,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/\",\"name\":\"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\",\"datePublished\":\"2026-03-19T18:16:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\",\"name\":\"YC 25\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"caption\":\"YC 25\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/editor25\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/","og_locale":"es_ES","og_type":"article","og_title":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto","og_description":"Tekit, Yucat\u00e1n, a 19 de marzo de 2026 Con una vaquer\u00eda tradicional organizada por las y los propios estudiantes de la Escuela Secundaria T\u00e9cnica No. 50, concluy\u00f3 el Modelo de Intervenci\u00f3n para la Prevenci\u00f3n de Conductas de Riesgo en Adolescentes KAAB: Panales Comunitarios, en una jornada que destac\u00f3 por el talento juvenil, la identidad cultural [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2026-03-19T18:16:42+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg","type":"image\/jpeg"}],"author":"YC 25","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"YC 25","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/"},"author":{"name":"YC 25","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771"},"headline":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional","datePublished":"2026-03-19T18:16:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/"},"wordCount":628,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/","name":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg","datePublished":"2026-03-19T18:16:42+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-09.28.31-scaled.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/clausuran-en-tekit-el-modelo-kaab-con-vaqueria-tradicional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Clausuran en Tekit el Modelo KAAB con vaquer\u00eda tradicional"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771","name":"YC 25","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","caption":"YC 25"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/editor25\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/116726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=116726"}],"version-history":[{"count":1,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/116726\/revisions"}],"predecessor-version":[{"id":116728,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/116726\/revisions\/116728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/116727"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=116726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=116726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=116726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}