{"id":117181,"date":"2026-05-14T15:28:56","date_gmt":"2026-05-14T21:28:56","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=117181"},"modified":"2026-05-14T15:28:56","modified_gmt":"2026-05-14T21:28:56","slug":"onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/","title":{"rendered":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-117182\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-150x100.jpeg 150w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-300x200.jpeg 300w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-696x464.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-1068x713.jpeg 1068w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><br \/>\nLa convenci\u00f3n re\u00fane a autoridades, empresarios y proveedores para analizar los retos del sector energ\u00e9tico y fortalecer oportunidades de inversi\u00f3n.<\/p>\n<p>El Gobernador Joaqu\u00edn D\u00edaz Mena inaugur\u00f3 la Convenci\u00f3n de la Organizaci\u00f3n Nacional de Expendedores de Petr\u00f3leo (Onexpo) 2026, el encuentro m\u00e1s grande de la industria de hidrocarburos l\u00edquidos en M\u00e9xico, que re\u00fane a empresarios gasolineros y proveedores de servicios de todo el pa\u00eds, consolidando a Yucat\u00e1n como sede estrat\u00e9gica para el sector energ\u00e9tico nacional y fortaleciendo la colaboraci\u00f3n en una industria clave para el crecimiento econ\u00f3mico.<\/p>\n<p>Durante el evento, D\u00edaz Mena tom\u00f3 protesta al nuevo Consejo Directivo de la Onexpo para el periodo 2026-2027, y reafirm\u00f3 la importancia de fortalecer la industria gasolinera y su papel en el desarrollo econ\u00f3mico de M\u00e9xico y Yucat\u00e1n.<\/p>\n<p>Desde el Centro de Convenciones y Exposiciones Yucat\u00e1n Siglo XXI, el mandatario estatal, acompa\u00f1ado de la presidenta de la Comisi\u00f3n de Energ\u00eda del Senado de la Rep\u00fablica, Beatriz Silvia Robles Guti\u00e9rrez, se\u00f1al\u00f3 que este encuentro, que se realiza desde el 12 hasta el 15 de mayo, posiciona al estado como sede de uno de los di\u00e1logos sectoriales m\u00e1s relevantes del pa\u00eds.<\/p>\n<p>\u201cDurante los pr\u00f3ximos d\u00edas, M\u00e9rida ser\u00e1 el epicentro de las discusiones sobre el presente y futuro energ\u00e9tico de M\u00e9xico, en una convenci\u00f3n que abordar\u00e1 temas clave como las perspectivas del sector, la regulaci\u00f3n, el cumplimiento normativo, la innovaci\u00f3n y la modernizaci\u00f3n de los modelos de negocio\u201d, manifest\u00f3.<\/p>\n<p>El mandatario destac\u00f3 que el sector energ\u00e9tico es uno de los pilares del desarrollo econ\u00f3mico nacional, pues las estaciones de servicio generan miles de empleos y sostienen actividades como el turismo, el comercio, el campo y la movilidad de las familias.<\/p>\n<p>Asimismo, reconoci\u00f3 los retos que enfrenta la industria, entre ellos la volatilidad de precios, los altos costos de operaci\u00f3n, la seguridad en la distribuci\u00f3n de combustibles y la necesidad de modernizar la infraestructura para avanzar hacia modelos m\u00e1s eficientes y sustentables.<\/p>\n<p>\u201cDetr\u00e1s de cada estaci\u00f3n hay familias y ciudadanos que dependen de esta actividad para impulsar la econom\u00eda, el turismo, el comercio y el campo. La presencia de empresarios en M\u00e9rida refleja la importancia del sector y abre oportunidades de negocio y colaboraci\u00f3n\u201d, expuso.<\/p>\n<p>En ese sentido, el Gobernador agradeci\u00f3 el respaldo de la Presidenta Claudia Sheinbaum Pardo para consolidar proyectos estrat\u00e9gicos en Yucat\u00e1n, como la modernizaci\u00f3n del Puerto de Altura de Progreso, el tren de carga y los Polos Industriales del Bienestar, adem\u00e1s de la inauguraci\u00f3n del nuevo Hospital General \u201cDr. Agust\u00edn O\u2019Hor\u00e1n\u201d y la Universidad Nacional Rosario Castellanos, que fortalecer\u00e1n la infraestructura y el desarrollo social del estado.<\/p>\n<p>En su intervenci\u00f3n, la presidenta de la Comisi\u00f3n de Energ\u00eda del Senado de la Rep\u00fablica, Beatriz Silvia Robles Guti\u00e9rrez, indic\u00f3 que esta convenci\u00f3n representa un espacio de reflexi\u00f3n e intercambio de experiencias para la industria gasolinera, con el objetivo de fortalecer el di\u00e1logo entre legisladores y actores del sector energ\u00e9tico.<\/p>\n<p>\u201cDesde el Senado y la comisi\u00f3n que presido existe el compromiso de dar seguimiento a los trabajos legislativos, recordando las reformas aprobadas en marzo de 2025 para devolver a Pemex su car\u00e1cter p\u00fablico y cumplir con su responsabilidad social\u201d, puntualiz\u00f3.<\/p>\n<p>A su vez, el presidente nacional de la Onexpo, Enrique F\u00e9lix Robelo, indic\u00f3 que el programa de Onexpo 2026 permitir\u00e1 escuchar voces acreditadas sobre regulaci\u00f3n, competencia, precios, innovaci\u00f3n, nuevas tecnolog\u00edas y seguridad, fortaleciendo la profesionalizaci\u00f3n del sector y el servicio a las y los consumidores.<\/p>\n<p>En el evento estuvieron presentes el presidente de la Confederaci\u00f3n Nacional de C\u00e1maras de Comercio, Servicios y Turismo (Concanaco Servytur), Octavio de la Torre de St\u00e9ffano; el director general de Contenido Nacional y Fomento en el Sector Energ\u00e9tico y representante personal del secretario de Econom\u00eda del Gobierno de M\u00e9xico, Marcelo Ebrard Casaub\u00f3n, Alberto Uribe Camacho; la presidenta municipal de M\u00e9rida, Cecilia Patr\u00f3n Laviada, y el presidente del Consejo Mexicano de la Energ\u00eda, Juan Acra L\u00f3pez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La convenci\u00f3n re\u00fane a autoridades, empresarios y proveedores para analizar los retos del sector energ\u00e9tico y fortalecer oportunidades de inversi\u00f3n. El Gobernador Joaqu\u00edn D\u00edaz Mena inaugur\u00f3 la Convenci\u00f3n de la Organizaci\u00f3n Nacional de Expendedores de Petr\u00f3leo (Onexpo) 2026, el encuentro m\u00e1s grande de la industria de hidrocarburos l\u00edquidos en M\u00e9xico, que re\u00fane a empresarios gasolineros [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":117182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-117181","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"La convenci\u00f3n re\u00fane a autoridades, empresarios y proveedores para analizar los retos del sector energ\u00e9tico y fortalecer oportunidades de inversi\u00f3n. El Gobernador Joaqu\u00edn D\u00edaz Mena inaugur\u00f3 la Convenci\u00f3n de la Organizaci\u00f3n Nacional de Expendedores de Petr\u00f3leo (Onexpo) 2026, el encuentro m\u00e1s grande de la industria de hidrocarburos l\u00edquidos en M\u00e9xico, que re\u00fane a empresarios gasolineros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T21:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"YC 25\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"YC 25\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/\"},\"author\":{\"name\":\"YC 25\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\"},\"headline\":\"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds\",\"datePublished\":\"2026-05-14T21:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/\"},\"wordCount\":730,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/\",\"name\":\"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\",\"datePublished\":\"2026-05-14T21:28:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/f0ec40c33447bbc0dc2d01d3006de771\",\"name\":\"YC 25\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g\",\"caption\":\"YC 25\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/editor25\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto","og_description":"La convenci\u00f3n re\u00fane a autoridades, empresarios y proveedores para analizar los retos del sector energ\u00e9tico y fortalecer oportunidades de inversi\u00f3n. El Gobernador Joaqu\u00edn D\u00edaz Mena inaugur\u00f3 la Convenci\u00f3n de la Organizaci\u00f3n Nacional de Expendedores de Petr\u00f3leo (Onexpo) 2026, el encuentro m\u00e1s grande de la industria de hidrocarburos l\u00edquidos en M\u00e9xico, que re\u00fane a empresarios gasolineros [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2026-05-14T21:28:56+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg","type":"image\/jpeg"}],"author":"YC 25","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"YC 25","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/"},"author":{"name":"YC 25","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771"},"headline":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds","datePublished":"2026-05-14T21:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/"},"wordCount":730,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/","name":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg","datePublished":"2026-05-14T21:28:56+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-14-at-15.21.44-scaled.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/onexpo-2026-reune-en-yucatan-a-la-industria-gasolinera-del-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Onexpo 2026 re\u00fane en Yucat\u00e1n a la industria gasolinera del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/f0ec40c33447bbc0dc2d01d3006de771","name":"YC 25","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20e0a6b626f38fa8e545fb3f80ce566efd790bf8877e65c3a482460cc3e0b5d1?s=96&d=mm&r=g","caption":"YC 25"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/editor25\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/117181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=117181"}],"version-history":[{"count":1,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/117181\/revisions"}],"predecessor-version":[{"id":117183,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/117181\/revisions\/117183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/117182"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=117181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=117181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=117181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}