{"id":69844,"date":"2021-01-31T12:12:16","date_gmt":"2021-01-31T18:12:16","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=69844"},"modified":"2021-01-31T12:12:16","modified_gmt":"2021-01-31T18:12:16","slug":"multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/","title":{"rendered":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto"},"content":{"rendered":"<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-69845\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\" alt=\"\" width=\"768\" height=\"432\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-696x392.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-1068x601.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-747x420.jpeg 747w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>M\u00e9rida, Yucat\u00e1n, 31 de enero de 2021.- Una multa de hasta 180,000 pesos podr\u00eda recibir el due\u00f1o de una casa en la playa de Chicxulub Puerto, en donde se realizaba una fiesta con m\u00e1s de 70 j\u00f3venes de entre 16 y 23 a\u00f1os de edad, quienes no respetaron las medidas sanitarias ante la pandemia del Coronavirus.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Como parte de los operativos de vigilancia sanitaria, elementos de las Secretar\u00edas de Salud de Yucat\u00e1n (SSY), de Seguridad P\u00fablica (SSP) y General de Gobierno, as\u00ed como de la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (Procivy) acudi\u00f3 a una casa de playa donde corrobor\u00f3 que la fiesta se llevaba a cabo sin las medidas y protocolos sanitarios, con la presencia de m\u00e1s de 70 personas, entre ellas menores de edad, quienes inger\u00edan bebidas alcoh\u00f3licas, por lo que se procedi\u00f3 a clausurar la reuni\u00f3n y a los menores se les dej\u00f3 ir.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Personal del Gobierno del Estado tambi\u00e9n clausur\u00f3 2 unidades deportivas, una en el municipio de Yaxkukul y la otra en Cholul, comisar\u00eda de M\u00e9rida, donde se llevaban a cabo un torneo de f\u00fatbol con la presencia de p\u00fablico y una visoria para detectar nuevos talentos infantiles y juveniles, actividades que tambi\u00e9n se encuentran suspendidas por la emergencia sanitaria. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Ambos espacios deportivos tambi\u00e9n podr\u00edan recibir una multa de hasta 180,000 pesos por incumplir con las disposiciones sanitarias.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En el caso de la unidad deportiva en el municipio de Yaxkukul, elementos de la SSP, SSY, Procivy y la SGG, clausuraron un torneo amateur que se llevaba a cabo con la presencia de p\u00fablico, cuando ligas y torneos se encuentran suspendidos por la contingencia sanitaria, ya que solo se ha reanudado la pr\u00e1ctica de deportes que no sean de contacto, ni de conjunto. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Mientras que, en la unidad deportiva Chivas M\u00e9rida de Cholul, personal del Gobierno estatal procedi\u00f3 a clausurar este sitio debido a que en \u00e9l se estaba desarrollando una jornada de visoria a ni\u00f1os y adolescentes menores de 16 a\u00f1os, acto que tambi\u00e9n congregaba a los padres de familia que acudieron en acompa\u00f1amiento. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Las acciones implementadas tienen la finalidad de salvaguardar la salud de los yucatecos en atenci\u00f3n al Acuerdo de Reactivaci\u00f3n Econ\u00f3mica Segura, conforme al sem\u00e1foro epidemiol\u00f3gico a fin de verificar el cumplimiento de dichas medidas sanitarias emitidas por las autoridades federales y estatales.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El Gobierno estatal reitera que se mantendr\u00e1 vigilante de que todos los negocios y establecimientos que est\u00e1n autorizados para operar dentro del Acuerdo de Reactivaci\u00f3n Econ\u00f3mica Segura cumplan con todas las disposiciones sanitarias, por lo que\u00a0\u00a0 seguir\u00e1 siendo firme y aplicar\u00e1 cero tolerancia para aquellos que atenten contra la salud de los yucatecos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 31 de enero de 2021.- Una multa de hasta 180,000 pesos podr\u00eda recibir el due\u00f1o de una casa en la playa de Chicxulub Puerto, en donde se realizaba una fiesta con m\u00e1s de 70 j\u00f3venes de entre 16 y 23 a\u00f1os de edad, quienes no respetaron las medidas sanitarias ante la pandemia del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-69844","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 31 de enero de 2021.- Una multa de hasta 180,000 pesos podr\u00eda recibir el due\u00f1o de una casa en la playa de Chicxulub Puerto, en donde se realizaba una fiesta con m\u00e1s de 70 j\u00f3venes de entre 16 y 23 a\u00f1os de edad, quienes no respetaron las medidas sanitarias ante la pandemia del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-31T18:12:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto\",\"datePublished\":\"2021-01-31T18:12:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/\",\"name\":\"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\",\"datePublished\":\"2021-01-31T18:12:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/","og_locale":"es_ES","og_type":"article","og_title":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 31 de enero de 2021.- Una multa de hasta 180,000 pesos podr\u00eda recibir el due\u00f1o de una casa en la playa de Chicxulub Puerto, en donde se realizaba una fiesta con m\u00e1s de 70 j\u00f3venes de entre 16 y 23 a\u00f1os de edad, quienes no respetaron las medidas sanitarias ante la pandemia del [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-01-31T18:12:16+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto","datePublished":"2021-01-31T18:12:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/"},"wordCount":492,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/","name":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg","datePublished":"2021-01-31T18:12:16+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/01\/6E6CCD2E-8890-448D-B384-DDBF4CB11716-scaled.jpeg","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/multa-de-hasta-180-mil-pesos-podria-recibir-casa-de-playa-en-donde-se-realizaba-fiesta-con-jovenes-en-chicxulub-puerto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Multa de hasta 180 mil pesos podr\u00eda recibir casa de playa en donde se realizaba fiesta con j\u00f3venes en Chicxulub Puerto"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/69844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=69844"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/69844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/69845"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=69844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=69844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=69844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}