{"id":69974,"date":"2021-02-06T19:33:19","date_gmt":"2021-02-07T01:33:19","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=69974"},"modified":"2021-02-06T19:33:19","modified_gmt":"2021-02-07T01:33:19","slug":"yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/","title":{"rendered":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus"},"content":{"rendered":"<div dir=\"ltr\">\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-69975\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\" alt=\"\" width=\"768\" height=\"435\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-696x394.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-741x420.jpeg 741w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>M\u00e9rida, Yucat\u00e1n, 6 de febrero de 2021.- Yucat\u00e1n es el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus, report\u00f3 el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) al presentar el estudio de Panorama de los programas y acciones sociales en las entidades federativas para dar respuesta a los efectos de la pandemia por el virus SARS-CoV-2 (COVID-19).<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El otorgamiento de cr\u00e9ditos, subsidios al empleo e incentivos fiscales dispuestos por el Gobernador Mauricio Vila Dosal para respaldar a las familias yucatecas frente a la contingencia, forman parte de las 20 intervenciones p\u00fablicas desarrolladas en este sentido que contribuyeron a colocar al estado como la entidad federativa con mayor n\u00famero de programas y acciones implementadas en materia de empleo formal frente a esta situaci\u00f3n.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) report\u00f3 que Yucat\u00e1n fue la entidad con el mayor n\u00famero de programas y acciones implementados en materia de empleo formal durante la contingencia sanitaria, al desarrollar 20 intervenciones p\u00fablicas que contemplan el otorgamiento de cr\u00e9ditos, subsidios al empleo e incentivos fiscales.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Dicha cifra duplic\u00f3 el total de apoyos entregados en el estado de Colima, entidad que ocupa la segunda posici\u00f3n nacional, lo que demuestra el importante impulso que el Gobierno de Vila Dosal brinda al cuidado de las fuentes de trabajo, especialmente durante la pandemia del Coronavirus.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Por lo que al tema de vivienda toca, el Coneval destac\u00f3 que Yucat\u00e1n, junto con Quintana Roo, fue la entidad con el mayor n\u00famero de programas de esta \u00edndole implementados, ya que representan el 20% del total nacional.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En el mismo sentido, se se\u00f1al\u00f3 que s\u00f3lo 11 entidades federativas realizaron, al menos, una acci\u00f3n para atender el tema de vivienda durante la emergencia sanitaria, entre las cuales se identificaron 22 acciones o programas implementados en todo el pa\u00eds.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Adem\u00e1s, Yucat\u00e1n se ubic\u00f3 en la segunda posici\u00f3n nacional, junto con Puebla, entre las entidades federativas con mayor n\u00famero de programas de protecci\u00f3n al empleo creados, con 9 dirigidos a este fin, es decir, el 45% del total de 20 intervenciones.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En documento dado a conocer recientemente se analizan las intervenciones gubernamentales estatales para identificar qu\u00e9 tipo de respuesta se est\u00e1 dando a las prioridades sociales que surgen en esta emergencia sanitaria en los 32 estados.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Como parte del an\u00e1lisis, el Coneval resalta la importancia de monitorear y evaluar los avances, resultados e identificar oportunidades de mejora de las acciones implementadas. En este sentido, Yucat\u00e1n fue la entidad con el mayor porcentaje de programas y acciones que cuentan con indicadores p\u00fablicos (66.7%), y, junto con Tlaxcala, fue la entidad que public\u00f3 la totalidad de las evaluaciones realizada a dichos programas sociales COVID-19, ya que, del 70.4% de los programas evaluados, todos cuentan con un informe de evaluaci\u00f3n p\u00fablico.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Cabe resaltar que el Gobierno de Vila Dosal implement\u00f3 el Plan Estatal para impulsar la Econom\u00eda, los Empleos y la Salud de los yucatecos, el cual se conform\u00f3 de diversos programas, como el de Seguro de Desempleo, a trav\u00e9s del cual se otorgaron 46, 106 apoyos con una inversi\u00f3n superior a los 230 millones de pesos.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">De manera complementaria, se otorgaron incentivos fiscales a 14,347 contribuyentes mediante la publicaci\u00f3n del decreto 196\/2020, a trav\u00e9s del cual se redujo, en diversos meses, un 100% de los impuestos: cedular sobre la obtenci\u00f3n de ingresos por actividades empresariales, sobre el ejercicio profesional, el adicional para la ejecuci\u00f3n de obras materiales y asistencia social, sobre hospedaje, entre otros, todo ello con el objetivo de respaldar las fuentes de empleos de los yucatecos.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Y para apoyar a las Micro, Peque\u00f1as y Medianas Empresas (Mipymes) y emprendedores del estado, se fortaleci\u00f3 la entrega de cr\u00e9ditos a trav\u00e9s del programa \u201cMicroyuc\u201d en sus diversas modalidades y se otorgaron m\u00e1s de 4 mil cr\u00e9ditos, cifra que representa 400% m\u00e1s que los apoyos entregados en 2019. Asimismo, se realiz\u00f3 un convenio con la banca de desarrollo Nafin para contar con una l\u00ednea de cr\u00e9dito de m\u00e1s de 2 mil millones de pesos.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Otro programa de apoyo durante la contingencia sanitaria fue el subsidio, durante el bimestre de abril a mayo, del 50% de los recibos de energ\u00eda el\u00e9ctrica, con el que se entregaron 507,471 apoyos por un monto de m\u00e1s de 31 millones de pesos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 6 de febrero de 2021.- Yucat\u00e1n es el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus, report\u00f3 el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) al presentar el estudio de Panorama de los programas y acciones sociales en las entidades federativas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-69974","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 6 de febrero de 2021.- Yucat\u00e1n es el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus, report\u00f3 el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) al presentar el estudio de Panorama de los programas y acciones sociales en las entidades federativas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-07T01:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus\",\"datePublished\":\"2021-02-07T01:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/\"},\"wordCount\":762,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/\",\"name\":\"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\",\"datePublished\":\"2021-02-07T01:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg\",\"width\":768,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 6 de febrero de 2021.- Yucat\u00e1n es el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus, report\u00f3 el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval) al presentar el estudio de Panorama de los programas y acciones sociales en las entidades federativas [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-02-07T01:33:19+00:00","og_image":[{"width":768,"height":435,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus","datePublished":"2021-02-07T01:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/"},"wordCount":762,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/","name":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg","datePublished":"2021-02-07T01:33:19+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/BD445E52-9AA1-427A-8F71-E60FD3CDA8A5-scaled.jpeg","width":768,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-el-estado-que-mas-apoyos-le-dio-a-la-gente-durante-la-contingencia-sanitaria-por-el-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Yucat\u00e1n, el estado que m\u00e1s apoyos le dio a la gente durante la contingencia sanitaria por el Coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/69974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=69974"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/69974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/69975"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=69974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=69974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=69974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}