{"id":70147,"date":"2021-02-17T20:57:12","date_gmt":"2021-02-18T02:57:12","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=70147"},"modified":"2021-02-17T20:57:12","modified_gmt":"2021-02-18T02:57:12","slug":"el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/","title":{"rendered":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial"},"content":{"rendered":"<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-70148\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-696x464.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-630x420.jpeg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>M\u00e9rida, Yucat\u00e1n, 17 de febrero de 2021.- Docentes afiliados a la secciones 33 y 57 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE) solicitaron al Gobierno del Estado realice las gestiones correspondientes ante la Federaci\u00f3n para que \u00e9sta destine los recursos necesarios al programa federal \u201cEscuelas de Tiempo Completo\u201d en Yucat\u00e1n, con el fin de atender las necesidades del sector magisterial y mejorar las condiciones de la ense\u00f1anza para cuando, las condiciones epidemiol\u00f3gicas de la pandemia del Coronavirus lo permitan, las clases vuelvan a ser presenciales.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Desde el presente a\u00f1o, el Programa de Escuelas de Tiempo Completo (PETC) fue incluido en el esquema de trabajo del programa federal denominado La Escuela es Nuestra y la designaci\u00f3n de sus recursos y operatividad depende en su totalidad al gobierno federal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Por instrucciones del Gobernador Mauricio Vial Dosal, el subsecretario de Desarrollo Social y Asuntos Religiosos del Gobierno del Estado, V\u00edctor Hugo Lozano Poveda, se reuni\u00f3 con el delegado especial de la secci\u00f3n 57, Jes\u00fas Jaime Rochin Carrillo y el secretario general de la secci\u00f3n 33 del SNTE, Ricardo Francisco Espinosa Maga\u00f1a, quienes expresaron su confianza en las autoridades estatales para hacer las gestiones ante el Gobierno federal y obtener una respuesta favorable.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En el encuentro, los dirigentes sindicales destacaron la relaci\u00f3n institucional que ha existido con el Gobierno del Estado, ya que siempre se ha mostrado sensibilidad y apertura al di\u00e1logo sobre esta problem\u00e1tica, a fin de encontrar una soluci\u00f3n de manera conjunta, al tiempo que coment\u00f3 que esta misma solicitud la hicieron este d\u00eda al Congreso del Estado, para que \u201cjuntos los Poderes Ejecutivo y Legislativo, junto con el SNTE, podamos caminar mejor\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Al respecto, Lozano Poveda reiter\u00f3 que el compromiso del Gobernador Vila Dosal es buscar todas las opciones y mecanismos necesarios para atender este este tema, que es de vital importancia para el magisterio y tambi\u00e9n para las autoridades estatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cLos hemos puesto en antecedente de los recortes presupuestales que ha sufrido Yucat\u00e1n, por lo que es muy importante que unamos esfuerzos para generar di\u00e1logo que sea propositivo y que nos lleve a alcanzar acuerdos importantes a nivel nacional y estatal, para poder beneficiar la calidad de vida y de educaci\u00f3n de las ni\u00f1as, ni\u00f1os y adolescentes del estado\u201d expres\u00f3 el funcionario estatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El subsecretario de Desarrollo Social y Asuntos Religiosos expres\u00f3 su confianza en que esta petici\u00f3n del magisterio yucateco tambi\u00e9n sea tomada en cuenta por los diputados locales para poder generar un punto de acuerdo haciendo una solicitud a la Federaci\u00f3n para la obtenci\u00f3n de los recursos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Lozano Poveda reiter\u00f3 la disposici\u00f3n del Gobierno del Estado a escuchar y dialogar con todos los sectores, en este caso con el magisterial, siempre con el \u00e1nimo de construir buenas relaciones y encontrar soluciones, sobre todo cuando se trata de quienes educan a nuestros ni\u00f1os, \u201cpor lo que consideramos importante atender sus demandas y sumar esfuerzos para alcanzar objetivos tan claros como el que se nos est\u00e1 planteando\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cSiempre es importante que se generen las v\u00edas de comunicaci\u00f3n adecuadas, para que sigamos teniendo en Yucat\u00e1n la paz social que nos caracteriza, y, en este caso, que los maestros y las maestras de Yucat\u00e1n sientan el respaldo permanente del Gobierno del Estado\u201d, finaliz\u00f3 el funcionario estatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">A su vez, Rochin Carrillo record\u00f3 que en el ciclo escolar pasado las escuelas de Tiempo Completo se vieron afectadas por el impacto de la pandemia, por lo que, a trav\u00e9s de una estrategia conjunta entre la Secretar\u00eda de Educaci\u00f3n del estado y la organizaci\u00f3n sindical se logr\u00f3 resolver un tema de dimensiones similares.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cReconocemos el trabajo que se est\u00e1 realizando desde el Gobierno estatal sobre este tema. Entonces, ahora estamos seguros que con esa misma voluntad que ha manifestado el Gobierno del Estado, aunque hay que mencionar que no es un tema privativo de esta entidad, nosotros esperamos que con estas gestiones que se realizar\u00e1n, pronto tengamos una respuesta favorable\u201d, extern\u00f3 el l\u00edder sindical.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 17 de febrero de 2021.- Docentes afiliados a la secciones 33 y 57 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE) solicitaron al Gobierno del Estado realice las gestiones correspondientes ante la Federaci\u00f3n para que \u00e9sta destine los recursos necesarios al programa federal \u201cEscuelas de Tiempo Completo\u201d en Yucat\u00e1n, con el fin [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":70148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-70147","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 17 de febrero de 2021.- Docentes afiliados a la secciones 33 y 57 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE) solicitaron al Gobierno del Estado realice las gestiones correspondientes ante la Federaci\u00f3n para que \u00e9sta destine los recursos necesarios al programa federal \u201cEscuelas de Tiempo Completo\u201d en Yucat\u00e1n, con el fin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-18T02:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial\",\"datePublished\":\"2021-02-18T02:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/\"},\"wordCount\":713,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/\",\"name\":\"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\",\"datePublished\":\"2021-02-18T02:57:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 17 de febrero de 2021.- Docentes afiliados a la secciones 33 y 57 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE) solicitaron al Gobierno del Estado realice las gestiones correspondientes ante la Federaci\u00f3n para que \u00e9sta destine los recursos necesarios al programa federal \u201cEscuelas de Tiempo Completo\u201d en Yucat\u00e1n, con el fin [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-02-18T02:57:12+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial","datePublished":"2021-02-18T02:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/"},"wordCount":713,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/","name":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg","datePublished":"2021-02-18T02:57:12+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/8E3ED1C6-E854-4AA5-8A01-326BD90C6427-scaled.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-gobierno-del-estado-reitera-su-compromiso-de-escuchar-y-atender-los-planteamientos-del-sector-magisterial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"El Gobierno del Estado reitera su compromiso de escuchar y atender los planteamientos del sector magisterial"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/70147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=70147"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/70147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/70148"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=70147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=70147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=70147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}