{"id":70158,"date":"2021-02-18T18:15:01","date_gmt":"2021-02-19T00:15:01","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=70158"},"modified":"2021-02-18T18:15:01","modified_gmt":"2021-02-19T00:15:01","slug":"inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/","title":{"rendered":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY)"},"content":{"rendered":"<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-70159\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-696x464.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-1068x712.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-630x420.jpeg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>Uc\u00fa, Yucat\u00e1n, 18 de febrero de 2021.- Yucat\u00e1n cuenta con infraestructura educativa equipada con tecnolog\u00eda de primer mundo y lo m\u00e1s avanzado en dise\u00f1o digital para contribuir a la especializaci\u00f3n de recursos humanos en capacidades tecnol\u00f3gicas enfocado a la industria aeron\u00e1utica y la industria 4.0, con el nuevo Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital que inaugur\u00f3 el Gobernador Mauricio Vila Dosal para mayor atracci\u00f3n de inversiones y mejor competitividad laboral para los yucatecos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Como resultado de la cooperaci\u00f3n entre el Gobierno de M\u00e9xico y Francia, en el marco de la Agenda Estrat\u00e9gica para el desarrollo de la industria Aeron\u00e1utica, a trav\u00e9s de la Red Nacional de Laboratorios para la Innovaci\u00f3n y el Dise\u00f1o Digital, en todo el pa\u00eds se instalar\u00e1n 8 Laboratorios Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El Presidente de la Confederaci\u00f3n Nacional de C\u00e1maras Industriales de la Rep\u00fablica Mexicana (CONCAMIN), Francisco Cervantes D\u00edaz indic\u00f3 que, con este avance en el estudio de nuevas tecnolog\u00edas, pone un ejemplo no s\u00f3lo en la parte sur-sureste sino a nivel nacional de hacer una transformaci\u00f3n en la entidad.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u00a0\u201cFelicitamos a ambas instancias del Gobierno por este esfuerzo coordinado que permitir\u00e1 a los j\u00f3venes de la entidad a acceder a una oferta de educaci\u00f3n de muy alta calidad y pertinencia ya que el dise\u00f1o y modelo 3D, la simulaci\u00f3n, la manufactura digital y la validaci\u00f3n de productos de realidad virtual, adem\u00e1s de que son poderosas palancas de aceleraci\u00f3n a la innovaci\u00f3n son precisamente los campos de especialidad que est\u00e1n siendo requeridos por las empresas de Yucat\u00e1n y de M\u00e9xico para competir exitosamente en mercados de alta complejidad como es el caso de la industria aeron\u00e1utica y automotriz\u201d, se\u00f1al\u00f3. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">De estos 8, Yucat\u00e1n contar\u00e1 con dos: uno en la UPY, enfocado en la industria 4.0, y otro se encontrar\u00e1 en la Universidad Tecnol\u00f3gica Metropolitana (UTM) donde acuden estudiantes originarios de 85 municipios del estado, convirtiendo a Yucat\u00e1n en una de las dos entidades en todo el pa\u00eds que tiene dos Laboratorios Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Al dirigirse a los asistentes, Vila Dosal se\u00f1al\u00f3 que Yucat\u00e1n es una entidad con grandes posibilidades de ser un actor en el tema de atracci\u00f3n de inversiones ya que cuenta con cualidades como calidad de vida, seguridad, pero tambi\u00e9n hay mucho talento y es importante que nuestros j\u00f3venes puedan tener la oportunidad de capacitarse en estos laboratorios con las m\u00e1s altas tecnolog\u00edas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cCuando viene una empresa a querer invertir en M\u00e9xico y empieza a ver diferentes estados, pues es l\u00f3gico que piensa en la calidad de vida, en las facilidades, en los incentivos, pero el principal punto de decisi\u00f3n siempre es la mano de obra y, por supuesto, qu\u00e9 tan calificada es. Y estos laboratorios van a permitir que aqu\u00ed en Yucat\u00e1n podamos contar con la mano de obra m\u00e1s calificada del pa\u00eds por lo que quiero agradecer la visi\u00f3n que tuvo la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP), pues no solamente para desarrollar este programa que se va a estar realizando en 8 estados de la Rep\u00fablica\u00bb, se\u00f1al\u00f3 el Gobernador. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En este marco, Mauricio Vila se\u00f1al\u00f3 que para poder cerrar esa brecha es el tema de la infraestructura. Mucho se ha hablado del tema de la suficiencia energ\u00e9tica de la pen\u00ednsula de Yucat\u00e1n, del gas natural, y son temas en los que estamos trabajando de la mano del Gobierno federal, son temas que estamos trabajando con CONCAMIN, que estamos trabajando con las c\u00e1maras empresariales porque, sin duda, es algo que tenemos que lograr y pronto, extern\u00f3. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u00abCon el Gobierno federal, hemos anunciado 2 plantas de ciclo combinado nuevas, una que se va a instalar en M\u00e9rida, la M\u00e9rida IV, otra que se va a instalar en Valladolid; el Presidente debe estar aqu\u00ed en marzo y tambi\u00e9n ya viene con el \u00edmpetu de poder iniciar los trabajos\u00bb. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Otro tema important\u00edsimo, continu\u00f3, es el tema del gas natural, que poco a poco se est\u00e1 logrando aumentar la capacidad que est\u00e1 llegando a Yucat\u00e1n, a trav\u00e9s de diversas obras que se han hecho en Cempoala, con la recepci\u00f3n del ducto mar\u00edtimo que viene de Texas, y por supuesto, tambi\u00e9n con las adaptaciones de ductos que se van a hacer pr\u00f3ximamente aqu\u00ed, en Yucat\u00e1n, asegur\u00f3 el Gobernador. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En presencia del Presidente de la Confederaci\u00f3n de C\u00e1maras Nacionales de Comercio, Servicios y Turismo (CONCANACO SERVYTUR), Jos\u00e9 Manuel L\u00f3pez Campos, Mauricio Vila asegur\u00f3 que el sector aeron\u00e1utico se ha vuelto prioritario y cada vez m\u00e1s demandante para los j\u00f3venes, ya que, de verdad, no es s\u00f3lo ser expertos en las \u00e1reas de especialidad de aeron\u00e1utica en que participen, sino que tambi\u00e9n ser h\u00e1biles para el trabajo multidisciplinario y de ingenier\u00eda concurrente; dominar las herramientas de dise\u00f1o, uso de plataformas colaborativas y los sistemas de gesti\u00f3n.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Para ambos laboratorios se realiz\u00f3 una inversi\u00f3n conjunta, de m\u00e1s de 31 millones de pesos en ambos laboratorios en la UPY y la UTM, en la que 15 millones de pesos, se destinaron para la construcci\u00f3n y equipamiento del Laboratorio Acad\u00e9mico, y para poder adquirir mobiliario, equipo especializado y licencias de software.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Adem\u00e1s, se incluy\u00f3 la capacitaci\u00f3n de docentes en 9 cursos, por 360 horas, no solamente de la Polit\u00e9cnica, sino tambi\u00e9n de otras instituciones. Estos Laboratorios consisten en 2 espacios: el de formaci\u00f3n, para albergar a 20 personas al mismo tiempo, y el de certificaci\u00f3n, que es para 8 personas de manera simult\u00e1nea.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El Gobernador tambi\u00e9n se\u00f1al\u00f3 que est\u00e1 en construcci\u00f3n en la Universidad Polit\u00e9cnica de Yucat\u00e1n, el edificio administrativo, en su primera etapa, que albergar\u00e1 la Rector\u00eda de la Universidad, la Direcci\u00f3n Administrativa y la Secretar\u00eda Acad\u00e9mica, con una inversi\u00f3n de 16 millones de pesos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u00abDe esta forma, debo agradecer a todas las partes que se han visto involucradas para poder hacer esto posible, ya que son muestra de que el di\u00e1logo y la coordinaci\u00f3n son, sin duda, lo que nos permite dar resultados; particularmente, agradecer a los representantes del Gobierno federal, as\u00ed como tambi\u00e9n el trabajo conjunto con el sector privado, ya que todos buscamos lo mismo: tener un mejor Yucat\u00e1n\u00bb, asever\u00f3. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En un recuento de las empresas aeron\u00e1uticas que se han decidido por Yucat\u00e1n, el Gobernador mencion\u00f3 a la empresa PCC Airfools, que ha invertido m\u00e1s de 300 millones de pesos en el estado; a m\u00ed me ha tocado visitarlos en varias ocasiones, y ya est\u00e1n generando alrededor de 800 empleos directos y 3,000 empleos indirectos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Por su parte, tambi\u00e9n la empresa espa\u00f1ola Deimos, de Grupo Elecnor, firm\u00f3 una carta de intenci\u00f3n con el Gobierno de Yucat\u00e1n, para instalar un centro tecnol\u00f3gico para la construcci\u00f3n de sat\u00e9lites de comunicaci\u00f3n e investigaci\u00f3n, la cual es una inversi\u00f3n aproximada de 130 millones de d\u00f3lares, que esperemos que se pueda concretar en los pr\u00f3ximos meses.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Estas inversiones son posibles, por supuesto, gracias a la din\u00e1mica que hoy se vive en Yucat\u00e1n, con condiciones favorables para la inversi\u00f3n, que no se dan en otros lugares del pa\u00eds, como es la calidad de vida; la seguridad; la conectividad por v\u00eda terrestre, ferroviaria, a\u00e9rea, mar\u00edtima, y cada vez un mejor capital humano, lo que coloca a nuestro estado como un destino muy atractivo para poder colocar inversiones, se\u00f1al\u00f3 Vila Dosal. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Destaca que, durante la actual administraci\u00f3n, se han anunciado inversiones por m\u00e1s de 86,448 millones de pesos, que van a estar generando miles de empleos en los pr\u00f3ximos a\u00f1os en la entidad.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Al finalizar, Vila Dosal se\u00f1al\u00f3 que, con toda seguridad, estos espacios ser\u00e1n de gran utilidad para hacer m\u00e1s estrecha la relaci\u00f3n entre M\u00e9xico y, especialmente, Yucat\u00e1n, con Francia, y atraer inversiones provenientes del sector aeron\u00e1utico, que beneficien a la poblaci\u00f3n yucateca.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En su turno, el Secretario de Investigaci\u00f3n, Innovaci\u00f3n y Educaci\u00f3n Superior del Estado de Yucat\u00e1n (SIIES), Bernardo Cisneros Buenfil, asegur\u00f3 que ambos nuevos Laboratorios generar\u00e1n muchos beneficios al estado al contar con herramientas funcionales para generar mayor valor en la capacitaci\u00f3n de los estudiantes yucatecos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cEl Gobernador siempre nos ha pedido trabajar en la generaci\u00f3n de condiciones para poner a Yucat\u00e1n como un sitio id\u00f3neo para la inversi\u00f3n extranjera y nacional, y una parte central es la construcci\u00f3n\u00a0 de talento, hoy m\u00e1s que nunca estamos convencidos de que la inversi\u00f3n sigue al talento y estos laboratorios sin duda ayudar\u00e1n a que los j\u00f3venes de Yucat\u00e1n cuenten el d\u00eda de ma\u00f1ana con el conocimiento y capacidades de hacer actividades de mucho valor agregado que representen a la larga extraordinarias oportunidades para su desarrollo\u201d, asegur\u00f3 el funcionario estatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Por su parte, el exembajador franc\u00e9s y actual CEO de Grupo Safran en M\u00e9xico, Daniel Parfait, destac\u00f3 los beneficios que traer\u00e1 a los j\u00f3venes yucatecos contar con los espacios y herramientas innovadoras para su preparaci\u00f3n que los convertir\u00e1 en los expertos del ma\u00f1ana. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cLa tecnolog\u00eda como todos sabemos avanza a pasos agigantados, los ciclos de desarrollo producci\u00f3n, mantenimiento y vida de nuestros productos espaciales son constantes y para el curso de innovaci\u00f3n es necesaria la correcta capacitaci\u00f3n del personal, eso es pieza clave. Es por ello que esta iniciativa es concreta y necesaria para dotar a los j\u00f3venes yucatecos de conocimientos \u00fanicos para dominar esos instrumentos m\u00e1s nuevos para enfrentar los retos t\u00e9cnicos del ma\u00f1ana. Felicito al Gobierno del Estado y Gobierno de la Rep\u00fablica que supieron impulsar este nuevo laboratorio\u201d, asever\u00f3. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Al tomar la palabra el Director General de Universidades Tecnol\u00f3gicas y Polit\u00e9cnicas, Herminio Baltazar Cisneros, puntualiz\u00f3 que, en M\u00e9xico actualmente se cuentan m\u00e1s de 350 empresas del sector aeroespacial distribuidas en 20 estados de la Rep\u00fablica que generan m\u00e1s de 65,000 puestos directos de trabajo y la exportaci\u00f3n en ese sector al cierre de 2019 fue de unos 9,700 millones de d\u00f3lares. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cEs as\u00ed como tenemos una inversi\u00f3n de m\u00e1s de 150 millones de pesos para instalar un Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital en 8 universidades polit\u00e9cnicas y tecnol\u00f3gicas que han demostrado una profunda consciencia en los problemas y necesidades del pa\u00eds, por lo que la instalaci\u00f3n de estos Laboratorios es una muestra de ello, en estos momentos de pandemia es importante apostar por la formaci\u00f3n e profesionales en estos ramos para trascender en una perspectiva m\u00e1s general de conocimiento y favorecer el pensamiento cr\u00edtico que considere la innovaci\u00f3n tecnol\u00f3gica y cient\u00edfica estrechamente vinculada con la comunidad sin olvidar que el empleo en tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n deben tener un sentido profundamente humano\u201d, asegur\u00f3. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Posteriormente, Vila Dosal realiz\u00f3 la develaci\u00f3n de la placa conmemorativa del Laboratorio y realiz\u00f3 un recorrido en el que constat\u00f3 el funcionamiento del Laboratorio que se centra en el concepto de continuidad digital, lo que contempla el espectro de pasar del mundo f\u00edsico al mundo digital a trav\u00e9s de la ingenier\u00eda inversa.\u00a0 <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Durante su traslado por el Laboratorio y las Aulas de Certificaci\u00f3n, el Gobernador observ\u00f3 actividades en materia de Dise\u00f1o digital, Ingenier\u00eda inversa, Validaci\u00f3n por realidad virtual e Impresi\u00f3n 3D de prototipos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">A trav\u00e9s de una inversi\u00f3n de m\u00e1s de 31 millones de pesos en ambos laboratorios del estado, se adquirieron mobiliario, equipo especializado, licencias de software y se incluy\u00f3 la capacitaci\u00f3n de docentes. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El proyecto consiste de dos espacios: el \u00c1rea de formaci\u00f3n y el \u00c1rea de Certificaci\u00f3n. El \u00e1rea de formaci\u00f3n es un espacio para entrenar hasta 20 personas, seis sistemas de energ\u00eda ininterrumpida, veinte estaciones de trabajo de alto desempe\u00f1o (workstations), un sistema de realidad virtual, tres esc\u00e1neres 3D, tres impresoras 3D, y el licenciamiento de la plataforma 3D Experience de Dassault Systems. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">En tanto, en el \u00e1rea de certificaci\u00f3n pueden presentar los ex\u00e1menes de certificaci\u00f3n hasta ocho personas simult\u00e1neamente. Lo que se eval\u00faa es la competencia en el adecuado uso de la plataforma de dise\u00f1o 3D Experience de Dassault Systems.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uc\u00fa, Yucat\u00e1n, 18 de febrero de 2021.- Yucat\u00e1n cuenta con infraestructura educativa equipada con tecnolog\u00eda de primer mundo y lo m\u00e1s avanzado en dise\u00f1o digital para contribuir a la especializaci\u00f3n de recursos humanos en capacidades tecnol\u00f3gicas enfocado a la industria aeron\u00e1utica y la industria 4.0, con el nuevo Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":70159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-70158","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Uc\u00fa, Yucat\u00e1n, 18 de febrero de 2021.- Yucat\u00e1n cuenta con infraestructura educativa equipada con tecnolog\u00eda de primer mundo y lo m\u00e1s avanzado en dise\u00f1o digital para contribuir a la especializaci\u00f3n de recursos humanos en capacidades tecnol\u00f3gicas enfocado a la industria aeron\u00e1utica y la industria 4.0, con el nuevo Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T00:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY)\",\"datePublished\":\"2021-02-19T00:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/\"},\"wordCount\":2185,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/\",\"name\":\"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\",\"datePublished\":\"2021-02-19T00:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/","og_locale":"es_ES","og_type":"article","og_title":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto","og_description":"Uc\u00fa, Yucat\u00e1n, 18 de febrero de 2021.- Yucat\u00e1n cuenta con infraestructura educativa equipada con tecnolog\u00eda de primer mundo y lo m\u00e1s avanzado en dise\u00f1o digital para contribuir a la especializaci\u00f3n de recursos humanos en capacidades tecnol\u00f3gicas enfocado a la industria aeron\u00e1utica y la industria 4.0, con el nuevo Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-02-19T00:15:01+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY)","datePublished":"2021-02-19T00:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/"},"wordCount":2185,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/","name":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY) - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg","datePublished":"2021-02-19T00:15:01+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/02\/58D0C898-4EC4-47CB-8780-9A9FC33AA9A9-scaled.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inauguran-el-laboratorio-academico-de-innovacion-diseno-y-manufactura-digital-de-la-universidad-politecnica-de-yucatan-upy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Inauguran el Laboratorio Acad\u00e9mico de Innovaci\u00f3n, Dise\u00f1o y Manufactura Digital de la Universidad Polit\u00e9cnica de Yucat\u00e1n (UPY)"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/70158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=70158"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/70158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/70159"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=70158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=70158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=70158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}