{"id":72590,"date":"2021-05-13T14:11:48","date_gmt":"2021-05-13T19:11:48","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=72590"},"modified":"2021-05-13T14:11:48","modified_gmt":"2021-05-13T19:11:48","slug":"renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/","title":{"rendered":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div dir=\"ltr\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-72591\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--696x464.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--1068x712.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e9rida, 13 de mayo de 2021. En aras de rescatar y reintegrar los espacios dedicados a mejorar el desarrollo de las y los meridanos de manera integral, el candidato del PAN a la Presidencia Municipal, Ren\u00e1n Barrera Concha, present\u00f3 su propuesta para crear los Centros M\u00e9rida Aprende (CEMAS)<\/p>\n<\/div>\n<div dir=\"ltr\">\n<p>\u201cEste proyecto consiste en el rescate de edificios p\u00fablicos, transform\u00e1ndolos en espacios de calidad para actividades l\u00fadicas, culturales, deportivas, de desarrollo personal y cuidado de la salud\u201d, dijo.<\/p>\n<p>Subray\u00f3 que esos centros fortalecer\u00e1n el encuentro y la colaboraci\u00f3n de la comunidad en distintos puntos de M\u00e9rida, impulsando el bienestar colectivo de una ciudad incluyente y participativa.<\/p>\n<p>Acompa\u00f1ado de V\u00edctor Hugo Lozano, candidato a diputado local por el IV Distrito y Gabriela Baqueiro, candidata a regidora, el aspirante panista indic\u00f3 que los CEMAS apuntan a tejer una red de transformaci\u00f3n social en la ciudad, para el encuentro y bienestar de todos los ciudadanos, focalizando las necesidades de cada zona para ofrecer lo que realmente sea de inter\u00e9s y utilidad para las personas que ah\u00ed habiten.<\/p>\n<p>Mencion\u00f3 que en la actualidad M\u00e9rida cuenta con un promedio de 50 espacios de aprendizaje por cada 100 mil habitantes, de ah\u00ed la necesidad de crecer este n\u00famero de espacios que har\u00e1n del municipio un lugar m\u00e1s incluyente.<\/p>\n<p>\u201cVamos a evolucionar con programas que se ofrecer\u00e1n a trav\u00e9s plataformas digitales, que armonicen y pongan al alcance de la ciudadan\u00eda todo lo que requiera la comunidad\u201d, expres\u00f3.<\/p>\n<p>Remarc\u00f3 que en esos espacios todas y todos tendr\u00e1n la oportunidad de desarrollar sus capacidades y talentos, podr\u00e1n aprender nuevos oficios o simplemente convivir como comunidad, siendo solidarios y participativos.<\/p>\n<p>Adem\u00e1s, en esos espacios tendr\u00e1n acceso a atenci\u00f3n m\u00e9dica y a la cultura, asegur\u00f3.<\/p>\n<p>El abanderado de Acci\u00f3n Nacional indic\u00f3 que impulsar este tipo de proyectos, en los que se prioriza la convivencia arm\u00f3nica, abona a que M\u00e9rida se mantenga como una ciudad que destaca por su calidad de vida, inclusi\u00f3n y seguridad.<\/p>\n<p>Asegur\u00f3 que los Centros M\u00e9rida Aprende ser\u00e1n el motor para continuar cambiando el Municipio a trav\u00e9s de la reconversi\u00f3n de espacios y unificaci\u00f3n de tareas.<\/p>\n<p>\u201cDebemos hacer viable nuestro desarrollo como sociedad, nosotros facilitaremos los espacios que estar\u00e1n a disposici\u00f3n de quienes decidan utilizarlos, siempre y cuando aporte beneficios que permitan seguir construyen M\u00e1s M\u00e9rida\u201d, indic\u00f3.<\/p>\n<p>\u201cSeguiremos construyendo una ciudad que facilite la sana convivencia y la colaboraci\u00f3n, ya que de esta forma podemos superar cualquier reto y alcanzar todas nuestras metas\u201d, finaliz\u00f3.<\/p>\n<p>En la presentaci\u00f3n tambi\u00e9n estuvieron presentes Ang\u00e9lica Couoh, alumna del taller de belleza y barber\u00eda del Centro de Desarrollo Integral Reforma Integral; Gilberto Us, alumno avanzado del taller de cocina y reposter\u00eda del Centro de Desarrollo Integral Lindavista: Luis Segura, alumno de taller de manualidades del Centro de Desarrollo Integral Chuburn\u00e1 y Paola Chac\u00f3n, alumna de taller de corte y confecci\u00f3n del Centro de Desarrollo Integral Vergel.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; M\u00e9rida, 13 de mayo de 2021. En aras de rescatar y reintegrar los espacios dedicados a mejorar el desarrollo de las y los meridanos de manera integral, el candidato del PAN a la Presidencia Municipal, Ren\u00e1n Barrera Concha, present\u00f3 su propuesta para crear los Centros M\u00e9rida Aprende (CEMAS) \u201cEste proyecto consiste en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":72591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-72590","post","type-post","status-publish","format-standard","has-post-thumbnail","category-merida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; M\u00e9rida, 13 de mayo de 2021. En aras de rescatar y reintegrar los espacios dedicados a mejorar el desarrollo de las y los meridanos de manera integral, el candidato del PAN a la Presidencia Municipal, Ren\u00e1n Barrera Concha, present\u00f3 su propuesta para crear los Centros M\u00e9rida Aprende (CEMAS) \u201cEste proyecto consiste en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T19:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende\",\"datePublished\":\"2021-05-13T19:11:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/\"},\"wordCount\":536,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Renan-1--scaled.jpg\",\"articleSection\":[\"M\u00e9rida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/\",\"name\":\"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Renan-1--scaled.jpg\",\"datePublished\":\"2021-05-13T19:11:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Renan-1--scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Renan-1--scaled.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/","og_locale":"es_ES","og_type":"article","og_title":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto","og_description":"&nbsp; &nbsp; &nbsp; M\u00e9rida, 13 de mayo de 2021. En aras de rescatar y reintegrar los espacios dedicados a mejorar el desarrollo de las y los meridanos de manera integral, el candidato del PAN a la Presidencia Municipal, Ren\u00e1n Barrera Concha, present\u00f3 su propuesta para crear los Centros M\u00e9rida Aprende (CEMAS) \u201cEste proyecto consiste en [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-05-13T19:11:48+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende","datePublished":"2021-05-13T19:11:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/"},"wordCount":536,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg","articleSection":["M\u00e9rida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/","name":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg","datePublished":"2021-05-13T19:11:48+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/05\/Renan-1--scaled.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-candidato-por-la-alcaldia-de-merida-presenta-su-propuesta-centros-merida-aprende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Ren\u00e1n Barrera candidato por la alcald\u00eda de M\u00e9rida presenta su propuesta Centros M\u00e9rida Aprende"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/72590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=72590"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/72590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/72591"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=72590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=72590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=72590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}