{"id":85444,"date":"2021-08-04T19:46:23","date_gmt":"2021-08-05T00:46:23","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=85444"},"modified":"2021-08-04T19:46:23","modified_gmt":"2021-08-05T00:46:23","slug":"el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/","title":{"rendered":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85445\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg 640w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera-630x420.jpg 630w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">M\u00e9rida, 4 de agosto de 2021. La planeaci\u00f3n de nuestra ciudad es un tema fundamental para alcanzar el desarrollo humano y trabajando de la mano, en alianzas con la propia sociedad, podremos seguir construyendo una ciudad con una visi\u00f3n a largo plazo, afirm\u00f3 el alcalde Ren\u00e1n Barrera Concha.<\/p>\n<p style=\"text-align: justify;\">El Concejal presidi\u00f3 esta ma\u00f1ana la \u00faltima sesi\u00f3n de la Junta Directiva del Instituto Municipal de Planeaci\u00f3n de M\u00e9rida, en el marco del s\u00e9ptimo aniversario de la creaci\u00f3n de este instituto, en la cual se rindi\u00f3 un informe general de las actividades realizadas durante la administraci\u00f3n 2018-2021.<\/p>\n<p style=\"text-align: justify;\">Ante representantes de instituciones de educaci\u00f3n superior, colegios y asociaciones de profesionales, c\u00e1maras empresariales y directores del Ayuntamiento, Barrera Concha destac\u00f3 que, a 7 a\u00f1os de la instalaci\u00f3n de ese consejo, el trabajo, la dedicaci\u00f3n y el esfuerzo de todos los involucrados han generado excelentes resultados que contribuyen a mejorar la calidad de vida de los habitantes del municipio.<\/p>\n<p style=\"text-align: justify;\">\u201cYo creo que hoy el IMPLAN est\u00e1 listo para poder seguir siendo este eje rector que le d\u00e9 rumbo y ruta a la planeaci\u00f3n del municipio porque hoy d\u00eda los retos y desaf\u00edos que tenemos como ciudad van mucho m\u00e1s all\u00e1 de la capacidad misma de una administraci\u00f3n municipal\u201d, subray\u00f3.<\/p>\n<p style=\"text-align: justify;\">En ese contexto, agreg\u00f3 que construir una ciudad con una visi\u00f3n de largo plazo requiere de un trabajo articulado entre todos los actores clave, adem\u00e1s de voluntad pol\u00edtica, financiamiento adecuado y normativa actualizada, ya que la contribuci\u00f3n municipal en materia de movilidad urbana es muy amplia.<\/p>\n<p style=\"text-align: justify;\">\u201cEl Ayuntamiento no solo se remite a ser una oficina de tr\u00e1mites, sino tambi\u00e9n tiene que liderar la planeaci\u00f3n y la organizaci\u00f3n de los diferentes sectores de la sociedad y buscar ese equilibrio sin menoscabar el derecho de todos los que habitan en el municipio\u201d, enfatiz\u00f3.<\/p>\n<p style=\"text-align: justify;\">Por su parte, Jorge Eu\u00e1n G\u00f3ngora, presidente de la Fundaci\u00f3n Plan Estrat\u00e9gico de Yucat\u00e1n, reconoci\u00f3 el trabajo del Ayuntamiento de M\u00e9rida a trav\u00e9s del IMPLAN, y exhort\u00f3 a las autoridades a continuar trabajando en la planeaci\u00f3n de la ciudad que cada vez requiere mayor atenci\u00f3n en su crecimiento y desarrollo.<\/p>\n<p style=\"text-align: justify;\">\u201cReconozco la enorme labor que se ha hecho y que ha sido de beneficio para M\u00e9rida y hacia all\u00e1 tenemos que seguir para consolidar a\u00fan m\u00e1s ese trabajo en el que la participaci\u00f3n de la sociedad civil se hecho mucho m\u00e1s notoria que en otros tiempos y as\u00ed debe continuar\u201d, expres\u00f3.<\/p>\n<p style=\"text-align: justify;\">A su vez, Ricardo Combaluzier Medina, representante de la C\u00e1mara Nacional de la Industria de Desarrollo y Promoci\u00f3n de la Vivienda (Canadevi), felicit\u00f3 al alcalde Ren\u00e1n Barrera por impulsar la creaci\u00f3n del IMPLAN y del consejo ciudadano que encabeza y que han trascendido con el paso de las administraciones.<\/p>\n<p style=\"text-align: justify;\">Esto ha permitido lograr el desarrollo de programas y acciones de gran beneficio para la ciudad y sus habitantes, expres\u00f3.<\/p>\n<p style=\"text-align: justify;\">En su turno, Leticia Torres Mes\u00edas, representante de la escuela de Arquitectura de la Universidad Modelo, enfatiz\u00f3 que Plan Estrat\u00e9gico para una Ciudad Amigable con las Personas Mayores es un acierto de la administraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cEste programa en especial me parece algo extraordinario, sin duda es una medida sensible y es buen momento para trabajarlo porque se anticipa con opciones que mejoren la atenci\u00f3n a las personas de la tercera edad y revierte la costumbre de solucionar los problemas cuando el ni\u00f1o ya se fue al pozo\u201d, coment\u00f3.<\/p>\n<p style=\"text-align: justify;\">En su intervenci\u00f3n, Edgardo Bolio Arceo, director del IMPLAN, record\u00f3 que en estos a\u00f1os de trabajo el instituto ha desarrollado importantes estudios estrat\u00e9gicos de planeaci\u00f3n urbana que se incluyen en el Programa Municipal de Desarrollo Urbano de M\u00e9rida, actualmente se trabaja en el proyecto de modificaci\u00f3n de este programa.<\/p>\n<p style=\"text-align: justify;\">En su informe de actividades, detall\u00f3 que en la presente administraci\u00f3n se llevaron a cabo 119 procesos participativos, de los cuales, 23 correspondieron a la planeaci\u00f3n urbana, 32 a movilidad urbana, 14 a espacios p\u00fablicos, 22 a parques de dise\u00f1o participativo y 2 de regeneraciones urbanas y de vivienda.<\/p>\n<p style=\"text-align: justify;\">Coment\u00f3 que la llegada de la pandemia oblig\u00f3 a replantear la visi\u00f3n que se ten\u00eda inicialmente, por lo que se tomaron e implementaron nuevas acciones en materia de movilidad que contribuyeron al cuidado de la salud p\u00fablica, como la ampliaci\u00f3n de las aceras y \u00e1reas para el peat\u00f3n, reducci\u00f3n de carriles para veh\u00edculos, instalaci\u00f3n de bici estacionamientos, entre otros.<\/p>\n<p style=\"text-align: justify;\">Agreg\u00f3 que, aunado a lo anterior, se reforz\u00f3 el programa Circuito Enlace para favorecer el traslado de adultos mayores, mujeres embarazadas y personas con discapacidad.<\/p>\n<p style=\"text-align: justify;\">Asimismo, mencion\u00f3 que entre los proyectos en desarrollo est\u00e1n el Gran Pulm\u00f3n de M\u00e9rida, que es uno de los principales proyectos que distinguen a este Ayuntamiento, as\u00ed como los sistemas urbanos de Drenaje Pluvial Sostenible, la regeneraci\u00f3n urbana y vivienda y el Plan Estrat\u00e9gico para una Ciudad Amigable con las Personas Mayores.<\/p>\n<p style=\"text-align: justify;\">En la sesi\u00f3n tambi\u00e9n estuvieron presentes Miguel Sosa Correa y Miguel \u00c1ngel Garc\u00eda Dom\u00ednguez, presidentes del Colegio Yucateco de Arquitectos y del Colegio de Ingenieros Civiles de Yucat\u00e1n A.C, respectivamente; la regidora Gloria Alonzo Tamayo, integrante de la Comisi\u00f3n de Desarrollo Urbano, Alfonso Gonz\u00e1lez Fern\u00e1ndez, representante, de la Asociaci\u00f3n Yucateca de Especialistas en Restauraci\u00f3n del Patrimonio Edificado.<\/p>\n<p style=\"text-align: justify;\">Asimismo, Julio Sauma Castillo, secretario de Participaci\u00f3n Ciudadana; Aura Loza \u00c1lvarez, Federico Sauri Molina y Jos\u00e9 Luis Mart\u00ednez Semerena, directores de Catastro, Desarrollo Urbano y Desarrollo Social, respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; M\u00e9rida, 4 de agosto de 2021. La planeaci\u00f3n de nuestra ciudad es un tema fundamental para alcanzar el desarrollo humano y trabajando de la mano, en alianzas con la propia sociedad, podremos seguir construyendo una ciudad con una visi\u00f3n a largo plazo, afirm\u00f3 el alcalde Ren\u00e1n Barrera Concha. El Concejal presidi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":85445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[761],"class_list":["post-85444","post","type-post","status-publish","format-standard","has-post-thumbnail","category-merida","tag-renan-barrera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; M\u00e9rida, 4 de agosto de 2021. La planeaci\u00f3n de nuestra ciudad es un tema fundamental para alcanzar el desarrollo humano y trabajando de la mano, en alianzas con la propia sociedad, podremos seguir construyendo una ciudad con una visi\u00f3n a largo plazo, afirm\u00f3 el alcalde Ren\u00e1n Barrera Concha. El Concejal presidi\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-05T00:46:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN\",\"datePublished\":\"2021-08-05T00:46:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/\"},\"wordCount\":972,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/renan-barrera.jpg\",\"keywords\":[\"Ren\u00e1n Barrera\"],\"articleSection\":[\"M\u00e9rida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/\",\"name\":\"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/renan-barrera.jpg\",\"datePublished\":\"2021-08-05T00:46:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/renan-barrera.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/renan-barrera.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/","og_locale":"es_ES","og_type":"article","og_title":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; M\u00e9rida, 4 de agosto de 2021. La planeaci\u00f3n de nuestra ciudad es un tema fundamental para alcanzar el desarrollo humano y trabajando de la mano, en alianzas con la propia sociedad, podremos seguir construyendo una ciudad con una visi\u00f3n a largo plazo, afirm\u00f3 el alcalde Ren\u00e1n Barrera Concha. El Concejal presidi\u00f3 [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-08-05T00:46:23+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN","datePublished":"2021-08-05T00:46:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/"},"wordCount":972,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg","keywords":["Ren\u00e1n Barrera"],"articleSection":["M\u00e9rida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/","name":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg","datePublished":"2021-08-05T00:46:23+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/08\/renan-barrera.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-alcalde-renan-barrera-encabezo-sesion-ordinaria-en-el-marco-del-7o-aniversario-del-implan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"El alcalde Ren\u00e1n Barrera encabez\u00f3 sesi\u00f3n ordinaria en el marco del 7o. Aniversario del IMPLAN"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/85444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=85444"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/85444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/85445"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=85444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=85444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=85444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}