{"id":87410,"date":"2021-11-11T17:07:47","date_gmt":"2021-11-11T23:07:47","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=87410"},"modified":"2021-11-11T17:07:47","modified_gmt":"2021-11-11T23:07:47","slug":"para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/","title":{"rendered":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-87411\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg\" alt=\"\" width=\"608\" height=\"342\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">M\u00e9rida, Yucat\u00e1n, 11 de noviembre de 2021. Informa sobre el arribo del frente fr\u00edo n\u00famero 8, este s\u00e1bado 13 por la tarde, con lluvias, vientos, incremento del oleaje y descenso en los term\u00f3metros.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">El titular de la dependencia, Enrique Alcocer Basto, precis\u00f3 que el sistema ingresar\u00e1 por el poniente del estado y ocasionar\u00e1 precipitaciones ligeras, acompa\u00f1adas de r\u00e1fagas moderadas en todo el territorio y un incremento en el oleaje, de 1.2 a 1.8 metros.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Lo acompa\u00f1ar\u00e1 un norte con rachas de viento de 30 a 40 kil\u00f3metros por hora en la costa y de 25 a 35 en el interior de la entidad; no se espera mayor descenso de temperatura y se mantendr\u00e1 el tiempo fresco, arriba de 17 grados Celsius, mientras que, en el cono sur y suroeste, estar\u00e1 en el rango de 14 a 16.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">De igual manera, la presencia de una vaguada inducida con gran carga de humedad provocar\u00e1 lluvias de moderada a fuerte intensidad, desde la tarde del viernes 12, cuyas mayores concentraciones se registrar\u00e1n en el oriente y sur del estado, precis\u00f3 el funcionario.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A partir de la madrugada del lunes 15, la masa de aire que impulsar\u00e1 al frente fr\u00edo influir\u00e1 en el descenso en los term\u00f3metros, con valores de 14 a 16 grados en el cono sur y el suroeste; en el resto de la entidad, se conservar\u00e1n arriba de los 17.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">El servidor p\u00fablico recomend\u00f3 a las familias proteger a ni\u00f1as, ni\u00f1os y personas adultas mayores ante los cambios de temperatura, as\u00ed como resguardarse durante las lluvias, teniendo en cuenta la disponibilidad de marcar el 9-1-1 para atender cualquier emergencia.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Para el presente periodo invernal 2021-2022, el Servicio Meteorol\u00f3gico (SMN) de la Comisi\u00f3n Nacional del Agua (Conagua) ha pronosticado 56 frentes fr\u00edos para todo el pa\u00eds, de los cuales la Pen\u00ednsula de Yucat\u00e1n captar\u00eda de 28 a 30, que es el promedio en cada temporada.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Cada mes, estad\u00edsticamente, ingresan a la regi\u00f3n entre tres y cuatro fen\u00f3menos de este tipo por mes, los cuales, conforme a sus caracter\u00edsticas e intensidad, ocasionan precipitaciones, vientos y oleaje; en otros casos, pueden ser d\u00e9biles y refrescar \u00fanicamente el ambiente.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">De los ocho que se ha registrado hasta el mes de noviembre, s\u00f3lo dos han tenido influencia directa sobre Yucat\u00e1n; uno de ellos, el n\u00famero 6, ocasion\u00f3 l\u00edneas de turbonada en Celest\u00fan y Progreso, con rachas de 60 kil\u00f3metros y temperatura m\u00ednima en Sotuta de 15.1 grados.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">La vaguada del pasado frente 7 provoc\u00f3 lluvia intensa de 106.0 mil\u00edmetros y encharcamiento en varias calles de Tizim\u00edn, donde resultaron afectadas 34 viviendas, que recibieron atenci\u00f3n inmediata de Procivy, y descenso de hasta 9.5 Celsius en Motul.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Ante la influencia del fen\u00f3meno c\u00edclico de la Ni\u00f1a, se espera que la temporada invernal 2021-2022 sea seca y fr\u00eda, ya que de los 56 frentes pronosticados para ella, se espera el paso de 28 a 30 en Yucat\u00e1n, de los cuales entre tres y cuatro influir\u00e1n directamente cada mes.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Por lo anterior, en noviembre, se esperan efectos de al menos tres sistemas frontales, adicionales al pasado n\u00famero 7. Actualmente, de los ocho frentes que se ha registrado en el pa\u00eds, hasta este 11 de noviembre, \u00fanicamente dos han impactado en el territorio, el 6 y el 7.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n, 11 de noviembre de 2021. Informa sobre el arribo del frente fr\u00edo n\u00famero 8, este s\u00e1bado 13 por la tarde, con lluvias, vientos, incremento del oleaje y descenso en los term\u00f3metros. El titular de la dependencia, Enrique Alcocer Basto, precis\u00f3 que el sistema ingresar\u00e1 por el poniente del estado y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":87411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9953,557,2041,1514,121],"class_list":["post-87410","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan","tag-arribo","tag-conagua","tag-fin-de-semana","tag-frente-frio","tag-lluvias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n, 11 de noviembre de 2021. Informa sobre el arribo del frente fr\u00edo n\u00famero 8, este s\u00e1bado 13 por la tarde, con lluvias, vientos, incremento del oleaje y descenso en los term\u00f3metros. El titular de la dependencia, Enrique Alcocer Basto, precis\u00f3 que el sistema ingresar\u00e1 por el poniente del estado y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T23:07:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados\",\"datePublished\":\"2021-11-11T23:07:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/\"},\"wordCount\":568,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/f608x342-443231_472954_0.jpg\",\"keywords\":[\"arribo\",\"conagua\",\"Fin de semana\",\"frente frio\",\"lluvias\"],\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/\",\"name\":\"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/f608x342-443231_472954_0.jpg\",\"datePublished\":\"2021-11-11T23:07:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/f608x342-443231_472954_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/f608x342-443231_472954_0.jpg\",\"width\":608,\"height\":342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/","og_locale":"es_ES","og_type":"article","og_title":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto","og_description":"&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n, 11 de noviembre de 2021. Informa sobre el arribo del frente fr\u00edo n\u00famero 8, este s\u00e1bado 13 por la tarde, con lluvias, vientos, incremento del oleaje y descenso en los term\u00f3metros. El titular de la dependencia, Enrique Alcocer Basto, precis\u00f3 que el sistema ingresar\u00e1 por el poniente del estado y [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2021-11-11T23:07:47+00:00","og_image":[{"width":608,"height":342,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados","datePublished":"2021-11-11T23:07:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/"},"wordCount":568,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg","keywords":["arribo","conagua","Fin de semana","frente frio","lluvias"],"articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/","name":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg","datePublished":"2021-11-11T23:07:47+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2021\/11\/f608x342-443231_472954_0.jpg","width":608,"height":342},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/para-el-fin-de-semana-llega-nuevo-frente-frio-trae-lluvias-y-hasta-14-grados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Para el fin de semana llega nuevo frente fr\u00edo trae lluvias y hasta 14 grados"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/87410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=87410"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/87410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/87411"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=87410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=87410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=87410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}