{"id":90685,"date":"2022-04-16T14:42:45","date_gmt":"2022-04-16T19:42:45","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=90685"},"modified":"2022-04-16T14:42:45","modified_gmt":"2022-04-16T19:42:45","slug":"yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/","title":{"rendered":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-90686\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-696x464.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 16 de abril de 2022.- Emprendedores yucatecos contin\u00faan recibiendo el apoyo del Gobernador Mauricio Vila Dosal a trav\u00e9s de diversos programas que significan un esfuerzo de m\u00e1s de 300 millones de pesos en beneficio de 70 mil emprendedores y peque\u00f1os empresarios yucatecos para impulsar sus negocios y continuar generando m\u00e1s empleos que impulsan la transformaci\u00f3n de un Yucat\u00e1n m\u00e1s pr\u00f3spero para las familias yucatecas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En lo que va de la administraci\u00f3n, a trav\u00e9s del Instituto Yucateco de Emprendedores (Iyem), se han ejercido m\u00e1s de 300 millones de pesos en apoyo a m\u00e1s de 70 mil personas emprendedoras y empresarias, con lo que se han incubado 87 proyectos, acelerado 79 empresas, atendido a m\u00e1s de 1,100 empresas y registraron m\u00e1s de 200 marcas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Resultado de este impulso que ejerce Vila Dosal, el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (CONEVAL), posiciona a Yucat\u00e1n en primer lugar en todo el pa\u00eds, como la entidad que m\u00e1s programas ejerci\u00f3 para apoyar emprendimientos, empresas o empleos para hacer frente a la pandemia por Coronavirus.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, el director general del IYEM, Antonio Gonz\u00e1lez Blanco, destac\u00f3 los logros que Yucat\u00e1n ha obtenido a trav\u00e9s de convocatorias a nivel nacional, as\u00ed como en las de nivel internacional, que lo posicionan como un estado competitivo e ideal para el desarrollo de negocios y que ofrece productos de calidad.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cTenemos muy buena participaci\u00f3n de las empresas y emprendimientos yucatecos a nivel nacional e internacional y los resultados se ven reflejados en las convocatorias realizadas con pa\u00edses como Alemania y Estados Unidos; cada vez que hay una convocatoria de talla nacional o internacional, Yucat\u00e1n se coloca en los primeros lugares de las empresas seleccionadas, y por ello, tambi\u00e9n somos de las entidades con mayor participaci\u00f3n en este tipo de eventos pues, impulsan de forma importante los proyectos locales\u201d, indic\u00f3 el funcionario estatal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Gonz\u00e1lez Blanco record\u00f3 que en Yucat\u00e1n se han generado m\u00e1s de 39 mil empleos, que significan el 54% m\u00e1s de los 25 mil que se hab\u00edan perdido por la pandemia del Coronavirus, y dicha cantidad hizo que Yucat\u00e1n rompa un nuevo r\u00e9cord hist\u00f3rico en generaci\u00f3n de empleos, al registrarse en el pasado mes de marzo un total de 400,048 trabajadores asegurados ante el Instituto Mexicano del Seguro Social (IMSS), lo que da muestra del \u00e9xito de programas como los que ejerce el Iyem, \u201clo cual quiere decir que las cosas se est\u00e1n haciendo y de ah\u00ed la importancia de seguir impulsando las buenas ideas\u201d, indic\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, la Presidenta Nacional de Empresarios J\u00f3venes de la Confederaci\u00f3n Patronal de la Rep\u00fablica Mexicana (Coparmex), Roc\u00edo del Mar Rosas Aguiar, reconoci\u00f3 el trabajo que ejerce el Gobierno del Estado para impulsar proyectos y cuidar los empleos que \u00e9stos generan en cada rinc\u00f3n del estado, \u201cpor lo que felicito al Gobernador por las acciones implementadas para llegar a cada vez m\u00e1s habitantes del Estado y as\u00ed brindarles una oportunidad de desarrollarse\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>De igual forma, la Presidenta Nacional de J\u00f3venes Industriales de la C\u00e1mara Nacional de la Industria de la Transformaci\u00f3n (Canacintra) Delegaci\u00f3n Yucat\u00e1n, destac\u00f3 que Yucat\u00e1n es un ejemplo a nivel nacional, al aplicar estrategias como \u201cla triple h\u00e9lice\u201d para impulsar proyectos productivos, lo que ya se realiza en la entidad y da un ejemplo de que es posible y los resultados hablan por s\u00ed solos e inspiran a dem\u00e1s entidades a replicar lo que se hace en el estado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Al brindar detalles sobre los diferentes esquemas estatales que se ofrecen a las y los emprendedores, as\u00ed como a peque\u00f1as empresas para impulsar sus negocios, se mencion\u00f3 que, la convocatoria \u201cEmprendiendo Desde Cero\u201d, tiene como objetivo desarrollar los conocimientos y habilidades de emprendimiento para abordar su proyecto empresarial y que le permitan una orientaci\u00f3n para introducirse al mercado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Con el programa \u201cIncubaci\u00f3n 2022\u201d, se otorgan capacitaciones y asesor\u00edas para convertir su idea en un proyecto viable de negocio, con lo que la poblaci\u00f3n emprendedora y empresarial se desenvuelven en un contexto favorable para el desarrollo de proyectos productivos con un enfoque de inclusi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Si la empresa ya se encuentra establecida y se desea crecer a trav\u00e9s de consultor\u00eda especializada, existe \u201cAceleraci\u00f3n Empresarial 2022 (Transformaci\u00f3n digital y sostenible)\u201d para impulsar el crecimiento acelerado de las empresas del estado, incorporando medios digitales y pr\u00e1cticas sostenibles que fortalezcan la competitividad.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En cuanto a la econom\u00eda naranja, est\u00e1 el programa \u201cAceleraci\u00f3n Empresarial 2022 (Industrias creativas)\u201d con la cual se pretende mejorar las condiciones de acceso al mercado para emprendedores creativos, especialmente mujeres y minor\u00edas para promover la diversidad cultural del estado y promover la creaci\u00f3n de un sistema de desarrollo de mercados para incrementar la competitividad y el potencial comercial de las empresas en crecimiento, privilegiando la producci\u00f3n diversa mediante la inclusi\u00f3n de grupos vulnerables.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, \u201cMicroYuc Emprendedores\u201d, es un programa de cr\u00e9dito de f\u00e1cil acceso para los emprendedores, micro y peque\u00f1as empresas, que operen en Yucat\u00e1n, para el desarrollo de proyectos productivos, asimismo, para las cooperativas o colectivos en el Estado, \u201cPosible Coop\u201d les otorga el impulso para convertirse en agentes de cambio para sus comunidades.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En materia del uso de energ\u00edas limpias, con el esquema \u201cMicroYuc Verde\u201d se ofrece un cr\u00e9dito de f\u00e1cil acceso para el financiamiento de pr\u00e1cticas en eficiencia y transici\u00f3n energ\u00e9tica, econ\u00f3mica circular u otras acciones con enfoque sostenible que operan en Yucat\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>De igual forma, se anuncia la pr\u00f3xima reapertura del Coworking del IYEM, que se realizar\u00e1 el pr\u00f3ximo 16 de mayo, cumpliendo con todas las medidas y protocolos de seguridad e higiene recomendados por la Secretar\u00eda de Salud de Yucat\u00e1n (SSY).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Para m\u00e1s detalles de los programas disponibles, las personas interesadas pueden visitar el sitio web del Instituto Yucateco de Emprendedores; www.iyem.yucatan.gob.mx donde encontrar\u00e1n las fechas claves de cada una de ellas, as\u00ed como los requisitos de participaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 16 de abril de 2022.- Emprendedores yucatecos contin\u00faan recibiendo el apoyo del Gobernador Mauricio Vila Dosal a trav\u00e9s de diversos programas que significan un esfuerzo de m\u00e1s de 300 millones de pesos en beneficio de 70 mil emprendedores y peque\u00f1os empresarios yucatecos para impulsar sus negocios y continuar generando m\u00e1s empleos que impulsan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":90686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-90685","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 16 de abril de 2022.- Emprendedores yucatecos contin\u00faan recibiendo el apoyo del Gobernador Mauricio Vila Dosal a trav\u00e9s de diversos programas que significan un esfuerzo de m\u00e1s de 300 millones de pesos en beneficio de 70 mil emprendedores y peque\u00f1os empresarios yucatecos para impulsar sus negocios y continuar generando m\u00e1s empleos que impulsan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-16T19:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores\",\"datePublished\":\"2022-04-16T19:42:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/\"},\"wordCount\":1092,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-6-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/\",\"name\":\"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-6-scaled.jpg\",\"datePublished\":\"2022-04-16T19:42:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-6-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-6-scaled.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/","og_locale":"es_ES","og_type":"article","og_title":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 16 de abril de 2022.- Emprendedores yucatecos contin\u00faan recibiendo el apoyo del Gobernador Mauricio Vila Dosal a trav\u00e9s de diversos programas que significan un esfuerzo de m\u00e1s de 300 millones de pesos en beneficio de 70 mil emprendedores y peque\u00f1os empresarios yucatecos para impulsar sus negocios y continuar generando m\u00e1s empleos que impulsan [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-04-16T19:42:45+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores","datePublished":"2022-04-16T19:42:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/"},"wordCount":1092,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/","name":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg","datePublished":"2022-04-16T19:42:45+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-6-scaled.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-ejemplo-a-nivel-nacional-en-el-impulso-a-proyectos-emprendedores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Yucat\u00e1n, ejemplo a nivel nacional en el impulso a proyectos emprendedores"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/90685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=90685"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/90685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/90686"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=90685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=90685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=90685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}