{"id":90697,"date":"2022-04-17T20:02:04","date_gmt":"2022-04-18T01:02:04","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=90697"},"modified":"2022-04-17T20:02:04","modified_gmt":"2022-04-18T01:02:04","slug":"yucatan-presente-en-la-feria-nacional-de-san-marcos","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/","title":{"rendered":"Yucat\u00e1n presente en la Feria Nacional de San Marcos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-90698\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg\" alt=\"\" width=\"768\" height=\"589\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-696x534.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-1068x820.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-547x420.jpg 547w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-80x60.jpg 80w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Aguascalientes, 17 de abril de 2022.- Con la participaci\u00f3n de m\u00e1s de 60 empresarios, emprendedores y artesanos locales, los colores, sabores y la cultura de Yucat\u00e1n inundan la edici\u00f3n 2022 de la Feria Nacional de San Marcos (FNSM) de Aguascalientes, evento que tiene por invitado especial al estado, que est\u00e1 ofreciendo una amplia muestra de las tradiciones y los productos locales, al tiempo que se promueve nuestros destinos para incentivar el turismo y la econom\u00eda de las familias yucatecas con la generaci\u00f3n de empleos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los Gobernadores Mauricio Vila Dosal y de Aguascalientes, Mart\u00edn Orozco Sandoval, encabezaron la ceremonia de inauguraci\u00f3n de este evento, el m\u00e1s importante en su tipo en el pa\u00eds, que se lleva a cabo hasta el pr\u00f3ximo 8 de mayo, reuniendo a visitantes de diversas partes del pa\u00eds, as\u00ed como del mundo, quienes estar\u00e1n disfrutando de lo mucho que Yucat\u00e1n tiene para ofrecer.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el primer patio de la Casa de la Cultura \u00abV\u00edctor Sandoval\u00bb, Vila Dosal afirm\u00f3 que es un gusto participar en esta Feria debido a la gran importancia que tiene a nivel nacional, ya que es un gran escaparate para mostrar lo muchos que tenemos que ofrecer, adem\u00e1s de contribuir con la promoci\u00f3n de los destinos y productos locales para la creaci\u00f3n de fuentes de trabajo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Acompa\u00f1ado del secretario de Turismo de Aguascalientes y presidente del Patronato de la Feria, Jos\u00e9 \u00c1ngel Gonz\u00e1lez Serna, el Gobernador se\u00f1al\u00f3 que para los yucatecos es un gusto y un gran orgullo participar en esta Feria y que cada vez sean m\u00e1s las personas que conozcan los productos locales y principales atractivos tur\u00edsticos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por ello, Vila Dosal agradeci\u00f3 al Gobernador de Aguascalientes la oportunidad de que el estado participe en esta gran fiesta, ya que el estado ha tra\u00eddo lo mejor de Yucat\u00e1n para que la gente se decida a visitar el territorio y enamorarse de los tantos atractivos que tiene.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abCon nuestra presencia aqu\u00ed en la feria pretendemos que ustedes tengan una probadita de Yucat\u00e1n, que puedan probar nuestros productos, que nuestros artesanos, que nuestros emprendedores tengan la oportunidad de ampliar sus horizontes, de tener m\u00e1s clientes, pero sobre todo de que ustedes tengan ganas de visitar Yucat\u00e1n\u00bb, asever\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Gobernador afirm\u00f3 que Yucat\u00e1n lo tiene todo, pues cuenta con zonas arqueol\u00f3gicas patrimonio de la humanidad, 4 pueblos m\u00e1gicos, m\u00e1s de 3 mil cenotes, 300 haciendas, as\u00ed como 387 kil\u00f3metros de hermosas playas, que cautivan a quien lo visita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A su vez, el Gobernador de Aguascalientes agradeci\u00f3 a Vila Dosal su inter\u00e9s y disposici\u00f3n para que Yucat\u00e1n participe como estado invitado en esta muestra, toda vez que las entidades tiene mucho para compartir y fusionar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abYucat\u00e1n es un estado que tiene mucho para presumir y todo eso es lo que nos trajeron aqu\u00ed a Aguascalientes para que lo disfrutemos y conozcamos\u00bb, asever\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En ese marco, el Gobernador y Orozco Sandoval hicieron el corte del list\u00f3n inaugural del pabell\u00f3n de Yucat\u00e1n, el cual cuenta con un dise\u00f1o de hacienda henequenera. Cabe destacar que, la entidad est\u00e1 participando en la magna verbena abrile\u00f1a con 30 stands, as\u00ed como la presencia de m\u00e1s de 60 empresarios, emprendedores y artesanos locales, la mayor\u00eda proveniente del interior del estado, quienes se encuentran exponiendo los productos hechos por las manos de mujeres y hombres yucatecos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Junto con el titular de la Secretar\u00eda de Fomento Econ\u00f3mico y Trabajo (Sefoet), Ernesto Herrera Novelo, Vila Dosal realiz\u00f3 un recorrido por las diversas \u00e1reas que Yucat\u00e1n tiene a lo largo de la Feria Nacional de San Marcos, donde constat\u00f3 el gran inter\u00e9s que la cultura, los productos yucatecos, los destinos tur\u00edsticos y la gastronom\u00eda de la entidad gener\u00f3 en los visitantes a este evento.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el pabell\u00f3n principal de Yucat\u00e1n, empresas locales llevaron sus productos para exponer, los cuales causaron una gran aceptaci\u00f3n, ya que la gente que por ah\u00ed pasaba se deten\u00eda para conocer y adquirir alg\u00fan art\u00edculo yucatecos, lo que pudo ser observado por el Gobernador.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>De igual manera, Vila Dosal se dirigi\u00f3 a un stand donde se dan a conocer productos realizados por hombres y mujeres que trabajan con henequ\u00e9n, cester\u00eda, j\u00edcara, talabarter\u00eda, urdido, jipi, filigrana, bordado a m\u00e1quina y a mano, madera piedra, bejuco y huano, provenientes de municipios como M\u00e9rida, Izamal, Valladolid, Tekit, Tinum, Tekax, Chemax, Conkal, Man\u00ed, Chumayel, Xocchel, Hunucm\u00e1, Motul, Tahdzi\u00fa, Teabo, Tixkokob, Yaxcab\u00e1, Hocab\u00e1, Kanas\u00edn, Progreso, Sey\u00e9, Tixm\u00e9huac y Um\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Otro de los puntos que acapara la atenci\u00f3n de los hidroc\u00e1lidos y asistentes a la Feria es el \u00e1rea gastron\u00f3mica, a cargo del restaurante Zamn\u00e1 de Izamal, al cual tambi\u00e9n acudi\u00f3 el Gobernador para comprobar la gran afluencia que ha registrado en sus primeras jornadas, ofreciendo un probadita de los sabores de la entidad a trav\u00e9s de platillos t\u00edpicos, como cochinita, lech\u00f3n al horno, panuchos y escabeche.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En ese punto, Vila Dosal degust\u00f3 una torta de cochinita, mientras que el Gobernador aguascalentense sabore\u00f3 un taco del mismo guiso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Posteriormente, se dirigi\u00f3 a la expo comercial e industrial de la Feria Nacional de San Marcos para constatar m\u00e1s productos hechos en Yucat\u00e1n, que cautivaron a los visitantes; as\u00ed como las diversas activaciones tur\u00edsticas para promover los destinos yucatecos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Dentro de las experiencias m\u00e1s gustadas por la gente, est\u00e1n las hamacas gigantes, de 10 metros cada una; as\u00ed como las sillas \u00abt\u00fa y yo\u00bb intervenidas por artistas estudiantes de la Escuela Superior de Artes de Yucat\u00e1n (ESAY) del Gobierno del Estado de Yucat\u00e1n, las cuales se convirtieron en los escenarios favoritos para retratar momentos en familia y conocer m\u00e1s de la entidad.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, como parte de la presencia de la marca Yucat\u00e1n existen figuras a base de fibra de flamencos a gran escala; al igual que photo opportunities, la campa\u00f1a \u00abYucat\u00e1n es color\u00bb, as\u00ed como carteles y espectaculares, para llevar un poco de lo mucho que ofrece Yucat\u00e1n como destino.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Dentro de las actividades art\u00edsticas y culturales que ofrece la entidad, los visitantes pueden disfrutar de presentaciones de la \u00abOrquesta Jaranera Del Mayab\u00bb, los \u00abTrovadores de Yucat\u00e1n\u00bb, el \u00abBallet Folkl\u00f3rico del Estado\u00bb y mucho m\u00e1s; todo ello con la participaci\u00f3n de m\u00e1s de 40 artistas yucatecos, que est\u00e1n poniendo en alto el nombre de Yucat\u00e1n en la Feria.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el marco de la ceremonia del corte del list\u00f3n inaugural, Vila Dosal, acompa\u00f1ado de Lucina Jim\u00e9nez L\u00f3pez, directora del Instituto Nacional de Bellas Artes (INBA), presenci\u00f3 la premiaci\u00f3n de los seleccionados en el cuadrag\u00e9simo segundo Encuentro Nacional de Arte Joven, que se realiza tradicionalmente durante esta fiesta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En un extenso recorrido por las atracciones de la Feria Nacional de San Marcos, el Gobernador tambi\u00e9n acompa\u00f1\u00f3 al titular del Ejecutivo de Aguascalientes en el corte del list\u00f3n inaugural del corredor Carranza, del m\u00f3dulo del DIF estatal, las expo industrial y artesanal, entre otras \u00e1reas que conforman la celebraci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La noche de ayer, Vila Dosal, junto con Orozco Sandoval, encabez\u00f3 la ceremonia de coronaci\u00f3n de Andrea Lizbeth Morales Montoya, reina de dicha edici\u00f3n de este magno evento, considerado el m\u00e1s importante en su tipo del pa\u00eds que re\u00fane visitantes de diversas partes del pa\u00eds, as\u00ed como del mundo, quienes estar\u00e1n disfrutando de las tradiciones, los colores y sabores de Yucat\u00e1n hasta el pr\u00f3ximo 8 de mayo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, conoci\u00f3 a 50 jinetes de Yucat\u00e1n, quienes, desde los municipios de Tizim\u00edn, Buctzotz y Panab\u00e1, llegaron hasta Aguascalientes para participar en la Cabalgata Nacional 2022 que se realiza en el marco de la Feria Nacional de San Marcos, convocados por la Federaci\u00f3n M\u00e9xico a Caballo. En esa actividad participaron cerca de 2 mil cabalgantes de toda la Rep\u00fablica para dar inicio a la feria m\u00e1s importante de todo M\u00e9xico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En esta edici\u00f3n, se prev\u00e9 una derrama econ\u00f3mica superior a los 9,000 millones de pesos y el rees tradici\u00f3n, durante esta conocida verbena, se ha tenido como invitado especial a una de las entidades del pa\u00eds y, en esta ocasi\u00f3n, es Yucat\u00e1n, lo que permitir\u00e1 refrendar el hermanamiento e intercambio cultural, para que tanto hidroc\u00e1lidos como visitantes de diversas partes del pa\u00eds y el mundo conozcan m\u00e1s de cerca nuestros atractivos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los eventos de mayor tradici\u00f3n que se ofrece, se encuentra un variado programa musical y de espect\u00e1culos para todos los gustos; pabellones, exposiciones ganaderas, industriales y agroalimentaria; corridas de toros, una vasta oferta de cultura y arte; grandes torneos y campeonatos deportivos, adem\u00e1s del desfile de primavera, colocaci\u00f3n del Bando Solemne y misa de gallo, entre otros, que hacen recordar un poco de la historia de esta Feria.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La presencia de Yucat\u00e1n en eventos de esta magnitud es ideal para promover y posicionar su oferta tur\u00edstica, lo cual se reflejar\u00e1 en el incremento de visitantes y, por tanto, m\u00e1s y mejores beneficios para quienes dependen del sector. Asimismo, se aprovechar\u00e1 para exponer y comercializar productos locales, en respaldo a las micro, peque\u00f1as y medianas empresas.gistro de aproximadamente 8 millones de visitas, nacionales e internacionales.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Como ya<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Aguascalientes, 17 de abril de 2022.- Con la participaci\u00f3n de m\u00e1s de 60 empresarios, emprendedores y artesanos locales, los colores, sabores y la cultura de Yucat\u00e1n inundan la edici\u00f3n 2022 de la Feria Nacional de San Marcos (FNSM) de Aguascalientes, evento que tiene por invitado especial al estado, que est\u00e1 ofreciendo una amplia muestra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":90698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-90697","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Aguascalientes, 17 de abril de 2022.- Con la participaci\u00f3n de m\u00e1s de 60 empresarios, emprendedores y artesanos locales, los colores, sabores y la cultura de Yucat\u00e1n inundan la edici\u00f3n 2022 de la Feria Nacional de San Marcos (FNSM) de Aguascalientes, evento que tiene por invitado especial al estado, que est\u00e1 ofreciendo una amplia muestra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-18T01:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Yucat\u00e1n presente en la Feria Nacional de San Marcos\",\"datePublished\":\"2022-04-18T01:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/\"},\"wordCount\":1668,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-8-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/\",\"name\":\"Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-8-scaled.jpg\",\"datePublished\":\"2022-04-18T01:02:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-8-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/0001-8-scaled.jpg\",\"width\":768,\"height\":589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/yucatan-presente-en-la-feria-nacional-de-san-marcos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yucat\u00e1n presente en la Feria Nacional de San Marcos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/","og_locale":"es_ES","og_type":"article","og_title":"Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto","og_description":"&nbsp; Aguascalientes, 17 de abril de 2022.- Con la participaci\u00f3n de m\u00e1s de 60 empresarios, emprendedores y artesanos locales, los colores, sabores y la cultura de Yucat\u00e1n inundan la edici\u00f3n 2022 de la Feria Nacional de San Marcos (FNSM) de Aguascalientes, evento que tiene por invitado especial al estado, que est\u00e1 ofreciendo una amplia muestra [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-04-18T01:02:04+00:00","og_image":[{"width":768,"height":589,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Yucat\u00e1n presente en la Feria Nacional de San Marcos","datePublished":"2022-04-18T01:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/"},"wordCount":1668,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/","name":"Yucat\u00e1n presente en la Feria Nacional de San Marcos - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg","datePublished":"2022-04-18T01:02:04+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/04\/0001-8-scaled.jpg","width":768,"height":589},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/yucatan-presente-en-la-feria-nacional-de-san-marcos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Yucat\u00e1n presente en la Feria Nacional de San Marcos"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/90697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=90697"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/90697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/90698"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=90697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=90697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=90697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}