{"id":92418,"date":"2022-07-26T18:43:15","date_gmt":"2022-07-26T23:43:15","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=92418"},"modified":"2022-07-26T18:43:15","modified_gmt":"2022-07-26T23:43:15","slug":"anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/","title":{"rendered":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-92419\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg\" alt=\"\" width=\"768\" height=\"538\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-696x488.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-1068x749.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-599x420.jpg 599w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-100x70.jpg 100w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>San Felipe, Yucat\u00e1n, 26 de julio de 2022.- Durante la entrega de apoyos del programa Peso a Peso Pesquero y Acu\u00edcola a hombres y mujeres del oriente del estado, el Gobernador Mauricio Vial Dosal anunci\u00f3 un conjunto de acciones para impulsar esta actividad y el turismo, as\u00ed como mejorar la imagen de San Felipe, proyectos que redundar\u00e1n en mejores oportunidades y m\u00e1s empleos para las familias.<\/p>\n<p>&nbsp;<\/p>\n<p>Los anuncios consisten en que el Gobierno del Estado dotar\u00e1 a cada una de las 2 cooperativas pesqueras locales de un motor y una lancha, para que auxilien a los hombres y las mujeres del mar, mientras que a las 4 del ramo tur\u00edstico se les apoyar\u00e1 con el 50% del costo para adquirir motores nuevos, a trav\u00e9s de un financiamiento a cubrirse en 18 meses.<\/p>\n<p>&nbsp;<\/p>\n<p>Inform\u00f3 que, a finales de este a\u00f1o o principios de 2023, iniciar\u00e1 la remodelaci\u00f3n del parque frente al Malec\u00f3n, para que ni\u00f1as y ni\u00f1os cuenten con espacios dignos donde jugar, y se comprometi\u00f3 a instalar mesas de trabajo para ver c\u00f3mo atender las necesidades de la comunidad, con el Ayuntamiento local, las Secretar\u00edas de Medio Ambiente y Recursos Naturales (Semarnat) y Marina (Semar), la Procuradur\u00eda Federal de Protecci\u00f3n al Ambiente (Profepa) y el Consejo Nacional del Ambiente (Conam).<\/p>\n<p>&nbsp;<\/p>\n<p>En su turno, el alcalde anfitri\u00f3n, Felipe Marrufo L\u00f3pez, agradeci\u00f3 la coordinaci\u00f3n con el Gobernador, ya que, aunque reconoce que no es f\u00e1cil para una autoridad resolver los requerimientos de todos, siempre ha mostrado inter\u00e9s en las problem\u00e1ticas de San Felipe y las demarcaciones del interior del estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Acompa\u00f1ado del titular de la Secretar\u00eda de Pesca y Acuacultura Sustentables (Sepasy), Rafael Combaluzier Medina, Vila Dosal continu\u00f3 con la distribuci\u00f3n de ayudas de Peso a Peso Pesquero y Acu\u00edcola, en beneficio de 659 hombres y mujeres del oriente de la entidad, que se dedican a estas actividades, a trav\u00e9s de una inversi\u00f3n r\u00e9cord de casi 6 millones de pesos, para fortalecer sus labores.<\/p>\n<p>&nbsp;<\/p>\n<p>Como parte de su gira de trabajo en este municipio, constat\u00f3 la activaci\u00f3n del centro cultural local y el funcionamiento del m\u00f3dulo del programa M\u00e9dico 24\/7; inaugur\u00f3 el Instituto Municipal de la Mujer, y entreg\u00f3 a Miguel Dur\u00e1n Dzul, presidente de la Asociaci\u00f3n Ganadera de San Felipe, un cheque por 90,000 pesos, para apoyar este organismo en la rehabilitaci\u00f3n y mejora de una b\u00e1scula.<\/p>\n<p>&nbsp;<\/p>\n<p>Dentro de Peso a Peso, reparti\u00f3 ayudas a 324 beneficiarios, provenientes de San Felipe; R\u00edo Lagartos y su comisar\u00eda Las Coloradas; Loch\u00e9, en Panab\u00e1, y el Cuyo, Tizim\u00edn. Se\u00f1al\u00f3 que, cada a\u00f1o, incrementa el monto del esquema en esta vertiente ofreciendo equipo, materiales y herramientas que verdaderamente necesitan los trabajadores, a un precio justo, m\u00e1s econ\u00f3mico y, especialmente, de manera oportuna.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cVamos a seguir trabajando junto con el Ayuntamiento y la Federaci\u00f3n, para seguir apoyando a San Felipe y su gente; muestra de ello es que, hoy, estamos entregando los apoyos a tiempo\u201d, destac\u00f3, tras exponer que el cat\u00e1logo, en esta ocasi\u00f3n, contempla m\u00e1s de 480 art\u00edculos.<\/p>\n<p>&nbsp;<\/p>\n<p>Incluye anzuelos, boyas, cabo de polipropileno, candado, hilos y l\u00ednea de nailon, l\u00ednea para palangre, pa\u00f1o de monofilamento, luz de malla, mallas de ca\u00edda, pa\u00f1o de monofilamento, piola pulpera, plomo redero, antena y radio m\u00f3vil, chaleco salvavidas, hilo y silbato marinos, acumulador, GPS, ecosonda striker, hielera de fibra de vidrio, malla sombra para embarcaci\u00f3n, aceite, propela de aluminio y congeladores de 7, 9 y 11 pies.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre las personas que recibieron este respaldo est\u00e1 Vanessa Candelaria D\u00edaz Marrufo, quien obtuvo una radio con pantalla grande, su antena, 4 metros de malla sombra y congelador horizontal de 7 pies, y agradeci\u00f3 al Gobernador por esta estrategia, ya que sus beneficios impactan directamente en las familias pesqueras de San Felipe y las zonas aleda\u00f1as.<\/p>\n<p>&nbsp;<\/p>\n<p>Sobre esto, Combaluzier Medina indic\u00f3 que 49% del total de beneficiarios corresponde a habitantes del oriente del estado, por lo que, en seguimiento a instrucciones de Vila Dosal, se continuar\u00e1 impulsando, en favor de las familias que dependen de la pesca, con un cat\u00e1logo diversificado, productos de calidad y buenos precios, para que puedan mejorar sus ingresos y calidad de vida.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante su visita a este municipio, junto con la titular de la Secretar\u00eda de la Cultura y las Artes (Sedeculta), Loreto Villanueva Trujillo, el Gobernador acudi\u00f3 al Espacio Cultural de esta localidad, donde se imparte talleres para fomentar esta sensibilidad entre ni\u00f1as, ni\u00f1os, adolescentes y personas adultas.<\/p>\n<p>&nbsp;<\/p>\n<p>Junto con la de la Secretar\u00eda de las Mujeres (Semujeres), Mar\u00eda Cristina Castillo Espinosa, el Gobernador cort\u00f3 el list\u00f3n inaugural del Instituto Municipal de la Mujer, en el que adolescentes, ni\u00f1as y dem\u00e1s habitantes de esta demarcaci\u00f3n recibir atenci\u00f3n y asesor\u00eda psicol\u00f3gica, jur\u00eddica y social, en caso de requerirla; tambi\u00e9n, supervis\u00f3 el funcionamiento del m\u00f3dulo M\u00e9dico 24\/7 de esta comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Felipe, Yucat\u00e1n, 26 de julio de 2022.- Durante la entrega de apoyos del programa Peso a Peso Pesquero y Acu\u00edcola a hombres y mujeres del oriente del estado, el Gobernador Mauricio Vial Dosal anunci\u00f3 un conjunto de acciones para impulsar esta actividad y el turismo, as\u00ed como mejorar la imagen de San Felipe, proyectos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":92419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-92418","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"San Felipe, Yucat\u00e1n, 26 de julio de 2022.- Durante la entrega de apoyos del programa Peso a Peso Pesquero y Acu\u00edcola a hombres y mujeres del oriente del estado, el Gobernador Mauricio Vial Dosal anunci\u00f3 un conjunto de acciones para impulsar esta actividad y el turismo, as\u00ed como mejorar la imagen de San Felipe, proyectos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-26T23:43:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe\",\"datePublished\":\"2022-07-26T23:43:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/\"},\"wordCount\":860,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/0003-25-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/\",\"name\":\"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/0003-25-scaled.jpg\",\"datePublished\":\"2022-07-26T23:43:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/0003-25-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/0003-25-scaled.jpg\",\"width\":768,\"height\":538},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/","og_locale":"es_ES","og_type":"article","og_title":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto","og_description":"San Felipe, Yucat\u00e1n, 26 de julio de 2022.- Durante la entrega de apoyos del programa Peso a Peso Pesquero y Acu\u00edcola a hombres y mujeres del oriente del estado, el Gobernador Mauricio Vial Dosal anunci\u00f3 un conjunto de acciones para impulsar esta actividad y el turismo, as\u00ed como mejorar la imagen de San Felipe, proyectos [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-07-26T23:43:15+00:00","og_image":[{"width":768,"height":538,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe","datePublished":"2022-07-26T23:43:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/"},"wordCount":860,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/","name":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg","datePublished":"2022-07-26T23:43:15+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/07\/0003-25-scaled.jpg","width":768,"height":538},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/anuncian-apoyos-y-proyectos-para-la-poblacion-de-san-felipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Anuncian apoyos y proyectos para la poblaci\u00f3n de San Felipe"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/92418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=92418"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/92418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/92419"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=92418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=92418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=92418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}