{"id":93123,"date":"2022-09-06T08:10:34","date_gmt":"2022-09-06T13:10:34","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=93123"},"modified":"2022-09-06T08:10:34","modified_gmt":"2022-09-06T13:10:34","slug":"nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/","title":{"rendered":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93124\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg\" alt=\"\" width=\"768\" height=\"557\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-696x504.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-1068x774.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-580x420.jpg 580w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-324x235.jpg 324w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 5 de septiembre de 2022.- El pr\u00f3ximo viernes 9 de septiembre se realizar\u00e1 una nueva jornada de vacunaci\u00f3n contra el Coronavirus para personas de 18 a\u00f1os en adelante de Sey\u00e9, Tekit y Sotuta que por alguna circunstancia no han podido completar su esquema, inform\u00f3 la Secretar\u00eda de Salud de Yucat\u00e1n (SSY).<\/p>\n<p>La dependencia estatal precis\u00f3 que dicho operativo se llevar\u00e1 a cabo en el Instituto Mexicano del Seguro Social (IMSS) Bienestar, y para el caso de Sey\u00e9 y Tekit, y en las instalaciones de la SSY de Sotuta.<\/p>\n<p>Se recomienda a la poblaci\u00f3n lo siguiente:<\/p>\n<p>&#8211; Presentar identificaci\u00f3n oficial<\/p>\n<p>&#8211; No es necesario llegar con horas de anticipaci\u00f3n<\/p>\n<p>&#8211; Consumir sus alimentos antes de acudir a la cita.<\/p>\n<p>&#8211; Tomar los medicamentos como de costumbre<\/p>\n<p>&#8211; Usar ropa c\u00f3moda y de manga corta.<\/p>\n<p>Asimismo, la SSY reitera que las personas mayores de 18 a\u00f1os que no hayan recibido vacuna alguna o requieran culminar su esquema contra el Coronavirus, pueden acudir a los m\u00f3dulos permanentes, ubicados en M\u00e9rida y el interior, con atenci\u00f3n de lunes a viernes, entre las 8:00 y 18:00 horas.<\/p>\n<p>Para el caso de la capital, los sitios se ubican en el Centro de Salud Urbano de la colonia Santa Rosa, la Unidad de Medicina Familiar n\u00famero 59 del IMSS y la del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (Issste) en Lindavista.<\/p>\n<p>Para el interior, est\u00e1n en el Hospital General de Tekax y los Centros de Salud tanto de Ticul como Tizim\u00edn; en Valladolid, el Almac\u00e9n Jurisdiccional de Vacunolog\u00eda; Izamal, el Hospital Rural; Motul, el General de Subzona 3, y en Progreso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 5 de septiembre de 2022.- El pr\u00f3ximo viernes 9 de septiembre se realizar\u00e1 una nueva jornada de vacunaci\u00f3n contra el Coronavirus para personas de 18 a\u00f1os en adelante de Sey\u00e9, Tekit y Sotuta que por alguna circunstancia no han podido completar su esquema, inform\u00f3 la Secretar\u00eda de Salud de Yucat\u00e1n (SSY). La dependencia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93123","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 5 de septiembre de 2022.- El pr\u00f3ximo viernes 9 de septiembre se realizar\u00e1 una nueva jornada de vacunaci\u00f3n contra el Coronavirus para personas de 18 a\u00f1os en adelante de Sey\u00e9, Tekit y Sotuta que por alguna circunstancia no han podido completar su esquema, inform\u00f3 la Secretar\u00eda de Salud de Yucat\u00e1n (SSY). La dependencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-06T13:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta\",\"datePublished\":\"2022-09-06T13:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/\"},\"wordCount\":307,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/0001-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/\",\"name\":\"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/0001-scaled.jpg\",\"datePublished\":\"2022-09-06T13:10:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/0001-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/0001-scaled.jpg\",\"width\":768,\"height\":557},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 5 de septiembre de 2022.- El pr\u00f3ximo viernes 9 de septiembre se realizar\u00e1 una nueva jornada de vacunaci\u00f3n contra el Coronavirus para personas de 18 a\u00f1os en adelante de Sey\u00e9, Tekit y Sotuta que por alguna circunstancia no han podido completar su esquema, inform\u00f3 la Secretar\u00eda de Salud de Yucat\u00e1n (SSY). La dependencia [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-09-06T13:10:34+00:00","og_image":[{"width":768,"height":557,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta","datePublished":"2022-09-06T13:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/"},"wordCount":307,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/","name":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg","datePublished":"2022-09-06T13:10:34+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/0001-scaled.jpg","width":768,"height":557},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/nueva-jornada-de-vacunacion-para-personas-de-18-anos-en-adelante-que-no-han-podido-completar-su-esquema-en-seye-tekit-y-sotuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Nueva jornada de vacunaci\u00f3n para personas de 18 a\u00f1os en adelante que no han podido completar su esquema en Sey\u00e9, Tekit y Sotuta"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=93123"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/93124"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=93123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=93123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=93123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}