{"id":93373,"date":"2022-09-16T03:17:26","date_gmt":"2022-09-16T08:17:26","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=93373"},"modified":"2022-09-16T03:17:26","modified_gmt":"2022-09-16T08:17:26","slug":"miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/","title":{"rendered":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93374\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg\" alt=\"\" width=\"768\" height=\"549\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-696x498.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-588x420.jpg 588w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-100x70.jpg 100w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 15 de septiembre de 2022.- Miles de yucatecos colmaron la Plaza Grande de esta ciudad para acompa\u00f1ar al Gobernador Mauricio Vila Dosal a encabezar la tradicional ceremonia del Grito que conmemora el 212 aniversario del inicio de la lucha por la Independencia de M\u00e9xico.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde el balc\u00f3n central de Palacio de Gobierno, Vila Dosal, con el l\u00e1baro patrio en las manos y acompa\u00f1ado de su esposa Mar\u00eda Eugenia Ortiz Abraham, record\u00f3 la convocatoria a la lucha armada por la independencia de nuestro pa\u00eds que realiz\u00f3 el cura Miguel Hidalgo y Costilla la madrugada del 16 de septiembre de 1810, ante la mirada de los miles de ni\u00f1os, j\u00f3venes y adultos que llenaron el coraz\u00f3n del Centro Hist\u00f3rico de M\u00e9rida.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abMexicanos, viva la independencia nacional, vivan los h\u00e9roes que nos dieron patria. Viva Hidalgo. Viva Morelos. Viva Guerrero. Viva Josefa Ortiz de Dom\u00ednguez. Viva Yucat\u00e1n. Viva la unidad de los yucatecos. Viva la soberan\u00eda nacional. Viva M\u00e9xico\u00bb, expres\u00f3 el Gobernador mientras hac\u00eda repicar la campana y ondeaba la bandera nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>Despu\u00e9s de cada frase, se escuchaba al un\u00edsono los \u00a1Viva! de los miles de asistentes que acudieron a esta gran fiesta popular mexicana, momento en que los \u00e1nimos se dejaron sentir en su m\u00e1ximo nivel, con el sonido de las cornetas, los gritos de j\u00fabilo y las matracas, lo que dio paso al canto del Himno Nacional, que se escuch\u00f3 en todos los alrededores de la explanada.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, el Gobernador presenci\u00f3, junto con autoridades civiles y militares, el espect\u00e1culo de pirotecnia que, con luces multicolores, ilumin\u00f3 el cielo de la capital yucateca y los rostros de la gente ah\u00ed reunida para ser parte de esta celebraci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Minutos antes, Vila Dosal encabez\u00f3 los honores de ordenanza y recibi\u00f3 el l\u00e1baro patrio de manos de la Teniente Fuerza A\u00e9rea Controlador de Vuelo, Cielo Nadxiely Garc\u00eda Arteaga, comandante de la primera escolta mixta de elementos de las Fuerzas Armadas que, por primera vez, fue la encargada de entregar la bandera nacional al Gobernador.<\/p>\n<p>&nbsp;<\/p>\n<p>Dicha escolta estuvo conformada por elementos del Ej\u00e9rcito, la Marina, la Fuerza A\u00e9rea y de la Guardia Nacional. Acto que dio paso a la lectura al Acta de Independencia por parte de la titular de la Secretar\u00eda General de Gobierno (SGG), Mar\u00eda Fritz Sierra.<\/p>\n<p>&nbsp;<\/p>\n<p>Para cerrar con broche de oro los festejos patrios de esta noche, el p\u00fablico disfrut\u00f3 del concierto gratuito que ofreci\u00f3 la banda \u201cEl Recodo, de Cruz Liz\u00e1rraga\u201d que, con sus m\u00e1s grandes \u00e9xitos como \u201cAc\u00e1bame de matar\u201d, \u201cLo mejor de mi vida\u201d, \u201cMe gusta todo de ti\u201d, \u201cY llegaste t\u00fa, entre otros, puso a bailar y cantar a los yucatecos frente al escenario que se coloc\u00f3 en el cruce de la calle 61 con 60.<\/p>\n<p>&nbsp;<\/p>\n<p>Para garantizar que las actividades se lleven a cabo en total orden y armon\u00eda, se implement\u00f3 un operativo de vigilancia a cargo de elementos pertenecientes a las Secretar\u00edas de Seguridad P\u00fablica (SSP) y de la Marina (Semar), as\u00ed como al Ej\u00e9rcito Mexicano, la Fiscal\u00eda General de la Rep\u00fablica (FGR), la Fiscal\u00eda General del Estado (FGE) y las Polic\u00edas Federal y Municipal de M\u00e9rida.<\/p>\n<p>&nbsp;<\/p>\n<p>Antes, durante y despu\u00e9s de la celebraci\u00f3n, se cont\u00f3 con filtros de seguridad en la zona circundante de la sede, torres de vigilancia, unidades de emergencia y de monitoreo, vallas met\u00e1licas y equipos caninos para el resguardo de la integridad de la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 15 de septiembre de 2022.- Miles de yucatecos colmaron la Plaza Grande de esta ciudad para acompa\u00f1ar al Gobernador Mauricio Vila Dosal a encabezar la tradicional ceremonia del Grito que conmemora el 212 aniversario del inicio de la lucha por la Independencia de M\u00e9xico. &nbsp; Desde el balc\u00f3n central de Palacio de Gobierno, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93373","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 15 de septiembre de 2022.- Miles de yucatecos colmaron la Plaza Grande de esta ciudad para acompa\u00f1ar al Gobernador Mauricio Vila Dosal a encabezar la tradicional ceremonia del Grito que conmemora el 212 aniversario del inicio de la lucha por la Independencia de M\u00e9xico. &nbsp; Desde el balc\u00f3n central de Palacio de Gobierno, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T08:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida\",\"datePublished\":\"2022-09-16T08:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/FB_IMG_1663316166854-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/\",\"name\":\"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/FB_IMG_1663316166854-scaled.jpg\",\"datePublished\":\"2022-09-16T08:17:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/FB_IMG_1663316166854-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/FB_IMG_1663316166854-scaled.jpg\",\"width\":768,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 15 de septiembre de 2022.- Miles de yucatecos colmaron la Plaza Grande de esta ciudad para acompa\u00f1ar al Gobernador Mauricio Vila Dosal a encabezar la tradicional ceremonia del Grito que conmemora el 212 aniversario del inicio de la lucha por la Independencia de M\u00e9xico. &nbsp; Desde el balc\u00f3n central de Palacio de Gobierno, [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-09-16T08:17:26+00:00","og_image":[{"width":768,"height":549,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida","datePublished":"2022-09-16T08:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/"},"wordCount":627,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/","name":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg","datePublished":"2022-09-16T08:17:26+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/FB_IMG_1663316166854-scaled.jpg","width":768,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/miles-de-personas-se-dieron-cita-en-el-grito-de-independencia-en-la-plaza-grande-de-merida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Miles de personas se dieron cita en el grito de Independencia en la plaza grande de M\u00e9rida"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=93373"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/93374"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=93373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=93373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=93373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}