{"id":93445,"date":"2022-09-20T16:05:35","date_gmt":"2022-09-20T21:05:35","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=93445"},"modified":"2022-09-20T16:05:35","modified_gmt":"2022-09-20T21:05:35","slug":"ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/","title":{"rendered":"Ponen en marcha el proyecto del Gran Parque La Plancha"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93446\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-696x464.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-1068x712.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 20 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal y el titular de la Secretar\u00eda de la Defensa Nacional (SEDENA), Luis Cresencio Sandoval Gonz\u00e1lez, pusieron en marcha el proyecto de construcci\u00f3n del Gran Parque La Plancha, obra que se da luego de constantes gestiones ante la Federaci\u00f3n y se convertir\u00e1 en un pulm\u00f3n verde, as\u00ed como en nuevo atractivo para el disfrute de las familias yucatecas y la llegada de m\u00e1s turistas, al contar con \u00e1reas de juegos, mercado gastron\u00f3mico, lago artificial, malec\u00f3n, skatepark, parque para mascotas, anfiteatro, andadores, zonas deportivas, gimnasio al aire libre, museos, estaci\u00f3n de IE-Tram, entre otras amenidades.<\/p>\n<p>&nbsp;<\/p>\n<p>En el patio central de la exestaci\u00f3n de ferrocarriles de esta ciudad, Vila Dosal y Sandoval Gonz\u00e1lez encabezaron el inicio a la edificaci\u00f3n de este proyecto que, con una inversi\u00f3n de m\u00e1s de 1,300 millones de pesos, impulsar\u00e1 el desarrollo econ\u00f3mico y tur\u00edstico de la entidad, el cual contar\u00e1 en sus m\u00e1s de 22 hect\u00e1reas de superficie, con un gran abanico de atractivos y \u00e1reas para la sana convivencia y recreaci\u00f3n de locales y quienes visiten Yucat\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>Al presentar el proyecto, el Gobernador afirm\u00f3 que hoy es un d\u00eda importante para los yucatecos porque, con el inicio de este proyecto, se demuestra que, trabajando en equipo, con di\u00e1logo y la disposici\u00f3n de los 3 \u00f3rdenes de Gobierno se pueden hacer grandes cosas por la gente.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, Vila Dosal extern\u00f3 su agradecimiento al Presidente Andr\u00e9s Manuel L\u00f3pez Obrador y el Secretario de la Defensa Nacional por la voluntad que siempre han mostrado para trabajar en coordinaci\u00f3n con Yucat\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abHan sido varios a\u00f1os de esfuerzo, di\u00e1logo y de ponernos de acuerdo, pero no hubiera podido ser posible sin la disposici\u00f3n del Gobierno encabezado por el Presidente, con quien siempre hemos trabajado en equipo\u00bb, afirm\u00f3 el Gobernador.<\/p>\n<p>&nbsp;<\/p>\n<p>Ante el Comandante de la X Regi\u00f3n Militar, General de Divisi\u00f3n Homero Mendoza Ruiz, Vila Dosal record\u00f3 que, tras a\u00f1os en desuso, este espacio se convirti\u00f3 en un basurero p\u00fablico, pues al ser un terreno abandonado, las personas depositaban ah\u00ed su basura, as\u00ed como sus cacharros, adem\u00e1s de que se convirti\u00f3 en un lugar propenso a incendios al haber ramas secas y basura acumulada en el terreno.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otra parte, continu\u00f3 el Gobernador, teniendo escuelas cercanas y siendo una zona concurrida, se volvi\u00f3 propensa a que se cometan actos de violencia y, en \u00e9pocas de lluvias, el lugar se llena de mosquitos que pueden transmitir enfermedades como Dengue, Zika y Chikungunya.<\/p>\n<p>&nbsp;<\/p>\n<p>Cabe se\u00f1alar que este proyecto es producto de las gestiones del Gobernador, ya que originalmente dicha \u00e1rea se dar\u00eda al Ej\u00e9rcito para que se construyeran viviendas y el nuevo cuartel de la Guardia Nacional, por lo que Vila Dosal gestion\u00f3 ante el L\u00f3pez Obrador y luego en un encuentro con Sandoval Gonz\u00e1lez, que dicho espacio de la capital yucateca se destinara para un parque p\u00fablico en esta zona.<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed, convenci\u00f3 al titular de la Sedena de mover las instalaciones militares a otras zonas de la ciudad y se acord\u00f3 que el Gobierno del Estado realizar\u00eda el proyecto del parque en \u201cLa Plancha\u201d y, en marzo pasado, Vila Dosal logr\u00f3 acordar con el Presidente que el terreno se utilice para realizar un parque p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p>Como parte de esta coordinaci\u00f3n, tambi\u00e9n se lleg\u00f3 al acuerdo en el que el Gobierno del Estado y el Ayuntamiento de M\u00e9rida ceder\u00e1n terrenos a las Fuerzas Armadas para construir otras instalaciones que necesitan.<\/p>\n<p>&nbsp;<\/p>\n<p>Este proyecto representa una inversi\u00f3n de m\u00e1s de mil 300 millones de pesos y contar\u00e1, en 4 secciones, con \u00e1reas verdes, andadores techados, ciclopistas, anfiteatro para 10 mil personas, Mercado gastron\u00f3mico, lago artificial de m\u00e1s de 13 mil metros cuadrados, malec\u00f3n, zona de Mascotas (Pet Park), gimnasio al aire libre y \u00e1reas deportivas, ciclov\u00eda, \u00e1reas de viviendas reubicadas, Museo de la Luz, Museo del Ferrocarril, 8 \u00e1reas de juegos infantiles, pista de patinaje y una estaci\u00f3n del IE-Tram.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los beneficios de este proyecto se encuentra que se convertir\u00e1 en pulm\u00f3n verde en la ciudad, con especies de \u00e1rboles y plantas end\u00e9micas por todos sus alrededores, mejorar\u00e1 la calidad de vida de la gente por las nuevas actividades, el comercio y los empleos que generar\u00e1 la obra, se crear\u00e1n m\u00e1s fuentes de empleo, ya que se reactivar\u00e1 giros inmobiliarios, oficinas, el comercio, actividades culturales y de recreaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n, se dar\u00e1 mejor uso a una zona con mucha historia, haci\u00e9ndola parte de nuestro presente y futuro, ser\u00e1 un nuevo espacio de convivencia donde las familias yucatecas disfrutar\u00e1n de amplias actividades deportivas, recreativas, culturales y educativa e incrementar\u00e1 el n\u00famero de visitantes de la zona y se aprovechar\u00e1 la oferta hotelera existente de m\u00e1s de 59 hoteles.<\/p>\n<p>&nbsp;<\/p>\n<p>Aunado a ello, contar\u00e1 con una estaci\u00f3n del IE-Tram, que llevar\u00e1 a pasajeros que lleguen del Tren Maya a Teya hasta el centro de la ciudad, al tiempo que estar\u00e1 unido las dem\u00e1s rutas.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese marco, se indic\u00f3 que en la planeaci\u00f3n del Parque se tom\u00f3 en cuenta la propuesta de un parque metropolitano que hizo la Facultad de Arquitectura y el Colegio Yucateco de Arquitecto en 1994, la de intervenci\u00f3n \u201cEstaci\u00f3n del Conocimiento\u201d impulsada por el Patronato del Centro Hist\u00f3rico 2012; las opiniones del foro interdisciplinario para rescatar el espacio hecho en 2014; las opiniones de los foros ciudadanos organizados por el PUEC \u2013 UNAM Y el Plan Maestro realizado a trav\u00e9s de un ejercicio de participaci\u00f3n ciudadana, ambos en 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>Al brindar detalles, se explic\u00f3 que el Gran parque La Plancha se divide en 4 secciones, de las cuales, la primera albergar\u00e1 el gimnasio al aire libre, las concesiones vagones y la casa de m\u00e1quinas; en la segunda, se encontrar\u00e1n los juegos infantiles, una fuente interactiva y los comedores; en la tercera, estar\u00e1 el acceso, el espejo de agua, un skate park, un pet park y un mercado gastron\u00f3mico y en el cuarto, se ubicar\u00e1 el anfiteatro, juegos infantiles y un gran lago. Todas ellas con ciclopista, andadores y m\u00f3dulos de ba\u00f1os y estacionamiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n se dio a conocer que las viviendas que actualmente se encuentran en esta superficie, se van a reubicar a una zona lateral, para ello se construir\u00e1n viviendas de 220 metros cuadrados, con 3 habitaciones, 2 ba\u00f1os y piezas adicionales. Ante esta situaci\u00f3n, el Gobernador agradeci\u00f3 a los vecinos por su apoyo y disposici\u00f3n en este proyecto.<\/p>\n<p>&nbsp;<\/p>\n<p>Posteriormente, Vila Dosal y el titular de la Sedena realizaron un recorrido por el terreno donde se encontrar\u00e1n las \u00e1reas principales de este nuevo atractivo donde se ubicar\u00e1n el anfiteatro, un lago, el mercado gastron\u00f3mico, la concesi\u00f3n de vagones, el Museo del ferrocarril, la fuente, as\u00ed como el lugar donde se ubicar\u00e1n las nuevas las casas habitaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 20 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal y el titular de la Secretar\u00eda de la Defensa Nacional (SEDENA), Luis Cresencio Sandoval Gonz\u00e1lez, pusieron en marcha el proyecto de construcci\u00f3n del Gran Parque La Plancha, obra que se da luego de constantes gestiones ante la Federaci\u00f3n y se convertir\u00e1 en un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93445","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 20 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal y el titular de la Secretar\u00eda de la Defensa Nacional (SEDENA), Luis Cresencio Sandoval Gonz\u00e1lez, pusieron en marcha el proyecto de construcci\u00f3n del Gran Parque La Plancha, obra que se da luego de constantes gestiones ante la Federaci\u00f3n y se convertir\u00e1 en un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-20T21:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Ponen en marcha el proyecto del Gran Parque La Plancha\",\"datePublished\":\"2022-09-20T21:05:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/\"},\"wordCount\":1203,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0032-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/\",\"name\":\"Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0032-scaled.jpg\",\"datePublished\":\"2022-09-20T21:05:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0032-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0032-scaled.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ponen en marcha el proyecto del Gran Parque La Plancha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/","og_locale":"es_ES","og_type":"article","og_title":"Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 20 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal y el titular de la Secretar\u00eda de la Defensa Nacional (SEDENA), Luis Cresencio Sandoval Gonz\u00e1lez, pusieron en marcha el proyecto de construcci\u00f3n del Gran Parque La Plancha, obra que se da luego de constantes gestiones ante la Federaci\u00f3n y se convertir\u00e1 en un [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-09-20T21:05:35+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Ponen en marcha el proyecto del Gran Parque La Plancha","datePublished":"2022-09-20T21:05:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/"},"wordCount":1203,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/","name":"Ponen en marcha el proyecto del Gran Parque La Plancha - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg","datePublished":"2022-09-20T21:05:35+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0032-scaled.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/ponen-en-marcha-el-proyecto-del-gran-parque-la-plancha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Ponen en marcha el proyecto del Gran Parque La Plancha"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=93445"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/93446"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=93445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=93445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=93445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}