{"id":93451,"date":"2022-09-20T18:05:25","date_gmt":"2022-09-20T23:05:25","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=93451"},"modified":"2022-09-20T18:05:25","modified_gmt":"2022-09-20T23:05:25","slug":"proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/","title":{"rendered":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93452\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-696x464.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-1068x712.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n a 20 de septiembre de 2022<\/p>\n<p>Durante la sesi\u00f3n de la comisi\u00f3n de Arte y Cultura, el presidente diputado Eduardo Sobrino Sierra (PRD), convoc\u00f3 a los integrantes de esta, para llevar a cabo una junta de trabajo y proponer actividades culturales con motivo del 200 aniversario del Augusto Congreso, en las que se considere la participaci\u00f3n de la gente, as\u00ed como de la sociedad civil organizada.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEn esta junta podemos hacer una lluvia de ideas, de c\u00f3mo la comisi\u00f3n puede enriquecer con actividades en este a\u00f1o conmemorativo\u201d, expres\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Al hacer uso de la palabra, la diputada Manuela Cocom Bolio y Jes\u00fas P\u00e9rez Ballote, ambos de la Fracci\u00f3n Legislativa del PAN, coincidieron con el presidente de la comisi\u00f3n, en realizar estas acciones que involucre a todas y todos, en actividades que ayudar\u00e1n a enriquecer el programa conmemorativo a los 200 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>Como parte de los puntos a tratar en la comisi\u00f3n, se distribuy\u00f3 la iniciativa para declarar el 24 de julio como \u201cEl D\u00eda Estatal de la Mediaci\u00f3n\u201d, presentada por la diputada Dafne L\u00f3pez Osorio (PAN).<\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo, la iniciativa para declarar las cabalgatas como Patrimonio Cultural Intangible del Estado de Yucat\u00e1n, suscrita por el diputado del PAN, Esteban Abraham Macari, para la cual, se solicit\u00f3 un proyecto de dictamen, mismo que se analizar\u00e1 y discutir\u00e1 en siguiente sesi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Posteriormente, en sesi\u00f3n de la comisi\u00f3n de Igualdad de G\u00e9nero, continuaron con el an\u00e1lisis de la iniciativa de reforma a la Ley de Acceso de las Mujeres a una Vida Libre de Violencia, en materia del protocolo de actuaci\u00f3n por violencia contra las mujeres en el \u00e1mbito educativo, signada por las diputadas y diputados integrantes de la fracci\u00f3n legislativa del Partido Acci\u00f3n Nacional, en la que se entreg\u00f3 una ficha t\u00e9cnica y un cuadro comparativo.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la distribuci\u00f3n de una ficha t\u00e9cnica y cuadro comparativo, se continu\u00f3 con el an\u00e1lisis de la iniciativa de reforma a la Ley de Acceso de las Mujeres a una Vida Libre de Violencia del Estado de Yucat\u00e1n, en materia de violencia institucional y la facultad de detecci\u00f3n de la violencia de los entes p\u00fablicos en cualquiera de sus modalidades y \u00e1mbitos, presentada por la Fracci\u00f3n Legislativa del PRI.<\/p>\n<p>&nbsp;<\/p>\n<p>De igual manera, se distribuy\u00f3 la iniciativa para modificar la Ley de Acceso de las Mujeres a una Vida Libre de Violencia, la Ley de Salud y la Ley de Educaci\u00f3n, todas del estado de Yucat\u00e1n, en materia de prevenci\u00f3n de la violencia de g\u00e9nero, presentada por la diputada Dafne L\u00f3pez Osorio, para la cual se solicit\u00f3 la elaboraci\u00f3n de una ficha t\u00e9cnica y cuadro comparativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n a 20 de septiembre de 2022 Durante la sesi\u00f3n de la comisi\u00f3n de Arte y Cultura, el presidente diputado Eduardo Sobrino Sierra (PRD), convoc\u00f3 a los integrantes de esta, para llevar a cabo una junta de trabajo y proponer actividades culturales con motivo del 200 aniversario del Augusto Congreso, en las que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93451","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n a 20 de septiembre de 2022 Durante la sesi\u00f3n de la comisi\u00f3n de Arte y Cultura, el presidente diputado Eduardo Sobrino Sierra (PRD), convoc\u00f3 a los integrantes de esta, para llevar a cabo una junta de trabajo y proponer actividades culturales con motivo del 200 aniversario del Augusto Congreso, en las que se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-20T23:05:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso\",\"datePublished\":\"2022-09-20T23:05:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/\"},\"wordCount\":488,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0021-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/\",\"name\":\"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0021-scaled.jpg\",\"datePublished\":\"2022-09-20T23:05:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0021-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220920-WA0021-scaled.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/","og_locale":"es_ES","og_type":"article","og_title":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n a 20 de septiembre de 2022 Durante la sesi\u00f3n de la comisi\u00f3n de Arte y Cultura, el presidente diputado Eduardo Sobrino Sierra (PRD), convoc\u00f3 a los integrantes de esta, para llevar a cabo una junta de trabajo y proponer actividades culturales con motivo del 200 aniversario del Augusto Congreso, en las que se [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-09-20T23:05:25+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso","datePublished":"2022-09-20T23:05:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/"},"wordCount":488,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/","name":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg","datePublished":"2022-09-20T23:05:25+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220920-WA0021-scaled.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/proponen-junta-de-trabajo-para-analizar-actividades-por-los-200-anos-del-augusto-congreso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Proponen junta de trabajo para analizar actividades por los 200 a\u00f1os del Augusto Congreso"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=93451"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/93452"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=93451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=93451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=93451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}