{"id":93630,"date":"2022-09-28T18:47:13","date_gmt":"2022-09-28T23:47:13","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=93630"},"modified":"2022-09-28T18:47:13","modified_gmt":"2022-09-28T23:47:13","slug":"revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/","title":{"rendered":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-93631\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg\" alt=\"\" width=\"768\" height=\"626\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-696x567.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-1068x870.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-515x420.jpg 515w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Ciudad de M\u00e9xico, 28 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal se reuni\u00f3 con el titular de la Defensa Nacional (Sedena), Luis Cresencio Sandoval Gonz\u00e1lez, para dar seguimiento a los avances del proyecto de construcci\u00f3n del Gran Parque La Plancha, que una vez finalizado, se convertir\u00e1 en un pulm\u00f3n verde y en nuevo atractivo para las familias yucatecas y la llegada de m\u00e1s turistas y a quien tambi\u00e9n present\u00f3 un proyecto en beneficio de la Escuela Superior de Artes de Yucat\u00e1n (ESAY).<\/p>\n<p>&nbsp;<\/p>\n<p>De igual manera, el Gobernador sostuvo un encuentro con el director de la Comisi\u00f3n Federal de Electricidad (CFE), Manuel Bartlett D\u00edaz, donde le present\u00f3 el proyecto del IE-Tram para garantizar el suministro el\u00e9ctrico, de la que ser\u00e1 la primera ruta el\u00e9ctrica en el sur-sureste del pa\u00eds y \u00fanica en su tipo en toda Latinoam\u00e9rica.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, Vila Dosal y Bartlett D\u00edaz revisaron los avances de la construcci\u00f3n de 2 plantas de generaci\u00f3n de energ\u00eda el\u00e9ctrica de ciclo combinado, en M\u00e9rida y Valladolid, y la ampliaci\u00f3n del ducto para garantizar el abasto de gas natural a la entidad, que estar\u00e1n contribuyendo a la autosuficiencia energ\u00e9tica de la entidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Al respecto, el director de la CFE inform\u00f3 al Gobernador que las 2 centrales termoel\u00e9ctricas, de M\u00e9rida y Valladolid, van por buen camino y tienen avances importantes, as\u00ed como el proyecto de ampliaci\u00f3n del ducto de gas natural para poder surtir la demanda actual y futura de la industria de Yucat\u00e1n, por lo que se espera que estas obras est\u00e9n listas antes de finalizar el 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>Sobre la reuni\u00f3n con el titular de la Sedena, hay que recordar que el pasado 20 de septiembre el Gobernador y Sandoval Gonz\u00e1lez pusieron en marcha este plan, luego de constantes gestiones ante la Federaci\u00f3n y con una inversi\u00f3n de m\u00e1s de 1,300 millones de pesos contribuir\u00e1 al desarrollo econ\u00f3mico y tur\u00edstico de la entidad, pues contar\u00e1 con una gran variedad de atractivos.<\/p>\n<p>&nbsp;<\/p>\n<p>En el encuentro, el Gobernador y el Secretario de la Defensa Nacional revisaron el proceso de este proyecto, el cual, en sus m\u00e1s de 22 hect\u00e1reas de superficie ofrecer\u00e1 a la gente un abanico de amenidades, tales como \u00e1reas de juegos, mercado gastron\u00f3mico, lago artificial, malec\u00f3n, skatepark, parque para mascotas, anfiteatro, andadores, zonas deportivas, gimnasio al aire libre, museos, estaci\u00f3n de IE-Tram, entre otras.<\/p>\n<p>&nbsp;<\/p>\n<p>Al respecto, Vila Dosal se\u00f1al\u00f3 que entre los beneficios de este proyecto se encuentra que se convertir\u00e1 en pulm\u00f3n verde en la ciudad, con especies de \u00e1rboles y plantas end\u00e9micas por todos sus alrededores, mejorar\u00e1 la calidad de vida de la gente por las nuevas actividades, el comercio y los empleos que generar\u00e1 la obra, ya que se reactivar\u00e1n giros inmobiliarios, oficinas, comercio, actividades culturales y de recreaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n, continu\u00f3, se dar\u00e1 mejor uso a una zona con mucha historia, haci\u00e9ndola parte de nuestro presente y futuro, ser\u00e1 un nuevo espacio de convivencia donde las familias yucatecas disfrutar\u00e1n de amplias actividades deportivas, recreativas, culturales y educativa e incrementar\u00e1 el n\u00famero de visitantes de la zona y se aprovechar\u00e1 la oferta hotelera existente de m\u00e1s de 59 hoteles.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, el Gobernador y el titular de la Sedena refrendaron la disposici\u00f3n de mantener los canales de comunicaci\u00f3n abiertos para seguir llevando por buen camino este proyecto, que contribuir\u00e1 a detonar las capacidades de la entidad con un nuevo espacio para la sana convivencia, el bienestar para la gente y un atractivo para los visitantes.<\/p>\n<p>&nbsp;<\/p>\n<p>Posteriormente, en reuni\u00f3n de trabajo, Vila Dosal present\u00f3 a Bartlett D\u00edaz el plan del IE-Tram, con el objetivo de asegurar el abasto el\u00e9ctrico de este medio de transporte, de manera que se contribuya a mejorar la calidad de la movilidad en el estado y que al mismo tiempo sea de manera amigable con el medio ambiente.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, el Gobernador indic\u00f3 que el IE-Tram es la primera ruta el\u00e9ctrica en todo el sur y sureste del pa\u00eds y \u00fanica en su tipo en toda Latinoam\u00e9rica, que ofrecer\u00e1 un modo de transporte moderno y sustentable, la cual ayudar\u00e1 a la movilidad de los usuarios del Tren Maya, pues sus rutas estar\u00e1n conectadas a las estaciones del proyecto federal.<\/p>\n<p>&nbsp;<\/p>\n<p>Acompa\u00f1ados de Juan Carlos Vega Milke, subsecretario de Energ\u00eda de la Secretar\u00eda de Fomento Econ\u00f3mico y Trabajo (Sefoet), el Gobernador y Bartlett D\u00edaz acordaron continuar trabajando de la mano en este tipo de planes que favorecen el desarrollo de la entidad, as\u00ed como la mejora de la calidad de vida de los yucatecos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico, 28 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal se reuni\u00f3 con el titular de la Defensa Nacional (Sedena), Luis Cresencio Sandoval Gonz\u00e1lez, para dar seguimiento a los avances del proyecto de construcci\u00f3n del Gran Parque La Plancha, que una vez finalizado, se convertir\u00e1 en un pulm\u00f3n verde y en nuevo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-93630","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Ciudad de M\u00e9xico, 28 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal se reuni\u00f3 con el titular de la Defensa Nacional (Sedena), Luis Cresencio Sandoval Gonz\u00e1lez, para dar seguimiento a los avances del proyecto de construcci\u00f3n del Gran Parque La Plancha, que una vez finalizado, se convertir\u00e1 en un pulm\u00f3n verde y en nuevo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T23:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha\",\"datePublished\":\"2022-09-28T23:47:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/\"},\"wordCount\":814,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220928-WA0041-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/\",\"name\":\"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220928-WA0041-scaled.jpg\",\"datePublished\":\"2022-09-28T23:47:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220928-WA0041-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220928-WA0041-scaled.jpg\",\"width\":768,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/","og_locale":"es_ES","og_type":"article","og_title":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto","og_description":"Ciudad de M\u00e9xico, 28 de septiembre de 2022.- El Gobernador Mauricio Vila Dosal se reuni\u00f3 con el titular de la Defensa Nacional (Sedena), Luis Cresencio Sandoval Gonz\u00e1lez, para dar seguimiento a los avances del proyecto de construcci\u00f3n del Gran Parque La Plancha, que una vez finalizado, se convertir\u00e1 en un pulm\u00f3n verde y en nuevo [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-09-28T23:47:13+00:00","og_image":[{"width":768,"height":626,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha","datePublished":"2022-09-28T23:47:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/"},"wordCount":814,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/","name":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg","datePublished":"2022-09-28T23:47:13+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/09\/IMG-20220928-WA0041-scaled.jpg","width":768,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/revisan-avances-del-proyecto-de-construccion-del-gran-parque-la-plancha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Revisan avances del proyecto de construcci\u00f3n del Gran Parque La Plancha"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=93630"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/93630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/93631"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=93630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=93630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=93630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}