{"id":94104,"date":"2022-10-19T09:38:36","date_gmt":"2022-10-19T14:38:36","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=94104"},"modified":"2022-10-19T09:38:36","modified_gmt":"2022-10-19T14:38:36","slug":"mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/","title":{"rendered":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-94105\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp\" alt=\"\" width=\"640\" height=\"360\" \/><\/p>\n<p>De enero a junio de este a\u00f1o, el\u00a0Instituto Mexicano del Seguro Social (IMSS)\u00a0ha atendido a 3 mil 566 derechohabientes con c\u00e1ncer de mama, con lo cual, ya se duplic\u00f3 la cifra de mil 544 mujeres que se atendieron durante todo el 2021, inform\u00f3 a\u00a0Exc\u00e9lsior, Silvia Mart\u00ednez S\u00e1nchez, coordinadora de programas m\u00e9dicos de la divisi\u00f3n de atenci\u00f3n ginecoobst\u00e9trica y perinatal del instituto.<\/p>\n<p>A\u00f1adi\u00f3 que m\u00e1s de 33% lleg\u00f3 en una etapa avanzada, pero aclar\u00f3 que, si una paciente es diagnosticada con un tumor que mida menos de un cent\u00edmetro y sin ganglios comprometidos en la axila, su curaci\u00f3n es mayor al 95%.<\/p>\n<p>Por lo anterior, una mastograf\u00eda a partir de los 40 a\u00f1os y la autoexploraci\u00f3n de los senos, desde los 20 a\u00f1os, hacen la diferencia entre la vida y la muerte, si se llega a padecer c\u00e1ncer de mama.<\/p>\n<p>Como mujeres debemos ense\u00f1ar a nuestras hijas y familiares que nos tenemos que autoexplorar desde los 20 a\u00f1os, que tenemos que conocer nuestro cuerpo, tenemos que tocar nuestras gl\u00e1ndulas y saber en qu\u00e9 momentos hay cambios.<\/p>\n<p>Si detectamos algo raro, debemos acudir inmediatamente al m\u00e9dico familiar. Y a partir de los 40 a\u00f1os debemos iniciar con el tamizaje a trav\u00e9s de una mastograf\u00eda porque la gl\u00e1ndula ya perdi\u00f3 tejido y al hacerse\u00a0 un poquito m\u00e1s grasa,\u00a0 permite ver cualquier malformaci\u00f3n\u201d, explic\u00f3.<\/p>\n<p>Ante este panorama, desde el a\u00f1o 2016 en todo el pa\u00eds, el IMSS cuenta con 10 unidades de detecci\u00f3n y diagn\u00f3stico de c\u00e1ncer de mama, que tienen el objetivo de lograr una detecci\u00f3n temprana de este tipo de neoplasia, con la participaci\u00f3n de 9 m\u00e9dicos radi\u00f3logos y 10 t\u00e9cnicos radi\u00f3logos en cada unidad.<\/p>\n<p>Cuando a la derechohabiente se le realiza la mastograf\u00eda, si se le detecta alguna anomal\u00eda, \u2014en el mismo d\u00eda\u2014 se le realiza un ultrasonido y de ser necesario, con el consentimiento de la paciente, se le practica una biopsia y se procesa.<\/p>\n<p>Si se confirma un tumor maligno, a m\u00e1s tardar en 5 d\u00edas, se le agenda una cita en el \u00e1rea de oncolog\u00eda en el tercer nivel de atenci\u00f3n.<\/p>\n<p>La ventaja que tienen estas unidades de diagn\u00f3stico de c\u00e1ncer es que en un solo d\u00eda se le pueden hacer todos los procesos y si la paciente es diagnosticada por imagen pasa a proyecciones adicionales a trav\u00e9s de un mast\u00f3grafo especial.<\/p>\n<p>Si se requiere alguna biopsia se habla con la paciente y si la paciente en ese momento acepta se le hace la biopsia y se env\u00eda a una unidad asociada y a m\u00e1s tardar en 5 d\u00edas es atendida\u201d, detall\u00f3.<br \/>\nLas citas en estas unidades de detecci\u00f3n y diagn\u00f3stico de c\u00e1ncer de mama del Seguro Social se pueden hacer directamente en cada centro, o a trav\u00e9s de la Unidad de Medicina Familiar (UMF) que le corresponda a la derechohabiente.<\/p>\n<p>EL LIST\u00d3N O MO\u00d1O ROSA<br \/>\nDurante este mes se invita a portar un list\u00f3n o mo\u00f1o rosa, que es el s\u00edmbolo internacional usado por personas, compa\u00f1\u00edas y organizaciones que se comprometen a crear conciencia sobre el c\u00e1ncer de mama y mostrar apoyo moral a las mujeres con esta enfermedad.<\/p>\n<p>El primer list\u00f3n o lazo rosa fue utilizado en el oto\u00f1o de 1991, cuando la Fundaci\u00f3n Susan G. Komen los obsequi\u00f3 a los participantes de una carrera en la ciudad de Nueva York, en alusi\u00f3n a los sobrevivientes del c\u00e1ncer de mama.<\/p>\n<p>La detecci\u00f3n temprana sigue siendo el punto m\u00e1s importante de la lucha contra esta enfermedad.<\/p>\n<p>Cuando el c\u00e1ncer de mama se detecta en una etapa temprana, las posibilidades de curaci\u00f3n son elevadas, si se detecta tard\u00edamente es raro que se pueda ofrecer un tratamiento curativo.<\/p>\n<p>La\u00a0Organizaci\u00f3n Mundial de la Salud (OMS)\u00a0fomenta programas integrales de lucha contra el c\u00e1ncer de mama, dando prioridad a estrategias de prevenci\u00f3n y detecci\u00f3n oportuna con base en la autoexploraci\u00f3n y mastograf\u00eda.<\/p>\n<p>Entre las actividades que se realizan en apoyo a las personas que sufren dicha enfermedad se encuentran:<\/p>\n<p>Carreras deportivas.<br \/>\nIluminaci\u00f3n en color rosa de edificios emblem\u00e1ticos.<br \/>\nCongresos m\u00e9dicos que re\u00fanen a m\u00e9dicos y especialistas para analizar los avances en torno a la cura y tratamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De enero a junio de este a\u00f1o, el\u00a0Instituto Mexicano del Seguro Social (IMSS)\u00a0ha atendido a 3 mil 566 derechohabientes con c\u00e1ncer de mama, con lo cual, ya se duplic\u00f3 la cifra de mil 544 mujeres que se atendieron durante todo el 2021, inform\u00f3 a\u00a0Exc\u00e9lsior, Silvia Mart\u00ednez S\u00e1nchez, coordinadora de programas m\u00e9dicos de la divisi\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-94104","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bienestar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"De enero a junio de este a\u00f1o, el\u00a0Instituto Mexicano del Seguro Social (IMSS)\u00a0ha atendido a 3 mil 566 derechohabientes con c\u00e1ncer de mama, con lo cual, ya se duplic\u00f3 la cifra de mil 544 mujeres que se atendieron durante todo el 2021, inform\u00f3 a\u00a0Exc\u00e9lsior, Silvia Mart\u00ednez S\u00e1nchez, coordinadora de programas m\u00e9dicos de la divisi\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T14:38:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os\",\"datePublished\":\"2022-10-19T14:38:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/\"},\"wordCount\":764,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prev_cancer_mama_251018.jpg_2002894772.webp\",\"articleSection\":[\"Bienestar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/\",\"name\":\"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prev_cancer_mama_251018.jpg_2002894772.webp\",\"datePublished\":\"2022-10-19T14:38:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prev_cancer_mama_251018.jpg_2002894772.webp\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/prev_cancer_mama_251018.jpg_2002894772.webp\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto","og_description":"De enero a junio de este a\u00f1o, el\u00a0Instituto Mexicano del Seguro Social (IMSS)\u00a0ha atendido a 3 mil 566 derechohabientes con c\u00e1ncer de mama, con lo cual, ya se duplic\u00f3 la cifra de mil 544 mujeres que se atendieron durante todo el 2021, inform\u00f3 a\u00a0Exc\u00e9lsior, Silvia Mart\u00ednez S\u00e1nchez, coordinadora de programas m\u00e9dicos de la divisi\u00f3n de [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-10-19T14:38:36+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp","type":"image\/webp"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os","datePublished":"2022-10-19T14:38:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/"},"wordCount":764,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp","articleSection":["Bienestar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/","name":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp","datePublished":"2022-10-19T14:38:36+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/10\/prev_cancer_mama_251018.jpg_2002894772.webp","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujeres-deben-iniciar-autoexploracion-desde-los-20-anos-mastografias-a-los-40-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mujeres deben iniciar autoexploraci\u00f3n desde los 20 a\u00f1os; mastograf\u00edas, a los 40 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/94104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=94104"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/94104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/94105"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=94104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=94104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=94104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}