{"id":94706,"date":"2022-11-14T15:47:52","date_gmt":"2022-11-14T21:47:52","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=94706"},"modified":"2022-11-14T15:47:52","modified_gmt":"2022-11-14T21:47:52","slug":"renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/","title":{"rendered":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-94708\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg 640w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera--630x420.jpeg 630w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div dir=\"ltr\">M\u00e9rida, Yucat\u00e1n a 14 de noviembre de 2022.- Para impulsar el desarrollo equitativo a trav\u00e9s de inversiones que impacten de manera integral la calidad de vida de las y los habitantes de las colonias y comisar\u00edas del sur de la ciudad, el Ayuntamiento de M\u00e9rida realiza obras de dotaci\u00f3n de servicios b\u00e1sicos, rehabilitaci\u00f3n de las vialidades y mantenimiento en el Municipio, afirm\u00f3 el Alcalde, Ren\u00e1n Barrera Concha.<\/div>\n<p>En la gira de trabajo que se realiz\u00f3 en la colonia Manuel Crescencio Rej\u00f3n, ubicada al sur de la ciudad, el Presidente Municipal supervis\u00f3 el mantenimiento integral de las vialidades, banquetas y alumbrado p\u00fablico, as\u00ed como la dotaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica que beneficiar\u00e1 a los habitantes de esa zona.<\/p>\n<p>Acompa\u00f1ado de David Lor\u00eda Magdub y Jos\u00e9 Collado Soberanis, directores de Obras P\u00fablicas y Servicios P\u00fablicos Municipales respectivamente, Barrera Concha tambi\u00e9n escuch\u00f3 y canaliz\u00f3 las solicitudes de las y los vecinos de la colonia, para continuar con el mejoramiento de la zona.<\/p>\n<p>\u201cEn el Ayuntamiento encaminamos las acciones a la construcci\u00f3n de una ciudad con oportunidades y servicios para todas y todos; por ejemplo, los trabajos que hoy supervisamos son una muestra de que realizamos obras de infraestructura, vialidades, espacios p\u00fablicos y ampliamos servicios b\u00e1sicos en las diferentes zonas de la ciudad\u201d, dijo.<\/p>\n<p>Inform\u00f3 que actualmente se construyen 17 obras de ampliaci\u00f3n de agua potable con una inversi\u00f3n de 3 millones 922 mil pesos y 15 obras de ampliaci\u00f3n de red el\u00e9ctrica por 15 millones 484 mil 271 pesos.<\/p>\n<p>\u201cEl servicio de agua potable y la electrificaci\u00f3n son indispensables para llevar una vida digna, por ello, a trav\u00e9s de estas obras, consolidamos la labor humana y social del Municipio para que todas y todos disfruten de sus beneficios\u201d, expres\u00f3.<\/p>\n<p>Adem\u00e1s, se\u00f1al\u00f3 que a finales de este mes dar\u00e1 inicio el programa permanente de rehabilitaci\u00f3n de banquetas en el Centro Hist\u00f3rico, donde se invertir\u00e1n 12 millones de pesos en una primera etapa.<\/p>\n<p>En la supervisi\u00f3n, el Primer Edil recorri\u00f3 la calle 23 por 26 B de la colonia Manuel Crescencio Rej\u00f3n, donde las cuadrillas municipales realizaban labores de poda, chapeo, bacheo, limpieza y desazolve de rejillas, y, posteriormente, recorri\u00f3 la calle 24 entre 23 y 25 donde se ejecutaban acciones de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica.<\/p>\n<p>Por su parte las y los vecinos agradecieron la visita del Alcalde a quien le agradecieron la ejecuci\u00f3n de estas obras que traer\u00e1 grandes beneficios a quienes habitan en esa calle, pero sobre todo porque ayudar\u00e1 a mejorar su calidad de vida.<\/p>\n<p>\u201cGracias a Ren\u00e1n Barrera que est\u00e1 haciendo un buen trabajo, porque ahora nos vamos a sentir m\u00e1s seguros de caminar por las calles ya que se encontraban oscuras, adem\u00e1s de que contaremos con agua potable que es algo de mucha necesidad\u201d, expres\u00f3 Mar\u00eda Gregoria Keb Chal\u00e9.<\/p>\n<p>El vecino Fausto Couoh y Cabrera, dijo que los servicios de red el\u00e9ctrica y agua potable eran un anhelo que ten\u00eda desde hace m\u00e1s de 50 a\u00f1os, tiempo en el que lleva viviendo por esa calle, por lo que agradeci\u00f3 al Presidente Municipal por acercar estas obras de vital importancia para su colonia.<\/p>\n<p>\u201cEste es un sue\u00f1o que nos alegra mucho, el cual nunca pensamos que se nos haga realidad, por eso agradecemos a los buenos gobiernos como el del Alcalde Ren\u00e1n Barrera, porque gracias a \u00e9l vamos a tener agua y luz en nuestra casa\u201d, manifest\u00f3.<\/p>\n<p>Otra vecina, Mar\u00eda Maas Dzul, tambi\u00e9n se sum\u00f3 a los agradecimientos para el Ayuntamiento de M\u00e9rida y el Alcalde Ren\u00e1n Barrera a quien le reconoci\u00f3 el trabajo que hace para beneficiar a la poblaci\u00f3n que habita por el Sur de la ciudad.<\/p>\n<p>\u201cMe siento muy feliz y contenta porque el Alcalde nos tom\u00f3 en cuenta para hacer este trabajo despu\u00e9s de tantos a\u00f1os. Adem\u00e1s, vemos que est\u00e1 trabajado para todos y eso nos da mucho gusto. Qu\u00e9 bueno que contamos con su apoyo\u201d, expres\u00f3.<\/p>\n<p>Los trabajos de ampliaci\u00f3n de red de agua potable de la calle 24 entre 23 y 25 corresponden a la instalaci\u00f3n de 137.00 metros lineales (ML) de tuber\u00eda de 2 1\/2&#8243; y suministro e instalaci\u00f3n de 137 ML de tuber\u00eda de PVC hidr\u00e1ulico de 2 1\/2&#8243; de di\u00e1metro.<\/p>\n<p>En cuanto a la red el\u00e9ctrica se intervienen 143.80 ML que comprende el suministro e instalaci\u00f3n de tres postes de concreto, 98.00 ML de l\u00ednea de media tensi\u00f3n en dos fases dos hilos con cable semi aislado, 143.80 ML de l\u00ednea de baja tensi\u00f3n de neutranel, un transformador monof\u00e1sico de 25 kilovoltamperio (KVA) y colocaci\u00f3n de tres luminarias led.<\/p>\n<p>Finalmente, la inversi\u00f3n de ambas acciones asciende a la cantidad de $565 mil 396.122 provenientes de recursos de infraestructura.<\/p>\n<p>Supervisi\u00f3n de Ampliaci\u00f3n de Red de Agua Potable y Red El\u00e9ctrica en la Colonia Manuel Crescencio Rej\u00f3n. Enlace de descarga\u00a0<a id=\"LPlnk651728\" href=\"https:\/\/we.tl\/t-Hw0fkAo7gN\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">https:\/\/we.tl\/t-Hw0fkAo7gN<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n a 14 de noviembre de 2022.- Para impulsar el desarrollo equitativo a trav\u00e9s de inversiones que impacten de manera integral la calidad de vida de las y los habitantes de las colonias y comisar\u00edas del sur de la ciudad, el Ayuntamiento de M\u00e9rida realiza obras de dotaci\u00f3n de servicios b\u00e1sicos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-94706","post","type-post","status-publish","format-standard","has-post-thumbnail","category-merida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n a 14 de noviembre de 2022.- Para impulsar el desarrollo equitativo a trav\u00e9s de inversiones que impacten de manera integral la calidad de vida de las y los habitantes de las colonias y comisar\u00edas del sur de la ciudad, el Ayuntamiento de M\u00e9rida realiza obras de dotaci\u00f3n de servicios b\u00e1sicos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T21:47:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n\",\"datePublished\":\"2022-11-14T21:47:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/\"},\"wordCount\":878,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/renan-barrera-.jpeg\",\"articleSection\":[\"M\u00e9rida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/\",\"name\":\"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/renan-barrera-.jpeg\",\"datePublished\":\"2022-11-14T21:47:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/renan-barrera-.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/renan-barrera-.jpeg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/","og_locale":"es_ES","og_type":"article","og_title":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto","og_description":"&nbsp; &nbsp; &nbsp; M\u00e9rida, Yucat\u00e1n a 14 de noviembre de 2022.- Para impulsar el desarrollo equitativo a trav\u00e9s de inversiones que impacten de manera integral la calidad de vida de las y los habitantes de las colonias y comisar\u00edas del sur de la ciudad, el Ayuntamiento de M\u00e9rida realiza obras de dotaci\u00f3n de servicios b\u00e1sicos, [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-11-14T21:47:52+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n","datePublished":"2022-11-14T21:47:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/"},"wordCount":878,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg","articleSection":["M\u00e9rida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/","name":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg","datePublished":"2022-11-14T21:47:52+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/11\/renan-barrera-.jpeg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-supervisa-los-trabajos-de-ampliacion-de-red-de-agua-potable-y-energia-electrica-en-la-colonia-manuel-crescencio-rejon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Ren\u00e1n Barrera supervisa los trabajos de ampliaci\u00f3n de red de agua potable y energ\u00eda el\u00e9ctrica en la colonia Manuel Crescencio Rej\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/94706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=94706"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/94706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/94708"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=94706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=94706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=94706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}