{"id":95256,"date":"2022-12-06T12:37:20","date_gmt":"2022-12-06T18:37:20","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95256"},"modified":"2022-12-06T12:37:20","modified_gmt":"2022-12-06T18:37:20","slug":"inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/","title":{"rendered":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95257\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-696x464.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-1068x712.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 6 de diciembre de 2022.- Los personajes navide\u00f1os como Santa Claus, Rodolfo el reno, un duende y un mu\u00f1eco de galleta de jengibre, entre otros, formado con m\u00e1s de 30,000 plantas que incluyen petunias azules, panalillos blancos, ageratos azules, kalanchoes rojos y diversos follajes entre los que destacan el iresine rojo, la carissa y los clavos compactos, se exhibir\u00e1n desde hoy y hasta el 6 de enero de 2023 en el \u201cPaseo Navide\u00f1o de las Flores\u201d en el parque de La Mejorada de esta ciudad.<\/p>\n<p>&nbsp;<\/p>\n<p>La muestra impulsada por el Gobernador Mauricio Vila Dosal como parte de las opciones gratuitas para el disfrute y la sana convivencia de las familias yucatecas durante estas fiestas decembrinas, inici\u00f3 este martes en M\u00e9rida y estar\u00e1 abierta al p\u00fablico en un horario de 9 de la ma\u00f1ana a 10 de la noche.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde temprana hora, visitantes locales y nacionales empezaron a llegar al lugar para apreciar la exhibici\u00f3n de arte floral que tiene como antecedente las ediciones previas del Camino de Flores, la cual se instal\u00f3 por primera ocasi\u00f3n en marzo de 2016 en el Parque de La Mejorada, a iniciativa del entonces presidente municipal de M\u00e9rida, Mauricio Vila Dosal, como un espacio temporal para promover el cuidado ambiental y la preservaci\u00f3n de las tradiciones.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, Cristian Canul Cab celebr\u00f3 que se realicen este tipo de muestras que les permiten a los ciudadanos que visitan el centro de la ciudad distraerse mientras realizan sus compras, esperan su transporte o salen de trabajar.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSe me hace algo muy padre e interesante, normalmente llegas al centro y no hay nada que ver, pero con esto pues ya hay con qu\u00e9 distraerse en los que se espera el cami\u00f3n. Creo que junto con las otras exhibiciones que se han hecho como el Filux, son opciones muy buenas porque distraes a la gente de lo cotidiano y tienes tiempo de pasar el rato\u201d, mencion\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>De manera casi simult\u00e1nea, el \u201cPaseo Navide\u00f1o de las Flores\u201d estar\u00e1 disponible para los habitantes del municipio de Hunucm\u00e1 a partir del 8 de diciembre al 6 de enero en la Plaza Principal, as\u00ed como en las demarcaciones de Izamal y Valladolid, desde el 15 de diciembre hasta el 6 de enero, en la Plaza Principal y en el Parque Sisal, respectivamente.<\/p>\n<p>&nbsp;<\/p>\n<p>La versi\u00f3n de Hunucm\u00e1 rendir\u00e1 un homenaje a la naturaleza de nuestro estado por ser un elemento que atrae a locales y extranjeros por su diversidad y belleza y los visitantes podr\u00e1n observar m\u00e1s de 25,000 plantas entre las que se encuentran: cempas\u00fachil, petunias, panalillos y ageratos, as\u00ed como diversos follajes tales como el leucophyllum y la dichondra plateados.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto en Izamal, se mostrar\u00e1 c\u00f3mo se vive la \u00e9poca navide\u00f1a en el \u00e1mbito familiar y hogare\u00f1o, por lo que recurre a elementos como el \u00e1rbol de navidad, los regalos, el tradicional nacimiento, la parte espiritual y la vivencia en comunidad de la navidad, con los tradicionales pasacalles, las pi\u00f1atas y las luces de las posadas. Ah\u00ed el tapete estar\u00e1 formado por m\u00e1s de 20,000 flores destacando las petunias, cempas\u00fachil y panalillos entre otros, adem\u00e1s de follajes de diversas especies.<\/p>\n<p>&nbsp;<\/p>\n<p>Para el caso de Valladolid, la muestra destaca el Mundo Prehisp\u00e1nico y legado Maya por lo que los sitios arqueol\u00f3gicos de Chich\u00e9n Itz\u00e1 y Ek Balam se combinar\u00e1n con diversos personajes navide\u00f1os como Santa, su trineo y un reno, entre otros. La exhibici\u00f3n estar\u00e1 compuesta por m\u00e1s de 30,000 flores de cempas\u00fachil, petunia, agerato y panalillo que otorgar\u00e1n vibrantes colores a los asistentes.<\/p>\n<p>&nbsp;<\/p>\n<p>En estos tres lugares, el horario de esta exhibici\u00f3n ser\u00e1 desde las 9 de la ma\u00f1ana hasta las 10 de la noche.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, Rosa Carmina Garduza Quiroga vecina del estado de Veracruz, manifest\u00f3 su admiraci\u00f3n por las atracciones que se tienen no solo en M\u00e9rida sino en Yucat\u00e1n y que dan muestra del buen trabajo que se realiza entre los Gobiernos para distraer a visitantes y locales.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEs algo muy bonito que puedan tener este tipo de exhibiciones, no en cualquier lugar se ven este tipo de muestras, ya nos toc\u00f3 igual ver el de las luces y nos divertimos much\u00edsimo\u201d, subray\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta muestra busca tener un alcance mayor a las ediciones anteriores, ya que la edici\u00f3n 2022 contar\u00e1 con cuatro distintas sedes, siendo tres de ellas en el interior del estado, lo cual otorga la oportunidad de generar una experiencia cultural de alto impacto y al mismo tiempo acercar este tipo de eventos a toda la poblaci\u00f3n yucateca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 6 de diciembre de 2022.- Los personajes navide\u00f1os como Santa Claus, Rodolfo el reno, un duende y un mu\u00f1eco de galleta de jengibre, entre otros, formado con m\u00e1s de 30,000 plantas que incluyen petunias azules, panalillos blancos, ageratos azules, kalanchoes rojos y diversos follajes entre los que destacan el iresine rojo, la carissa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-95256","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 6 de diciembre de 2022.- Los personajes navide\u00f1os como Santa Claus, Rodolfo el reno, un duende y un mu\u00f1eco de galleta de jengibre, entre otros, formado con m\u00e1s de 30,000 plantas que incluyen petunias azules, panalillos blancos, ageratos azules, kalanchoes rojos y diversos follajes entre los que destacan el iresine rojo, la carissa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-06T18:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida\",\"datePublished\":\"2022-12-06T18:37:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/\"},\"wordCount\":804,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0005-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/\",\"name\":\"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0005-scaled.jpg\",\"datePublished\":\"2022-12-06T18:37:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0005-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0005-scaled.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/","og_locale":"es_ES","og_type":"article","og_title":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 6 de diciembre de 2022.- Los personajes navide\u00f1os como Santa Claus, Rodolfo el reno, un duende y un mu\u00f1eco de galleta de jengibre, entre otros, formado con m\u00e1s de 30,000 plantas que incluyen petunias azules, panalillos blancos, ageratos azules, kalanchoes rojos y diversos follajes entre los que destacan el iresine rojo, la carissa [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-12-06T18:37:20+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida","datePublished":"2022-12-06T18:37:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/"},"wordCount":804,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/","name":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg","datePublished":"2022-12-06T18:37:20+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0005-scaled.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inicia-la-exhibicion-paseo-navideno-de-las-flores-en-parque-de-la-mejorada-de-merida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Inicia la exhibici\u00f3n \u201cPaseo Navide\u00f1o de las Flores\u201d en parque de La Mejorada de M\u00e9rida"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95256"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95257"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}