{"id":95291,"date":"2022-12-07T10:14:23","date_gmt":"2022-12-07T16:14:23","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95291"},"modified":"2022-12-07T10:14:23","modified_gmt":"2022-12-07T16:14:23","slug":"en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/","title":{"rendered":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95292\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\" alt=\"\" width=\"768\" height=\"511\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-696x463.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-1068x711.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-631x420.jpeg 631w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><br \/>\nM\u00e9rida, Yucat\u00e1n, 7 de diciembre de 2022.- Yucat\u00e1n se reafirma como un importante polo tur\u00edstico gracias a la promoci\u00f3n del estado que realiza el Gobernador Mauricio Vila Dosal a nivel nacional e internacional, y como resultado de ello, en el mes de noviembre arribaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida, siendo el mes con mayor movimiento de pasajeros desde que se tiene registro y que represent\u00f3 un crecimiento de m\u00e1s del 40% respecto del mismo mes de 2021, con lo que se super\u00f3 una vez m\u00e1s el record hist\u00f3rico de llegadas por esta v\u00eda al territorio estatal.<\/p>\n<p>Con ello, se super\u00f3 la cifra hist\u00f3rica del mes de diciembre de 2019, cuando llegaron casi 266,000 pasajeros a la misma terminal a\u00e9rea, por lo que el aumento registrado en el tr\u00e1fico de pasajeros para el reci\u00e9n concluido mes de noviembre de este a\u00f1o comparado con el previo fue de 9%, de acuerdo con datos proporcionados por Grupo Aeroportuario del Sureste (ASUR).<\/p>\n<p>Asimismo, ASUR report\u00f3 un incremento de 39.5% respecto del mismo mes de 2021 en el movimiento de pasajeros de vuelos nacionales y respecto a pasajeros internacionales, se alcanz\u00f3 un aumento del 46.9%, respecto del mismo mes de 2021.<\/p>\n<p>Estas cifras hist\u00f3ricas son consecuencia de una buena recuperaci\u00f3n en Yucat\u00e1n, luego de atravesar la peor pandemia de la historia, por lo que el estado se sigue transformando y avanzando en materia econ\u00f3mica, como resultado de la gran variedad de atractivos tur\u00edsticos que ofrece al p\u00fablico nacional e internacional, por lo que, de enero a noviembre de este a\u00f1o, el tr\u00e1fico de pasajeros que llegaron a la capital yucateca v\u00eda a\u00e9rea fue de 2,752,025 personas.<\/p>\n<p>Aunado a ello, el estado ha incrementado su conexi\u00f3n a\u00e9rea al inaugurar recientemente, el nuevo vuelo directo Guanajuato-M\u00e9rida los d\u00edas lunes y viernes, que opera la l\u00ednea Volaris, as\u00ed como la ruta a\u00e9rea M\u00e9rida-Guatemala y M\u00e9rida-Flores de TAG Airlines, los cuales tienen frecuencias de 4 y 3 vuelos a la semana, respectivamente, con tarifas competitivas.<\/p>\n<p>Adem\u00e1s, el mes de agosto pasado, el Gobernador Vila Dosal y directivos de Viva Aerobus, anunciaron que Yucat\u00e1n contar\u00e1 con una nueva base operativa (Hub a\u00e9reo), de la aerol\u00ednea en el Aeropuerto Internacional de M\u00e9rida, resultado de las gestiones del Gobernador con lo que se permitir\u00e1 que tres aeronaves realicen pernocta y, con ello, se incrementar\u00e1 la conectividad hacia este destino y la generaci\u00f3n de 600 empleos, entre directos e indirectos.<\/p>\n<p>De acuerdo con lo dado a conocer, en su primera fase, la nueva base operar\u00e1 m\u00e1s de 400 vuelos mensuales transportando a m\u00e1s de 160 mil pasajeros, as\u00ed como la entrada de operaci\u00f3n, en los pr\u00f3ximos meses, de 3 nuevas rutas a\u00e9reas para conectar directamente a Yucat\u00e1n con Le\u00f3n, Quer\u00e9taro y Toluca, con lo que sumar\u00edan en total 10 rutas de esta aerol\u00ednea, manteni\u00e9ndose como la l\u00ednea con mayor oferta en el territorio.<\/p>\n<p>Es importante recordar que, Yucat\u00e1n est\u00e1 conectado a trav\u00e9s de 11 rutas nacionales a urbes como Ciudad de M\u00e9xico, Guadalajara, Monterrey, Tuxtla Guti\u00e9rrez, Veracruz, Villahermosa, Tijuana, Oaxaca y en lo que resta de este a\u00f1o se sumar\u00e1n Toluca, Le\u00f3n y Quer\u00e9taro, al igual que 8 trayectos internacionales a Toronto, Canad\u00e1; Houston, Miami, Dallas y Oakland en Estados Unidos; La Habana, Cuba; y Ciudad de Guatemala y Flores, en Guatemala.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 7 de diciembre de 2022.- Yucat\u00e1n se reafirma como un importante polo tur\u00edstico gracias a la promoci\u00f3n del estado que realiza el Gobernador Mauricio Vila Dosal a nivel nacional e internacional, y como resultado de ello, en el mes de noviembre arribaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida, siendo el mes con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-95291","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 7 de diciembre de 2022.- Yucat\u00e1n se reafirma como un importante polo tur\u00edstico gracias a la promoci\u00f3n del estado que realiza el Gobernador Mauricio Vila Dosal a nivel nacional e internacional, y como resultado de ello, en el mes de noviembre arribaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida, siendo el mes con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-07T16:14:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida\",\"datePublished\":\"2022-12-07T16:14:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/\"},\"wordCount\":592,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/\",\"name\":\"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\",\"datePublished\":\"2022-12-07T16:14:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg\",\"width\":768,\"height\":511},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/","og_locale":"es_ES","og_type":"article","og_title":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 7 de diciembre de 2022.- Yucat\u00e1n se reafirma como un importante polo tur\u00edstico gracias a la promoci\u00f3n del estado que realiza el Gobernador Mauricio Vila Dosal a nivel nacional e internacional, y como resultado de ello, en el mes de noviembre arribaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida, siendo el mes con [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-12-07T16:14:23+00:00","og_image":[{"width":768,"height":511,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida","datePublished":"2022-12-07T16:14:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/"},"wordCount":592,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/","name":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg","datePublished":"2022-12-07T16:14:23+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/A3FE54B4-C84F-4900-898B-6A0B722DDA12-scaled.jpeg","width":768,"height":511},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/en-el-mes-de-noviembre-llegaron-310372-pasajeros-al-aeropuerto-internacional-de-merida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"En el mes de noviembre llegaron 310,372 pasajeros al Aeropuerto Internacional de M\u00e9rida"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95291"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95292"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}