{"id":95478,"date":"2022-12-15T09:08:47","date_gmt":"2022-12-15T15:08:47","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95478"},"modified":"2022-12-15T10:27:07","modified_gmt":"2022-12-15T16:27:07","slug":"mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/","title":{"rendered":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95479\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg\" alt=\"\" width=\"768\" height=\"513\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-696x465.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-629x420.jpg 629w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Detuvieron a una mujer que\u00a0mat\u00f3 a sus tres nietos\u00a0en 2019, en Venezuela, cuando estaba tratando de escapar, y que desde hace casi tres a\u00f1os estaba\u00a0pr\u00f3fuga de la ley\u00a0y era intensamente buscada por el asesinato de los menores.<\/p>\n<p>Se trata de Yasm\u00edn Prieto Paduaniz, quien fue detenido en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar de Maiquet\u00eda cuando\u00a0trat\u00f3 de pasar por migraci\u00f3n\u00a0para realizar un vuelo.<\/p>\n<p>La mujer fue acusada por el delito de homicidio intencional calificado, y ten\u00eda una orden de captura el 23 de enero de 2019. Supuestamente, Yazm\u00edn\u00a0ahog\u00f3 a los menores\u00a0porque estaba cansada de mantenerlos, y estaba a su cuidado desde que la madre fue encarcelada.<\/p>\n<p>Anteriormente, a una t\u00eda de los nietos, tambi\u00e9n la hab\u00edan detenido. Aparentemente, la joven de 21 a\u00f1os,\u00a0denunci\u00f3 que no encontraba\u00a0a los menores. El organismo de seguridad empez\u00f3 las pesquisas y encontr\u00f3 los cad\u00e1veres.<\/p>\n<p>Los cuerpos estaban escondidos\u00a0dentro de un tambo sin agua, en un apartamento. Para aquel entonces, el Servicio Nacional de Medicina y Ciencias Forenses determin\u00f3 que los ni\u00f1os fallecieron ahogados. \u201cAsfixia mec\u00e1nica por inmersi\u00f3n\u201d, se\u00f1ala el informe.<\/p>\n<p>Yoenny Daniela, Barayan Alejandro y Barnyelis Fabiana, de cinco, siete y ocho a\u00f1os, respectivamente, son los nombres de los menores que fueron asesinados. Se presume que la madre se encuentra recluida en\u00a0Tocor\u00f3n, un centro penitenciario de Aragua, por un delito totalmente aislado al caso.<\/p>\n<p>Otro caso similar ocurri\u00f3 en la\u00a0India, cuando una madre mat\u00f3 a sus seis hijos avent\u00e1ndolos a un pozo, luego de\u00a0una discusi\u00f3n con su marido. Los menores de 10 a\u00f1os, cayeron a una ci\u00e9naga con una profundidad de seis metros y murieron ahogados.<\/p>\n<p>La polic\u00eda de la India hab\u00eda indicado que se sospechaba que una discusi\u00f3n con el esposo,\u00a0quien estaba borracho, hizo que la mujer de 30 a\u00f1os decidiera arrojar a sus hijos, y que incluso trat\u00f3 de\u00a0quitarse la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detuvieron a una mujer que\u00a0mat\u00f3 a sus tres nietos\u00a0en 2019, en Venezuela, cuando estaba tratando de escapar, y que desde hace casi tres a\u00f1os estaba\u00a0pr\u00f3fuga de la ley\u00a0y era intensamente buscada por el asesinato de los menores. Se trata de Yasm\u00edn Prieto Paduaniz, quien fue detenido en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar de Maiquet\u00eda cuando\u00a0trat\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8908],"tags":[],"class_list":["post-95478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-viral-y-asombroso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Detuvieron a una mujer que\u00a0mat\u00f3 a sus tres nietos\u00a0en 2019, en Venezuela, cuando estaba tratando de escapar, y que desde hace casi tres a\u00f1os estaba\u00a0pr\u00f3fuga de la ley\u00a0y era intensamente buscada por el asesinato de los menores. Se trata de Yasm\u00edn Prieto Paduaniz, quien fue detenido en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar de Maiquet\u00eda cuando\u00a0trat\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T15:08:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T16:27:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela\",\"datePublished\":\"2022-12-15T15:08:47+00:00\",\"dateModified\":\"2022-12-15T16:27:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/\"},\"wordCount\":352,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/apa-scaled.jpg\",\"articleSection\":[\"Viral y Asombroso\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/\",\"name\":\"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/apa-scaled.jpg\",\"datePublished\":\"2022-12-15T15:08:47+00:00\",\"dateModified\":\"2022-12-15T16:27:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/apa-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/apa-scaled.jpg\",\"width\":768,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto","og_description":"Detuvieron a una mujer que\u00a0mat\u00f3 a sus tres nietos\u00a0en 2019, en Venezuela, cuando estaba tratando de escapar, y que desde hace casi tres a\u00f1os estaba\u00a0pr\u00f3fuga de la ley\u00a0y era intensamente buscada por el asesinato de los menores. Se trata de Yasm\u00edn Prieto Paduaniz, quien fue detenido en el Aeropuerto Internacional Sim\u00f3n Bol\u00edvar de Maiquet\u00eda cuando\u00a0trat\u00f3 [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-12-15T15:08:47+00:00","article_modified_time":"2022-12-15T16:27:07+00:00","og_image":[{"width":768,"height":513,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela","datePublished":"2022-12-15T15:08:47+00:00","dateModified":"2022-12-15T16:27:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/"},"wordCount":352,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg","articleSection":["Viral y Asombroso"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/","name":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg","datePublished":"2022-12-15T15:08:47+00:00","dateModified":"2022-12-15T16:27:07+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/apa-scaled.jpg","width":768,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/mujer-mata-a-sus-tres-nietos-porque-supuestamente-estaba-cansada-de-mantenerlos-y-es-detenida-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mujer mata a sus tres nietos porque supuestamente estaba cansada de mantenerlos y es detenida en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95478"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95479"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}