{"id":95493,"date":"2022-12-15T13:41:05","date_gmt":"2022-12-15T19:41:05","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95493"},"modified":"2022-12-15T13:41:05","modified_gmt":"2022-12-15T19:41:05","slug":"familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/","title":{"rendered":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95494\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg\" alt=\"\" width=\"768\" height=\"432\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-696x392.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-1068x601.jpg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-747x420.jpg 747w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Valladolid, Yucat\u00e1n, 15 de diciembre de 2022.- Familias del interior del estado comenzaron a disfrutar de la muestra Paseo Navide\u00f1o de las Flores, que este d\u00eda abri\u00f3 sus puertas de manera simult\u00e1nea en los municipios de Valladolid e Izamal, como parte de las acciones que impulsa el Gobernador Mauricio Vila Dosal para ofrecer opciones gratuitas para el disfrute y la sana convivencia de las familias yucatecas durante las fiestas decembrinas.<\/p>\n<p>&nbsp;<\/p>\n<p>La exhibici\u00f3n de obras de arte floral estar\u00e1 disponible desde hoy y hasta el 6 de enero en un horario de las 9 de la ma\u00f1ana a 10 de la noche, de manera simult\u00e1nea, en el Parque Sisal de la ciudad de Valladolid y en la Plaza Principal, frente al Convento de San Antonio de Padua, en Izamal.<\/p>\n<p>&nbsp;<\/p>\n<p>Para el caso de Valladolid, la exposici\u00f3n de flores y plantas destaca el Mundo Prehisp\u00e1nico y legado Maya por lo que los sitios arqueol\u00f3gicos de Chich\u00e9n Itz\u00e1 y Ek Balam se combinar\u00e1n con diversos personajes navide\u00f1os conformados por m\u00e1s de 30,000 ejemplares de cempas\u00fachil, petunia, agerato y panalillo que otorgar\u00e1n vibrantes colores a las familias y turistas.<\/p>\n<p>&nbsp;<\/p>\n<p>En Izamal, la exhibici\u00f3n muestra c\u00f3mo se vive la \u00e9poca navide\u00f1a en el \u00e1mbito familiar y hogare\u00f1o, por lo que recurre a elementos navide\u00f1os formados por m\u00e1s de 20,000 flores entre las que se incluyen petunias, cempas\u00fachil y panalillos entre otros, adornados con follajes de diversas especies.<\/p>\n<p>&nbsp;<\/p>\n<p>Este espect\u00e1culo de entretenimiento familiar tambi\u00e9n se encuentra disponible para los habitantes del municipio de Hunucm\u00e1 en la Plaza Principal de 9 de la ma\u00f1ana a 10 de la noche como una atracci\u00f3n m\u00e1s para locales y extranjeros que concluir\u00e1 el pr\u00f3ximo 6 de enero.<\/p>\n<p>&nbsp;<\/p>\n<p>De manera similar, desde el pasado 6 de diciembre y hasta el 6 de enero, el Paseo se encuentra abierto en el parque de La Mejorada de la capital, donde los visitantes podr\u00e1n disfrutar de personajes navide\u00f1os hechos con m\u00e1s de 30,000 plantas que otorgan un espect\u00e1culo colorido y atractivo en un horario de 9 de la ma\u00f1ana a 10 de la noche.<\/p>\n<p>&nbsp;<\/p>\n<p>Cabe recordar que esta exhibici\u00f3n tiene como antecedente las ediciones previas del Camino de Flores, la cual se instal\u00f3 por primera ocasi\u00f3n en marzo de 2016 en el Parque de La Mejorada, a iniciativa del entonces presidente municipal de M\u00e9rida, Mauricio Vila Dosal, como un espacio temporal para promover el cuidado ambiental y la preservaci\u00f3n de las tradiciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valladolid, Yucat\u00e1n, 15 de diciembre de 2022.- Familias del interior del estado comenzaron a disfrutar de la muestra Paseo Navide\u00f1o de las Flores, que este d\u00eda abri\u00f3 sus puertas de manera simult\u00e1nea en los municipios de Valladolid e Izamal, como parte de las acciones que impulsa el Gobernador Mauricio Vila Dosal para ofrecer opciones gratuitas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-95493","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Valladolid, Yucat\u00e1n, 15 de diciembre de 2022.- Familias del interior del estado comenzaron a disfrutar de la muestra Paseo Navide\u00f1o de las Flores, que este d\u00eda abri\u00f3 sus puertas de manera simult\u00e1nea en los municipios de Valladolid e Izamal, como parte de las acciones que impulsa el Gobernador Mauricio Vila Dosal para ofrecer opciones gratuitas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T19:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores\",\"datePublished\":\"2022-12-15T19:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/\"},\"wordCount\":440,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0006-1-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/\",\"name\":\"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0006-1-scaled.jpg\",\"datePublished\":\"2022-12-15T19:41:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0006-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/0006-1-scaled.jpg\",\"width\":768,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/","og_locale":"es_ES","og_type":"article","og_title":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto","og_description":"Valladolid, Yucat\u00e1n, 15 de diciembre de 2022.- Familias del interior del estado comenzaron a disfrutar de la muestra Paseo Navide\u00f1o de las Flores, que este d\u00eda abri\u00f3 sus puertas de manera simult\u00e1nea en los municipios de Valladolid e Izamal, como parte de las acciones que impulsa el Gobernador Mauricio Vila Dosal para ofrecer opciones gratuitas [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-12-15T19:41:05+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores","datePublished":"2022-12-15T19:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/"},"wordCount":440,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/","name":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg","datePublished":"2022-12-15T19:41:05+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/0006-1-scaled.jpg","width":768,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/familias-del-interior-del-estado-disfrutan-del-paseo-navideno-de-las-flores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Familias del interior del estado disfrutan del Paseo Navide\u00f1o de las Flores"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95493"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95494"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}