{"id":95622,"date":"2022-12-21T19:22:15","date_gmt":"2022-12-22T01:22:15","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95622"},"modified":"2022-12-21T19:22:15","modified_gmt":"2022-12-22T01:22:15","slug":"arrancan-las-obras-de-construccion-en-el-hospital-de-ticul","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/","title":{"rendered":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95623\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\" alt=\"\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-696x464.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-1068x712.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-630x420.jpeg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Ticul, Yucat\u00e1n, 21 de diciembre de 2022.- El Gobernador Mauricio Vila Dosal y el director del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo Aburto, pusieron en marcha la obra del Hospital General de la zona Ticul, proyecto que qued\u00f3 inconcluso desde hace m\u00e1s de 10 a\u00f1os, y que ofrecer\u00e1 una mejor atenci\u00f3n a la poblaci\u00f3n del sur del estado y fortalecer\u00e1 los servicios de salud en Yucat\u00e1n.<\/p>\n<p>Vila Dosal y Robledo Aburto encabezaron el inicio de edificaci\u00f3n de este nosocomio que, con 70 camas y 15 especialidades, estar\u00e1 fortaleciendo la capacidad hospitalaria de la regi\u00f3n, as\u00ed como la atenci\u00f3n de la poblaci\u00f3n, esto a trav\u00e9s de una inversi\u00f3n 1,073 millones de pesos para su construcci\u00f3n y equipamiento.<\/p>\n<p>Cabe recordar que, resultado de 3 a\u00f1os de di\u00e1logo y gestiones del Gobernador Vila Dosal, ante la empresa Marhnos y la Federaci\u00f3n, el Gobierno del Estado evit\u00f3 un pago de 740 millones de pesos y recuper\u00f3 el proyecto de infraestructura, para reactivar el Hospital de Ticul.<\/p>\n<p>En 2011, el Gobierno de Ivonne Ortega Pacheco firm\u00f3 un convenio para construir un nosocomio en este municipio, bajo un esquema de Proyecto de Prestaci\u00f3n de Servicios (PPS), con una inversi\u00f3n de 5,500 millones de pesos, que se iba a pagar a 25 a\u00f1os. Sin embargo, durante su gesti\u00f3n, Rolando Zapata Bello decidi\u00f3 cancelar el acuerdo, lo que dio paso a una disputa jur\u00eddica y, en 2015, el Tribunal de Arbitraje de la C\u00e1mara de Comercio Internacional conden\u00f3 al Ejecutivo yucateco a pagar 740 millones, como indemnizaci\u00f3n por haber rescindido ese contrato.<\/p>\n<p>Durante su campa\u00f1a, Vila Dosal se comprometi\u00f3 con la gente de Ticul y demarcaciones aleda\u00f1os a terminar esta obra, ya que desde el 2011 han estado esper\u00e1ndola; al iniciar su administraci\u00f3n, el Gobernador se reuni\u00f3 con el Presidente Andr\u00e9s Manuel L\u00f3pez Obrador para platicar de esta problem\u00e1tica, heredada de pasados sexenios, y acordaron trabajar juntos y en equipo para poder resolverla: primero, para que el Gobierno de Yucat\u00e1n no tuviera que hacer el pago del fallo, ya que afectar\u00eda las finanzas estatales, y por otro lado, para que la gente de esa regi\u00f3n pudiera tener el hospital que tanto necesitan.<\/p>\n<p>Por m\u00e1s de a\u00f1o y medio, el Gobernador estuvo trabajando muy fuertemente con el entonces consejero Jur\u00eddico de la Presidencia de la Rep\u00fablica, Julio Scherer Ibarra, y con la empresa Marhnos, dando como resultado que la firma constructora desista de la demanda y el Estado evite pagar los 740 millones de pesos.<\/p>\n<p>Entonces, se firm\u00f3 un convenio, en el que la administraci\u00f3n estatal dio al Instituto Mexicano del Seguro Social (IMSS) el terreno y el edificio construido hasta ahora, para reactivar el proyecto del Hospital de Ticul, lo cual aval\u00f3 el Congreso local.<\/p>\n<p>En su mensaje, el Gobernador expres\u00f3 su agradeciendo al Presidente Andr\u00e9s Manuel porque desde la primera reuni\u00f3 con \u00e9l mostr\u00f3 voluntad para trabajar en conjunto para atender este tema, as\u00ed como al director del IMSS y todo su equipo de trabajo por la disposici\u00f3n para encontrar soluci\u00f3n a la situaci\u00f3n de ese nosocomio.<\/p>\n<p>Tambi\u00e9n, Vila Dosal agradeci\u00f3 a las diputadas y los diputados del Congreso del Estado por aprobar que este patrimonio que es del Gobierno del Estado de Yucat\u00e1n pueda pasar a formar parte del patrimonio del Instituto Mexicano del Seguro Social para que ellos puedan invertir los recursos necesarios en poder terminar esta importante obra.<\/p>\n<p>Acompa\u00f1ado del titular de la Secretar\u00eda de Salud del estado (SSY), Mauricio Sauri Vivas, y la delegada del IMSS Yucat\u00e1n, Miriam S\u00e1nchez Castro, el Gobernador afirm\u00f3 que este hospital vendr\u00e1 a atender una necesidad que se tiene desde hace muchos a\u00f1os, favoreciendo no solo a los ticule\u00f1os, sino a los pobladores de todos los municipios del sur.<\/p>\n<p>Aunado a ello, Vila Dosal se\u00f1al\u00f3 que el beneficio se extiende a todos los yucatecos, ya que contribuir\u00e1 a aliviar la demanda de los hospitales de M\u00e9rida, permitiendo que los yucatecos de otras regiones reciban asistencia de mayor calidad.<\/p>\n<p>\u00abEsto es un ganar-ganar por donde le queramos buscar. Estamos ante uno de los grandes ejemplos de trabajo coordinado entre los 3 \u00f3rdenes de Gobierno, el estatal, el federal y el municipal\u00bb, asever\u00f3.<\/p>\n<p>Indic\u00f3 que est\u00e1 seguro de que trabajando en equipo se va a poder terminar en tiempo y forma, para mayo de 2024 la obra civil, con el posterior equipamiento pueda entrar en funcionamiento al 100%.<\/p>\n<p>\u00abCuando trabajamos en equipo podemos conseguir mejores resultados. Aqu\u00ed en Yucat\u00e1n siempre hemos estado trabajando si colores, eso siempre ha sido desde el primer d\u00eda y creo que este es resultado del trabajo conjunto que estamos realizando\u00bb, finaliz\u00f3.<\/p>\n<p>El director del IMSS, Zo\u00e9 Robledo Aburto, afirm\u00f3 que este d\u00eda es un logro y un hito muy importante en la vinculaci\u00f3n entre el Gobierno de Yucat\u00e1n con el de la Rep\u00fablica, por lo que agradeci\u00f3 al Gobernador por su voluntad pol\u00edtica, disposici\u00f3n y trabajo en equipo para llegar hasta donde ahora se ha llegado.<\/p>\n<p>\u00abNo podemos dejar que la historia se repita para Ticul y su gente, por eso nos vimos como un solo equipo y a partir de eso se estamos trabajando en un proyecto de hospital resolutivo\u00bb, afirm\u00f3.<\/p>\n<p>Tambi\u00e9n, dijo que adem\u00e1s de ofrecer servicios de calidad a derechohabientes, tambi\u00e9n tendr\u00e1 la posibilidad de atender a personas sin seguridad social, lo que lo hace un nosocomio de mucho beneficio para la gente.<\/p>\n<p>Por su parte, el director de la Empresa constructora EPCCOR, Frausto Le\u00f3n Navarro, reiter\u00f3 el compromiso de la firma para que sea concluido en tiempo y forma, para as\u00ed cumplir con la poblaci\u00f3n de esa zona del estado, adem\u00e1s que har\u00e1 todo lo posible para que la gente de la regi\u00f3n sea beneficiada con esta obra a trav\u00e9s de la generaci\u00f3n de empleos y derrama econ\u00f3mica.<\/p>\n<p>En su turno, el alcalde ticule\u00f1o, Rafael Montalvo Mata, agradeci\u00f3 al Gobernador Vila Dosal por cumplir con su palabra, as\u00ed como poner todo el empe\u00f1o y la dedicaci\u00f3n para que la obra del Hospital de Ticul pueda ser una realidad en favor de la regi\u00f3n sur.<\/p>\n<p>En ese sentido, Montalvo Mata agradeci\u00f3 al Gobernador en nombre de Ticul y todo el sur del estado por poner siempre por delante el di\u00e1logo y la salud de las y los yucatecos.<\/p>\n<p>\u00abGracias por darle a Ticul y al sur el hospital que necesitamos. Esta reactivaci\u00f3n es una muestra de voluntad, trabajo coordinado, colaboraci\u00f3n y cooperaci\u00f3n\u00bb, afirm\u00f3.<\/p>\n<p>Sobre el proyecto, Ram\u00f3n Aguirre D\u00edaz, titular de la Unidad de Infraestructura, Proyectos Especiales y Cartera de Inversi\u00f3n del IMSS, se\u00f1al\u00f3 que la instrucci\u00f3n es dotar a Yucat\u00e1n, Ticul y todo el sur de una infraestructura de alta durabilidad y que requiera el m\u00ednimo mantenimiento. Actualmente se est\u00e1n realizando trabajos de limpieza y desmantelamiento.<\/p>\n<p>De acuerdo con lo dado a conocer, este hospital contar\u00e1 con 70 camas, de las cuales 30 ser\u00e1n para hospitalizaci\u00f3n por enfermedades generales y 40 para traumatolog\u00eda, lo que viene a ampliar la capacidad hospitalaria, pero adem\u00e1s se podr\u00e1 ofrecer servicios en 15 especialidades, como terapia respiratoria, inhaloterapia, ginecolog\u00eda y obstetricia, telemedicina, medicina interna, f\u00edsica y rehabilitaci\u00f3n, tococirug\u00eda, nutrici\u00f3n, imagenolog\u00eda y anatom\u00eda patol\u00f3gica, entre otras.<\/p>\n<p>Con ello se estar\u00e1 beneficiando a 36 mil habitantes de Ticul y 10 municipios de la regi\u00f3n, as\u00ed como a m\u00e1s de un mill\u00f3n de derechohabientes en todo el estado con las 40 camas de traumatolog\u00eda.<\/p>\n<p>La obra est\u00e1 programada a ser concluida en mayo de 2024, para pasar a la etapa de equipamiento y pueda iniciar su funcionamiento en junio de ese mismo a\u00f1o.<\/p>\n<p>Del total de la inversi\u00f3n, 636 millones de pesos ser\u00e1n dirigidos a la construcci\u00f3n y 436 millones de pesos para su equipamiento m\u00e9dico especializado, adem\u00e1s que se cobrar\u00e1 con una superficie de 50 mil metros cuadrados, de los cuales 19 mil ser\u00e1n de hospitalizaci\u00f3n.<\/p>\n<p>La construcci\u00f3n est\u00e1 a cargo de la empresa EPCCOR, especializada en proyectos a gran escala como hospitales, con experiencia de m\u00e1s de 70 a\u00f1os y operaciones en M\u00e9xico, Estados Unidos y Latinoam\u00e9rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ticul, Yucat\u00e1n, 21 de diciembre de 2022.- El Gobernador Mauricio Vila Dosal y el director del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo Aburto, pusieron en marcha la obra del Hospital General de la zona Ticul, proyecto que qued\u00f3 inconcluso desde hace m\u00e1s de 10 a\u00f1os, y que ofrecer\u00e1 una mejor atenci\u00f3n a la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-95622","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"Ticul, Yucat\u00e1n, 21 de diciembre de 2022.- El Gobernador Mauricio Vila Dosal y el director del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo Aburto, pusieron en marcha la obra del Hospital General de la zona Ticul, proyecto que qued\u00f3 inconcluso desde hace m\u00e1s de 10 a\u00f1os, y que ofrecer\u00e1 una mejor atenci\u00f3n a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-22T01:22:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal\",\"datePublished\":\"2022-12-22T01:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/\"},\"wordCount\":1410,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/\",\"name\":\"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\",\"datePublished\":\"2022-12-22T01:22:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/","og_locale":"es_ES","og_type":"article","og_title":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto","og_description":"Ticul, Yucat\u00e1n, 21 de diciembre de 2022.- El Gobernador Mauricio Vila Dosal y el director del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo Aburto, pusieron en marcha la obra del Hospital General de la zona Ticul, proyecto que qued\u00f3 inconcluso desde hace m\u00e1s de 10 a\u00f1os, y que ofrecer\u00e1 una mejor atenci\u00f3n a la [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2022-12-22T01:22:15+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal","datePublished":"2022-12-22T01:22:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/"},"wordCount":1410,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/","name":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg","datePublished":"2022-12-22T01:22:15+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2022\/12\/AAEFB802-130E-4FCE-B0F8-EF57437FDFF6-scaled.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/arrancan-las-obras-de-construccion-en-el-hospital-de-ticul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Arrancan las obras de construcci\u00f3n en el hospital de Tic\u00fal"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95622"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95623"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}