{"id":95973,"date":"2023-01-10T10:57:19","date_gmt":"2023-01-10T16:57:19","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=95973"},"modified":"2023-01-10T10:57:19","modified_gmt":"2023-01-10T16:57:19","slug":"grandes-obras-seran-construidas-en-el-estado","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/","title":{"rendered":"Grandes obras ser\u00e1n construidas en el estado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-95974\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\" alt=\"\" width=\"768\" height=\"533\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-218x150.jpeg 218w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-696x483.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-1068x741.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-605x420.jpeg 605w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-100x70.jpeg 100w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><br \/>\nM\u00e9rida, Yucat\u00e1n, 10 de enero de 2023.- Resultado del trabajo coordinado entre el Gobierno estatal, federal, municipal y la iniciativa privada, la administraci\u00f3n de Mauricio Vila Dosal ha impulsado inversiones importantes en materia de infraestructura tur\u00edstica, cultural, deportiva y recreativa, as\u00ed como hospitalaria, educativa, de vivienda, conectividad y de seguridad p\u00fablica que permiten mejorar la calidad de vida de miles de familias yucatecas que ahora cuentan con m\u00e1s oportunidades de empleo y desarrollo.<\/p>\n<p>Es as\u00ed como con el objetivo de fortalecer el turismo a partir de acciones de infraestructura, se present\u00f3 el proyecto del Gran Corredor Tur\u00edstico Gastron\u00f3mico, el cual forma parte tambi\u00e9n de la estrategia M\u00e9rida 2050 que se trabajar\u00e1 en conjunto con el ayuntamiento de M\u00e9rida.<\/p>\n<p>Este proyecto buscar\u00e1 conectar la Plaza Grande, el parque de Santa Luc\u00eda, Santa Ana y el Gran Parque de \u201cLa Plancha\u201d de manera segura y accesible para todos con mejoras a la infraestructura de la movilidad urbana, mediante la mejora de 1,750 ml de calles.<\/p>\n<p>Esta obra incluye la ampliaci\u00f3n de calles, nuevas banquetas, ciclov\u00eda, postes de baja altura, podot\u00e1ctiles para invidentes, rampas para personas con discapacidad motriz, espacios de ascenso y descenso de pasajeros, as\u00ed como carga y descarga de mercanc\u00eda y la instalaci\u00f3n de mesas afuera de negocios, con lo que se transforma la movilidad urbana y, sobre todo, se impulsa la econom\u00eda de los comercios de esta zona.<\/p>\n<p>En materia de conectividad a\u00e9rea, se realizan obras de mejoramiento en el Aeropuerto Internacional de la Ciudad de M\u00e9rida \u201cManuel Crescencio Rej\u00f3n\u201d que permitir\u00e1n ampliar la capacidad de pasajeros que se reciben actualmente en este espacio.<\/p>\n<p>Durante la actual Administraci\u00f3n el Grupo Asur, ha realizado en los \u00faltimos 5 a\u00f1os una inversi\u00f3n de capital privado por un monto de 2,500 millones de pesos, a fin de ampliar y modernizar el edificio terminal y plataforma comercial del aeropuerto, con lo cual dicho inmueble incrementar\u00e1 su capacidad de atenci\u00f3n de pasajeros, que pasar\u00e1 de 2 millones a 4.7 millones de personas al a\u00f1o e incrementar\u00e1 de 10 a 13 posiciones para aeronaves.<\/p>\n<p>Esta inversi\u00f3n tambi\u00e9n incluye la rehabilitaci\u00f3n de plataformas, pistas de rodaje, as\u00ed como la modernizaci\u00f3n del edificio terminal, \u00e1reas comerciales y de servicio. Se espera que las obras concluyan durante el primer semestre del 2023.<\/p>\n<p>Para atraer m\u00e1s visitantes y hacer no s\u00f3lo de M\u00e9rida, sino de todo Yucat\u00e1n un referente en materia tur\u00edstica, durante la administraci\u00f3n de Mauricio Vila se han realizado diversas obras de rehabilitaci\u00f3n del malec\u00f3n de Progreso, con una inversi\u00f3n superior a los 93 millones de pesos; as\u00ed mismo se realiz\u00f3 una inversi\u00f3n de poco m\u00e1s de 9.6 millones de pesos en el mantenimiento y conservaci\u00f3n del malec\u00f3n de Dzilam de Bravo.<\/p>\n<p>Tambi\u00e9n, se trabaj\u00f3 en la reconstrucci\u00f3n y ampliaci\u00f3n del malec\u00f3n de R\u00edo Lagartos con una inversi\u00f3n de 7.54 millones de pesos.<\/p>\n<p>Porque la cultura y las artes tambi\u00e9n son un elemento fundamental para la creaci\u00f3n de empleos y el reforzamiento del tejido social, se realiz\u00f3 la obra de construcci\u00f3n del teatro Jos\u00e9 Mar\u00eda Iturralde y Traconis de Valladolid con una inversi\u00f3n de 7.5 millones de pesos, adem\u00e1s se trabaj\u00f3 en la construcci\u00f3n y mantenimiento del zool\u00f3gico la Reina de Tizim\u00edn con una inversi\u00f3n de 24 millones de pesos.<\/p>\n<p>En materia deportiva y recreativa, durante la administraci\u00f3n se llev\u00f3 a cabo el mantenimiento y conservaci\u00f3n del estadio General Salvador Alvarado con una inversi\u00f3n de 69.7 millones de pesos, as\u00ed como la construcci\u00f3n del parque metropolitano \u201cPaseo Henequenes\u201d donde se erogaron recursos por 177 millones de pesos.<\/p>\n<p>En 2022, se encuentra en ejecuci\u00f3n obras de mantenimiento integral y de construcci\u00f3n de nuevos espacios en el Centro de Alto Rendimiento Deportivo (CARD) con una inversi\u00f3n de 14.3 millones de pesos, adem\u00e1s de la rehabilitaci\u00f3n del centro acu\u00e1tico Rommel Pacheco Marrufo y la cancha de front\u00f3n de la Unidad Deportiva Kukulc\u00e1n en el municipio de M\u00e9rida. Tambi\u00e9n se llev\u00f3 a cabo la impermeabilizaci\u00f3n de la c\u00fapula del Polif\u00f3rum Zamn\u00e1, los cuales contemplan una inversi\u00f3n acumulada de 24.72 millones de pesos.<\/p>\n<p>Como resultado de diversas gestiones, en el periodo que se informa la Secretar\u00eda de la Defensa Nacional (SEDENA) inici\u00f3 en el mes de septiembre los trabajos de construcci\u00f3n del Gran Parque de La Plancha en la que el Gobierno Federal invertir\u00e1 m\u00e1s de 1,300 millones de pesos.<br \/>\nEn infraestructura hospitalaria, en el Gobierno de Vila se han realizado trabajos de rehabilitaci\u00f3n y equipamiento de m\u00e1s de 50 centros de salud con una inversi\u00f3n superior a los 80 millones de pesos.<\/p>\n<p>De igual forma, se llevaron a cabo las primeras etapas para la construcci\u00f3n del Hospital General Naval (SEMAR) en la Base Naval de la localidad de Yucalpet\u00e9n en el municipio de Progreso, Yucat\u00e1n con una inversi\u00f3n conjunta de m\u00e1s de 129 millones de pesos.<\/p>\n<p>En el sector educativo, se realiz\u00f3 la construcci\u00f3n de las primeras 2 etapas del campus de la Escuela Normal Superior con una Inversi\u00f3n de 64.6 millones de pesos; se realizaron 7,200 acciones de infraestructura en 2,118 escuelas p\u00fablicas de nivel b\u00e1sico, medio superior y superior del estado de Yucat\u00e1n. En materia de construcci\u00f3n, rehabilitaci\u00f3n, equipamiento y mantenimiento emergente, se intervinieron 702 centros escolares de preescolar, 943 de primaria, 372 de secundaria, 68 de media superior y 33 en nivel superior de los 106 municipios del estado. Todas estas acciones contaron con una inversi\u00f3n de 1, 292 millones de pesos.<\/p>\n<p>Tambi\u00e9n se realizaron 6,423 acciones de mantenimiento emergente, con una inversi\u00f3n de 289.7 millones de pesos, en beneficio de 1,975 escuelas del estado de Yucat\u00e1n: 662 centros preescolares, 916 primarias, 353 secundarias y 44 de nivel medio superior.<\/p>\n<p>En la actual administraci\u00f3n, tambi\u00e9n se han atendido un total de 358.608 kil\u00f3metros con trabajos de conservaci\u00f3n, modernizaci\u00f3n, construcci\u00f3n y reconstrucci\u00f3n de carreteras y caminos, con una inversi\u00f3n superior a los 667.04 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 10 de enero de 2023.- Resultado del trabajo coordinado entre el Gobierno estatal, federal, municipal y la iniciativa privada, la administraci\u00f3n de Mauricio Vila Dosal ha impulsado inversiones importantes en materia de infraestructura tur\u00edstica, cultural, deportiva y recreativa, as\u00ed como hospitalaria, educativa, de vivienda, conectividad y de seguridad p\u00fablica que permiten mejorar la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-95973","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 10 de enero de 2023.- Resultado del trabajo coordinado entre el Gobierno estatal, federal, municipal y la iniciativa privada, la administraci\u00f3n de Mauricio Vila Dosal ha impulsado inversiones importantes en materia de infraestructura tur\u00edstica, cultural, deportiva y recreativa, as\u00ed como hospitalaria, educativa, de vivienda, conectividad y de seguridad p\u00fablica que permiten mejorar la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T16:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Grandes obras ser\u00e1n construidas en el estado\",\"datePublished\":\"2023-01-10T16:57:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/\"},\"wordCount\":1028,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/\",\"name\":\"Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\",\"datePublished\":\"2023-01-10T16:57:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg\",\"width\":768,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/grandes-obras-seran-construidas-en-el-estado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grandes obras ser\u00e1n construidas en el estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/","og_locale":"es_ES","og_type":"article","og_title":"Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 10 de enero de 2023.- Resultado del trabajo coordinado entre el Gobierno estatal, federal, municipal y la iniciativa privada, la administraci\u00f3n de Mauricio Vila Dosal ha impulsado inversiones importantes en materia de infraestructura tur\u00edstica, cultural, deportiva y recreativa, as\u00ed como hospitalaria, educativa, de vivienda, conectividad y de seguridad p\u00fablica que permiten mejorar la [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2023-01-10T16:57:19+00:00","og_image":[{"width":768,"height":533,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Grandes obras ser\u00e1n construidas en el estado","datePublished":"2023-01-10T16:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/"},"wordCount":1028,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/","name":"Grandes obras ser\u00e1n construidas en el estado - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg","datePublished":"2023-01-10T16:57:19+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/AB76E52C-3336-41CF-A9D2-ABAE8108E8BE-scaled.jpeg","width":768,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/grandes-obras-seran-construidas-en-el-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Grandes obras ser\u00e1n construidas en el estado"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=95973"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/95973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/95974"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=95973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=95973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=95973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}