{"id":96010,"date":"2023-01-12T09:05:18","date_gmt":"2023-01-12T15:05:18","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=96010"},"modified":"2023-01-12T09:05:18","modified_gmt":"2023-01-12T15:05:18","slug":"el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/","title":{"rendered":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-96011\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg\" alt=\"\" width=\"768\" height=\"433\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549-696x392.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549-745x420.jpg 745w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>El peso mexicano alcanz\u00f3 ayer su mejor cotizaci\u00f3n frente al d\u00f3lar en tres a\u00f1os, antes de que el coronavirus se declarara pandemia. Por primera vez desde febrero de 2020, el tipo de cambio se negoci\u00f3 en menos de 19 pesos por d\u00f3lar, un valor que refleja la depreciaci\u00f3n de la moneda estadunidense y el incremento de la llegada de divisas a M\u00e9xico, tanto por operaciones de comercio exterior, como por remesas e inversi\u00f3n extranjera.<\/p>\n<p>De acuerdo con datos del Banco de M\u00e9xico (BdeM), el peso se apreci\u00f3 0.58 por ciento frente a la moneda estadunidense, equivalente a 11.15 centavos, para cerrar en 18.9498 unidades por d\u00f3lar\u00a0spot\u00a0(mercado al mayoreo), convirti\u00e9ndola en la quinta moneda m\u00e1s apreciada a nivel internacional durante el d\u00eda.<\/p>\n<p>La paridad peso-d\u00f3lar oper\u00f3 la sesi\u00f3n entre un m\u00e1ximo de 19.0850 unidades y un m\u00ednimo de 18.9170. Con el cierre de ayer, la moneda mexicana acumul\u00f3 una ganancia de 2.9 por ciento en 2023; en pleno inicio de la emergencia sanitaria, durante abril de 2020, lleg\u00f3 a 25.1050 por d\u00f3lar.<\/p>\n<p>La moneda mexicana alcanz\u00f3 su mejor nivel frente al d\u00f3lar en tres a\u00f1os, debido a que la divisa estadunidense se depreci\u00f3 ante la expectativa de que la inflaci\u00f3n comience a desacelerar y, por tanto, venga un freno sustancial en los incrementos de las tasas de inter\u00e9s de la Reserva Federal (Fed). Tambi\u00e9n se apreciaron las monedas de Colombia, Chile, Indonesia, Per\u00fa, Rusia e India, entre otras.<\/p>\n<p>Si se cumplen las previsiones de los analistas, el dato de inflaci\u00f3n estadunidense que se conocer\u00e1 hoy podr\u00eda registrar una ca\u00edda, desde el 7.1 por ciento de noviembre a un rango de entre 6.5 y 6.7 por ciento, lo que implicar\u00eda alzas menos agresivas de la Fed.<\/p>\n<p>La Secretar\u00eda de Hacienda destac\u00f3 en su cuenta de Twitter que el peso se consolida como una de las monedas m\u00e1s fuertes, dada la cotizaci\u00f3n en que cerr\u00f3 ayer, por debajo de los 19 pesos respecto al d\u00f3lar, lo que no suced\u00eda desde hace casi tres a\u00f1os.<\/p>\n<p>La extraordinaria entrada de d\u00f3lares a M\u00e9xico por concepto de exportaciones, remesas, inversi\u00f3n extranjera directa, turismo e inversi\u00f3n extranjera en valores gubernamentales ayuda a la percepci\u00f3n del peso en los mercados, reiter\u00f3 Janneth Quiroz, subdirectora de an\u00e1lisis econ\u00f3micos de Monex.<\/p>\n<p>A\u00f1adi\u00f3 que la Cumbre de L\u00edderes de Am\u00e9rica del Norte aliment\u00f3 las expectativas de que podr\u00eda acelerarse la inversi\u00f3n en el pa\u00eds por el\u00a0nearshoring\u00a0(relocalizaci\u00f3n de empresas) y de que se tenga una soluci\u00f3n amistosa del posible panel de arbitraje internacional por las diferencias en materia energ\u00e9tica, en el marco del T-MEC.<\/p>\n<p>Juan Musi, asesor financiero y socio en Alpha Patrimonial, afirm\u00f3 que el mercado financiero se ha adelantado a un buen dato.<\/p>\n<p>Octava sesi\u00f3n al hilo de ganancias en la BMV<\/p>\n<p>Un mayor apetito por el riesgo a nivel global se ha extendido al \u00cdndice de Precios y Cotizaciones de la Bolsa Mexicana de Valores (S&amp;P\/BMV IPC). El principal \u00edndice accionario mexicano gan\u00f3 ayer 1.55 por ciento, llegando a 53 mil 209 puntos, marcando su octava sesi\u00f3n consecutiva de ganancias. Con esto, el IPC acumula una avance de 9.79 por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso mexicano alcanz\u00f3 ayer su mejor cotizaci\u00f3n frente al d\u00f3lar en tres a\u00f1os, antes de que el coronavirus se declarara pandemia. Por primera vez desde febrero de 2020, el tipo de cambio se negoci\u00f3 en menos de 19 pesos por d\u00f3lar, un valor que refleja la depreciaci\u00f3n de la moneda estadunidense y el incremento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":96011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-96010","post","type-post","status-publish","format-standard","has-post-thumbnail","category-emprendedores-y-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"El peso mexicano alcanz\u00f3 ayer su mejor cotizaci\u00f3n frente al d\u00f3lar en tres a\u00f1os, antes de que el coronavirus se declarara pandemia. Por primera vez desde febrero de 2020, el tipo de cambio se negoci\u00f3 en menos de 19 pesos por d\u00f3lar, un valor que refleja la depreciaci\u00f3n de la moneda estadunidense y el incremento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-12T15:05:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar\",\"datePublished\":\"2023-01-12T15:05:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/\"},\"wordCount\":562,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/prin2-69d8c0d8-focus-0-0-732-549.jpg\",\"articleSection\":[\"Emprendedores y Finanzas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/\",\"name\":\"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/prin2-69d8c0d8-focus-0-0-732-549.jpg\",\"datePublished\":\"2023-01-12T15:05:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/prin2-69d8c0d8-focus-0-0-732-549.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/prin2-69d8c0d8-focus-0-0-732-549.jpg\",\"width\":768,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/","og_locale":"es_ES","og_type":"article","og_title":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto","og_description":"El peso mexicano alcanz\u00f3 ayer su mejor cotizaci\u00f3n frente al d\u00f3lar en tres a\u00f1os, antes de que el coronavirus se declarara pandemia. Por primera vez desde febrero de 2020, el tipo de cambio se negoci\u00f3 en menos de 19 pesos por d\u00f3lar, un valor que refleja la depreciaci\u00f3n de la moneda estadunidense y el incremento [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2023-01-12T15:05:18+00:00","og_image":[{"width":768,"height":433,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar","datePublished":"2023-01-12T15:05:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/"},"wordCount":562,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg","articleSection":["Emprendedores y Finanzas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/","name":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg","datePublished":"2023-01-12T15:05:18+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/prin2-69d8c0d8-focus-0-0-732-549.jpg","width":768,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/el-peso-se-fortalece-cotizacion-en-menos-de-19-por-dolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"El peso se fortalece; cotizaci\u00f3n en menos de 19 por d\u00f3lar"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=96010"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/96011"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=96010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=96010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=96010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}