{"id":96273,"date":"2023-01-24T14:13:49","date_gmt":"2023-01-24T20:13:49","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=96273"},"modified":"2023-01-24T14:13:49","modified_gmt":"2023-01-24T20:13:49","slug":"inician-los-trabajos-del-proyecto-ie-tram","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/","title":{"rendered":"Inician los trabajos del proyecto Ie-Tram"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-96274\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg\" alt=\"\" width=\"768\" height=\"563\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-696x511.jpg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-572x420.jpg 572w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-80x60.jpg 80w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>M\u00e9rida, Yucat\u00e1n, 24 de enero de 2023.- Arrancan, con el banderazo del Gobernador Mauricio Vila Dosal, los trabajos preliminares del Ie-Tram, transporte p\u00fablico \u00fanico en Latinoam\u00e9rica y que ser\u00e1 100% el\u00e9ctrico para ofrecer a los yucatecos una opci\u00f3n de movilidad eficiente, moderna y segura conectando a m\u00e1s de 100 rutas de transporte p\u00fablico y m\u00e1s de 137 colonias de la zona conurbada, uniendo a M\u00e9rida, Kanas\u00edn y Um\u00e1n.<\/p>\n<p>Desde los rieles del fraccionamiento Mayap\u00e1n, Vila Dosal, junto con los alcaldes de M\u00e9rida, Ren\u00e1n Barrera Concha; Kanas\u00edn, Edwin Boj\u00f3rquez Ram\u00edrez y de Um\u00e1n, Gaspar Cisneros Polanco, realiz\u00f3 el banderazo y supervisi\u00f3n del inicio de los trabajos de construcci\u00f3n preliminares de los corredores de lo que ser\u00e1 el nuevo transporte p\u00fablico Ie-Tram, en un esfuerzo sin precedente para ofrecer los servicios de transporte p\u00fablico a la altura de lo que merecen las y los yucatecos.<\/p>\n<p>En ese marco, Vila Dosal indic\u00f3 que el Ie-Tram es producto del trabajo coordinado entre los 3 \u00f3rdenes de gobierno y la iniciativa privada, con una inversi\u00f3n total de 2,820 millones de pesos, donde el Gobierno del Estado va a poner 61% de los recursos; el Gobierno federal el 23%, y la iniciativa privada, el 16% para la instalaci\u00f3n de este tipo de veh\u00edculo que tiene todas las bondades de un tranv\u00eda, pero la flexibilidad de un autob\u00fas que ser\u00e1 la primera ruta 100% el\u00e9ctrica del sureste del pa\u00eds, medio de transporte que, hoy en d\u00eda, solamente est\u00e1n circulando en algunas ciudades de Europa y del Medio Oriente, en Qatar y en Emiratos \u00c1rabes Unidos, por lo que se estar\u00e1 generando una serie de infraestructura.<\/p>\n<p>\u201cEste es un proyecto que present\u00e9 al Presidente Andr\u00e9s Manuel L\u00f3pez Obrador y que estar\u00e1 uniendo a m\u00e1s de 137 colonias de M\u00e9rida, Kanas\u00edn y Um\u00e1n, con m\u00e1s de 100 rutas de autobuses, y son m\u00e1s de 200,000 personas que van a ser beneficiadas; adem\u00e1s de que sus rutas van a conferir tambi\u00e9n en el Gran Parque de La plancha que ya se est\u00e1 construyendo por la Secretar\u00eda de la Defensa Nacional con una inversi\u00f3n de 1,300 millones de pesos\u201d, apunt\u00f3 Vila Dosal.<\/p>\n<p>El Gobernador indic\u00f3 que vamos a estar trabajando todo este a\u00f1o a marchas forzadas y necesitamos el apoyo de todos los que estamos aqu\u00ed, especialmente de los ciudadanos y tenemos el compromiso de poder terminar esta obra para diciembre de este a\u00f1o, se\u00f1al\u00f3 en presencia del representante de la Secretar\u00eda de Gobernaci\u00f3n en Yucat\u00e1n, Andr\u00e9s Peralta Rivera.<\/p>\n<p>Acompa\u00f1ado del titular de la Secretar\u00eda de Obras P\u00fablicas (SOP), Aref Miguel Karam Esp\u00f3sitos y del director general del Instituto de Movilidad de Desarrollo Urbano Territorial (Imdut), Rafael Hern\u00e1ndez Kotasek, Vila Dosal record\u00f3 tambi\u00e9n que, \u201cVa y ven\u201d es el nuevo Sistema de Transporte P\u00fablico que estamos creando en la ciudad de M\u00e9rida, con su Ruta Perif\u00e9rico, su Ruta Aeropuerto, las Rutas Nocturnas y ahora, se sumar\u00e1n las rutas del Ie-Tram.<\/p>\n<p>Tambi\u00e9n, el Gobernador destac\u00f3 que este a\u00f1o se recibir\u00e1n 350 nuevos autobuses, de los cuales, ya se encuentran los primeros 34 que est\u00e1n en pruebas y a principios de febrero se podr\u00e1n estar incorporando para continuar mejorando los servicios de transporte p\u00fablico como parte de las 10 acciones concretas para reducir los tiempos de espera y brindar un servicio de calidad a la altura de lo que los yucatecos merecen.<\/p>\n<p>Al ofrecer una explicaci\u00f3n sobre los primeros trabajos, el director general del Instituto de Infraestructura Carretera de Yucat\u00e1n, Sergio Augusto Chan Lugo, indic\u00f3 que se est\u00e1 iniciando con este proceso que consta en este tramo de 5 kil\u00f3metros que ser\u00e1n los m\u00e1s complejos por el retiro de las rieles y en el cual se trabajar\u00e1 durante 120 d\u00edas, donde estar\u00e1 con un carril confinado que va desde La plancha hasta el Perif\u00e9rico, toda la calle 39, se construir\u00e1 despu\u00e9s de haber retirado las rieles, toda la infraestructura necesaria para los carriles exclusivos o confinados.<\/p>\n<p>\u201cLa inversi\u00f3n en este primer tramo es de m\u00e1s de 244 millones de pesos tomando en cuenta lo estrat\u00e9gico para enlazar la terminal del Tren Maya con la plancha y en junio estaremos terminando el tramo Teya-Kanas\u00edn hacia La Plancha. Estamos en tiempo con los trabajos y se tendr\u00e1n en este primer tramo, 5 frentes de trabajo simult\u00e1neos para entregar en tiempo y forma las debidas obras en beneficio de 1,141,652 habitantes\u201d, indic\u00f3 Chan Lugo.<\/p>\n<p>Los trabajos preliminares consisten en la construcci\u00f3n de pavimentos de concreto hidr\u00e1ulico, guarniciones, banquetas y separador, ciclov\u00eda con concreto asf\u00e1ltico y se\u00f1alamiento horizontal y vertical. Tambi\u00e9n, la rehabilitaci\u00f3n de alumbrado p\u00fablico y canalizaciones para sem\u00e1foros en cruceros; adem\u00e1s se instalar\u00e1n 46 estaciones de transbordo gratuito y 21 paraderos. En los casos de las estaciones el transbordo es gratuito y en caso de los paraderos cuando el usuario venga de otra ruta pagar\u00e1 solo el 50%.<\/p>\n<p>El Ie-Tram, adem\u00e1s de unir M\u00e9rida, Kanas\u00edn, Um\u00e1n y 137 colonias, tambi\u00e9n ser\u00e1 un transporte complementario a las estaciones del Tren Maya y ser\u00e1 una realidad a trav\u00e9s de una inversi\u00f3n total de 2,820 millones de pesos, de los cuales el 60% aportar\u00e1 el Gobierno del Estado, el Gobierno federal el 23% y la iniciativa privada el 16%, presupuesto que incluye las unidades, infraestructura vial complementaria y el\u00e9ctrica, as\u00ed como adecuaciones en ruta y en el Centro Hist\u00f3rico.<\/p>\n<p>Para su funcionamiento, se har\u00e1 uso de novedosas unidades que hacen de este servicio una actividad sustentable al ser 100% el\u00e9ctrico con cero emisiones, reducir la contaminaci\u00f3n del ruido y el di\u00f3xido de carbono que absorben estas unidades y equivalen a m\u00e1s de 170 mil \u00e1rboles plantados en cuanto a la reducci\u00f3n de CO2 en 10 a\u00f1os.<\/p>\n<p>Dichas unidades est\u00e1n equipadas con sistemas innovadores de seguridad para el control de velocidad, as\u00ed como optimizaci\u00f3n del manejo de los operadores, cargadores USB, WiFi, pulsadores en Braille, geolocalizador en tiempo real, informaci\u00f3n para el pasajero, integrado a la App del Va y Ven, y vinilos interiores. Es accesible, con 4 puertas deslizantes y entradas bajas, entrada y espacios para sillas de ruedas.<\/p>\n<p>Para el desarrollo del Ie-tram en el estado, se realizar\u00e1 un refuerzo integral en la infraestructura vial con m\u00e1s de 100 kil\u00f3metros de carriles nuevos y preferente para el transporte, infraestructura el\u00e9ctrica de carga, accesibilidad en autobuses, ruta y paraderos, paraderos e infraestructura complementaria en el Centro Hist\u00f3rico de M\u00e9rida para conectar con rutas actuales para mejorar la vialidad e imagen de este punto.<\/p>\n<p>Son 100 kil\u00f3metros a trav\u00e9s de 5 rutas con alta demanda: Centro-Um\u00e1n, Facultad de Ingenier\u00eda Uady-Centro, Kanas\u00edn-Centro, Poxil\u00e1-Centro y Teya-Centro y se utilizar\u00e1 las viejas v\u00edas del tren que se encuentran abandonadas, transform\u00e1ndolas en senderos de uso para el transporte p\u00fablico y movilidad urbana sustentable.<\/p>\n<p>Todo ello para ofrecer a las y los yucatecos una alternativa de traslado m\u00e1s r\u00e1pido, moderno y sustentable, con lo que Yucat\u00e1n contin\u00faa avanzando firmemente en la transformaci\u00f3n del sistema de transporte p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, Yucat\u00e1n, 24 de enero de 2023.- Arrancan, con el banderazo del Gobernador Mauricio Vila Dosal, los trabajos preliminares del Ie-Tram, transporte p\u00fablico \u00fanico en Latinoam\u00e9rica y que ser\u00e1 100% el\u00e9ctrico para ofrecer a los yucatecos una opci\u00f3n de movilidad eficiente, moderna y segura conectando a m\u00e1s de 100 rutas de transporte p\u00fablico y m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":96274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-96273","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, Yucat\u00e1n, 24 de enero de 2023.- Arrancan, con el banderazo del Gobernador Mauricio Vila Dosal, los trabajos preliminares del Ie-Tram, transporte p\u00fablico \u00fanico en Latinoam\u00e9rica y que ser\u00e1 100% el\u00e9ctrico para ofrecer a los yucatecos una opci\u00f3n de movilidad eficiente, moderna y segura conectando a m\u00e1s de 100 rutas de transporte p\u00fablico y m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-24T20:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Inician los trabajos del proyecto Ie-Tram\",\"datePublished\":\"2023-01-24T20:13:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/\"},\"wordCount\":1231,\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/0002-4-scaled.jpg\",\"articleSection\":[\"Yucat\u00e1n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/\",\"name\":\"Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/0002-4-scaled.jpg\",\"datePublished\":\"2023-01-24T20:13:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/0002-4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/0002-4-scaled.jpg\",\"width\":768,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/inician-los-trabajos-del-proyecto-ie-tram\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inician los trabajos del proyecto Ie-Tram\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/","og_locale":"es_ES","og_type":"article","og_title":"Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto","og_description":"M\u00e9rida, Yucat\u00e1n, 24 de enero de 2023.- Arrancan, con el banderazo del Gobernador Mauricio Vila Dosal, los trabajos preliminares del Ie-Tram, transporte p\u00fablico \u00fanico en Latinoam\u00e9rica y que ser\u00e1 100% el\u00e9ctrico para ofrecer a los yucatecos una opci\u00f3n de movilidad eficiente, moderna y segura conectando a m\u00e1s de 100 rutas de transporte p\u00fablico y m\u00e1s [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2023-01-24T20:13:49+00:00","og_image":[{"width":768,"height":563,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Inician los trabajos del proyecto Ie-Tram","datePublished":"2023-01-24T20:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/"},"wordCount":1231,"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg","articleSection":["Yucat\u00e1n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/","name":"Inician los trabajos del proyecto Ie-Tram - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg","datePublished":"2023-01-24T20:13:49+00:00","author":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/01\/0002-4-scaled.jpg","width":768,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/inician-los-trabajos-del-proyecto-ie-tram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Inician los trabajos del proyecto Ie-Tram"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=96273"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/96274"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=96273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=96273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=96273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}