{"id":96953,"date":"2023-03-01T19:33:12","date_gmt":"2023-03-02T01:33:12","guid":{"rendered":"https:\/\/www.yucatanencorto.com\/noticias\/?p=96953"},"modified":"2023-03-01T19:41:02","modified_gmt":"2023-03-02T01:41:02","slug":"renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes","status":"publish","type":"post","link":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/","title":{"rendered":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-96957\" src=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-scaled.jpeg\" alt=\"\" width=\"576\" height=\"768\" srcset=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-scaled.jpeg 576w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-768x1024.jpeg 768w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-1152x1536.jpeg 1152w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-696x928.jpeg 696w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-1068x1424.jpeg 1068w, https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.35.23-315x420.jpeg 315w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/p>\n<p>San Jos\u00e9, California, Estados Unidos, a 1 de marzo de 2023.- El Alcalde Ren\u00e1n Barrera Concha explora los mercados digitales y las plataformas electr\u00f3nicas para impulsar a las micro y medianas empresas locales a trav\u00e9s de su inclusi\u00f3n en los modelos competitivos de los circuitos internacionales y las tendencias en la econom\u00eda global basada en la tecnolog\u00eda.<br \/>\nEn el marco de la visita a los Estados Unidos para consolidar el corredor California, Barrera Concha sostuvo reuniones de trabajo en la ciudad de San Jos\u00e9, para conocer nuevas oportunidades para impulsar a los emprendedores e incluir la econom\u00eda yucateca a los grandes circuitos internacionales.<\/p>\n<p>\u201cCon la invitaci\u00f3n que nos hizo la Secretar\u00eda de Relaciones Exteriores, realizamos un plan de trabajo para sostener reuniones con las empresas y l\u00edderes en materia de desarrollo econ\u00f3mico basado en plataformas de comercializaci\u00f3n en l\u00ednea y capacitaci\u00f3n a micro empresas\u201d, expres\u00f3.<\/p>\n<p>Cabe se\u00f1alar que el Presidente Municipal acept\u00f3 la invitaci\u00f3n de la Secretar\u00eda de Relaciones Exteriores para participar en la iniciativa denominada \u201cConvoy para la Internacionalizaci\u00f3n de Municipios Mexicanos\u201d, Corredor California, con el objetivo de ampliar las estrategias y v\u00ednculos comerciales a trav\u00e9s de la presentaci\u00f3n de las \u00e1reas de oportunidad que existen en las ciudades mexicanas.<\/p>\n<p>En esta jornada de trabajo, se retomaron las actividades con las empresas y l\u00edderes en vanguardia tecnol\u00f3gica, empresas digitales y mesas de di\u00e1logo para explorar las posibles inversiones que podr\u00edan realizarse en suelo yucateco.<br \/>\nLa delegaci\u00f3n mexicana se traslad\u00f3 a la empresa PayPal para conocer los \u00faltimos avances en la operaci\u00f3n del sistema de pagos en l\u00ednea relacionados con las transferencias de dinero entre usuarios, siendo una de las alternativas electr\u00f3nicas para cubrir el pago de diferentes productos o el cobro de servicios que den mayor certeza a los usuarios.<br \/>\nComo segundo punto, el Presidente Municipal acudi\u00f3 a las instalaciones de Google Bay View Campus, empresa que ha unido esfuerzos con el Gobierno Federal y ayuntamientos para desarrollar proyectos en sectores estrat\u00e9gicos.<\/p>\n<p>Barrera Concha adelant\u00f3 que establecer\u00e1 una alianza estrat\u00e9gica con Google para que brinden cursos de capacitaci\u00f3n y certificados de carrera de esta empresa a las y los emprendedores que forman parte del programa \u201cSoy Parte de los 100\u201d, con lo cual se reforzar\u00e1 la contribuci\u00f3n econ\u00f3mica positiva.<\/p>\n<p>Destac\u00f3 que la certificaci\u00f3n avalar\u00e1 las habilidades y competencias de los j\u00f3venes, permiti\u00e9ndoles una mayor movilidad econ\u00f3mica y acceder a empleos altamente remunerados en campos de amplia demanda y crecimiento.<\/p>\n<p>Como parte de las actividades de la jornada la delegaci\u00f3n se reuni\u00f3 con Alejandra Bologna Zubikarai, C\u00f3nsul General de M\u00e9xico en San Jos\u00e9, California, para establecer acuerdos y estrategias que beneficien al sector tur\u00edstico.<\/p>\n<p>Finalmente, en esta reuni\u00f3n se abordaron diferentes temas para la promoci\u00f3n tur\u00edstica como son el aprovechamiento de las nuevas aplicaciones digitales, que permitir\u00edan atraer a m\u00e1s visitantes al Municipio y a otras zonas de inter\u00e9s en Yucat\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; San Jos\u00e9, California, Estados Unidos, a 1 de marzo de 2023.- El Alcalde Ren\u00e1n Barrera Concha explora los mercados digitales y las plataformas electr\u00f3nicas para impulsar a las micro y medianas empresas locales a trav\u00e9s de su inclusi\u00f3n en los modelos competitivos de los circuitos internacionales y las tendencias en la econom\u00eda global basada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":96954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-96953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-merida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto\" \/>\n<meta property=\"og:description\" content=\"&nbsp; San Jos\u00e9, California, Estados Unidos, a 1 de marzo de 2023.- El Alcalde Ren\u00e1n Barrera Concha explora los mercados digitales y las plataformas electr\u00f3nicas para impulsar a las micro y medianas empresas locales a trav\u00e9s de su inclusi\u00f3n en los modelos competitivos de los circuitos internacionales y las tendencias en la econom\u00eda global basada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/\" \/>\n<meta property=\"og:site_name\" content=\"Yucat\u00e1n en corto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/yucatanencorto\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T01:33:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T01:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yucat\u00e1n en Corto FC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:site\" content=\"@yucatanencorto\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yucat\u00e1n en Corto FC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/\"},\"author\":{\"name\":\"Yucat\u00e1n en Corto FC\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\"},\"headline\":\"Renan Barrera visita oficinas de Google como parte de gira de alcaldes\",\"datePublished\":\"2023-03-02T01:33:12+00:00\",\"dateModified\":\"2023-03-02T01:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/\"},\"wordCount\":531,\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg\",\"articleSection\":[\"M\u00e9rida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/\",\"name\":\"Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg\",\"datePublished\":\"2023-03-02T01:33:12+00:00\",\"dateModified\":\"2023-03-02T01:41:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg\",\"width\":768,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renan Barrera visita oficinas de Google como parte de gira de alcaldes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"name\":\"Yucat\u00e1n en corto\",\"description\":\"Noticias\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#organization\",\"name\":\"Yucat\u00e1n en corto\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Logo-web.png\",\"width\":272,\"height\":90,\"caption\":\"Yucat\u00e1n en corto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/yucatanencorto\",\"https:\\\/\\\/x.com\\\/yucatanencorto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/#\\\/schema\\\/person\\\/14f82d355225a1f4075dd84a31f45a72\",\"name\":\"Yucat\u00e1n en Corto FC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g\",\"caption\":\"Yucat\u00e1n en Corto FC\"},\"url\":\"https:\\\/\\\/www.yucatanencorto.com\\\/noticias\\\/author\\\/flor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/","og_locale":"es_ES","og_type":"article","og_title":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto","og_description":"&nbsp; San Jos\u00e9, California, Estados Unidos, a 1 de marzo de 2023.- El Alcalde Ren\u00e1n Barrera Concha explora los mercados digitales y las plataformas electr\u00f3nicas para impulsar a las micro y medianas empresas locales a trav\u00e9s de su inclusi\u00f3n en los modelos competitivos de los circuitos internacionales y las tendencias en la econom\u00eda global basada [&hellip;]","og_url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/","og_site_name":"Yucat\u00e1n en corto","article_publisher":"http:\/\/www.facebook.com\/yucatanencorto","article_published_time":"2023-03-02T01:33:12+00:00","article_modified_time":"2023-03-02T01:41:02+00:00","og_image":[{"width":768,"height":614,"url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg","type":"image\/jpeg"}],"author":"Yucat\u00e1n en Corto FC","twitter_card":"summary_large_image","twitter_creator":"@yucatanencorto","twitter_site":"@yucatanencorto","twitter_misc":{"Escrito por":"Yucat\u00e1n en Corto FC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#article","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/"},"author":{"name":"Yucat\u00e1n en Corto FC","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72"},"headline":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes","datePublished":"2023-03-02T01:33:12+00:00","dateModified":"2023-03-02T01:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/"},"wordCount":531,"publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg","articleSection":["M\u00e9rida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/","name":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes - Yucat\u00e1n en corto","isPartOf":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#primaryimage"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg","datePublished":"2023-03-02T01:33:12+00:00","dateModified":"2023-03-02T01:41:02+00:00","breadcrumb":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#primaryimage","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-01-at-19.29.51-scaled.jpeg","width":768,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/www.yucatanencorto.com\/noticias\/renan-barrera-visita-oficinas-de-google-como-parte-de-gira-de-alcaldes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.yucatanencorto.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Renan Barrera visita oficinas de Google como parte de gira de alcaldes"}]},{"@type":"WebSite","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#website","url":"https:\/\/www.yucatanencorto.com\/noticias\/","name":"Yucat\u00e1n en corto","description":"Noticias","publisher":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yucatanencorto.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#organization","name":"Yucat\u00e1n en corto","url":"https:\/\/www.yucatanencorto.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","contentUrl":"https:\/\/www.yucatanencorto.com\/noticias\/wp-content\/uploads\/2026\/08\/Logo-web.png","width":272,"height":90,"caption":"Yucat\u00e1n en corto"},"image":{"@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/yucatanencorto","https:\/\/x.com\/yucatanencorto"]},{"@type":"Person","@id":"https:\/\/www.yucatanencorto.com\/noticias\/#\/schema\/person\/14f82d355225a1f4075dd84a31f45a72","name":"Yucat\u00e1n en Corto FC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/147d4b30cd728c53c29c49a3f7834dedca33707f4cd259761355846009a88250?s=96&d=mm&r=g","caption":"Yucat\u00e1n en Corto FC"},"url":"https:\/\/www.yucatanencorto.com\/noticias\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/comments?post=96953"}],"version-history":[{"count":0,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/posts\/96953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media\/96954"}],"wp:attachment":[{"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/media?parent=96953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/categories?post=96953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yucatanencorto.com\/noticias\/wp-json\/wp\/v2\/tags?post=96953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}